{"id":38956,"date":"2024-09-20T10:47:33","date_gmt":"2024-09-20T16:47:33","guid":{"rendered":"https:\/\/encartes.mx\/?p=38956"},"modified":"2024-09-25T14:08:55","modified_gmt":"2024-09-25T20:08:55","slug":"dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia","status":"publish","type":"post","link":"https:\/\/encartes.mx\/pt\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/","title":{"rendered":"Aprendendo a ver e sentir o invis\u00edvel: Pedagogia som\u00e1tica na pr\u00e1tica espiritual alternativa"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Resumen<\/h2>\n\n\n\n<p class=\"abstract\">El art\u00edculo expone un proceso de aprendizaje som\u00e1tico progresivo que tiene como objetivo la producci\u00f3n de un cuerpo sensible capaz de interactuar con agentes no humanos promovidos en pr\u00e1cticas espirituales de inspiraci\u00f3n New Age y neopagana. Los rituales contempor\u00e1neos realizados en el sitio arqueol\u00f3gico de Carnac, Francia, se toman como base etnogr\u00e1fica y emp\u00edrica al considerarlos espacios de aprendizaje sensorial donde los participantes desarrollan su atenci\u00f3n corporal para verificar la eficacia de las t\u00e9cnicas implementadas. El an\u00e1lisis muestra que los elementos principales que componen la pedagog\u00eda som\u00e1tica aplicada son el aprendizaje de un lenguaje sensorial alternativo, la ejecuci\u00f3n de t\u00e9cnicas corporales, la pr\u00e1ctica de la visualizaci\u00f3n y la incorporaci\u00f3n de imaginarios som\u00e1ticos.<\/p>\n\n\n\n<p class=\"abstract\">Palabras claves: <a href=\"https:\/\/encartes.mx\/pt\/tag\/aprendizaje-sensorial\/\" rel=\"tag\">aprendizaje sensorial<\/a>, <a href=\"https:\/\/encartes.mx\/pt\/tag\/carnac\/\" rel=\"tag\">Carnac<\/a>, <a href=\"https:\/\/encartes.mx\/pt\/tag\/espiritualidad\/\" rel=\"tag\">espiritualidad<\/a>, <a href=\"https:\/\/encartes.mx\/pt\/tag\/experiencia-somatica\/\" rel=\"tag\">experiencia som\u00e1tica<\/a>, <a href=\"https:\/\/encartes.mx\/pt\/tag\/francia\/\" rel=\"tag\">Francia<\/a>, <a href=\"https:\/\/encartes.mx\/pt\/tag\/megalitos\/\" rel=\"tag\">megalitos<\/a>, <a href=\"https:\/\/encartes.mx\/pt\/tag\/neopaganismo\/\" rel=\"tag\">neopaganismo<\/a><\/p>\n\n\n\n<p class=\"en-title\"><span class=\"small-caps\">learning to see and feel the invisible: somatic learning in alternative spiritual practices<\/span><\/p>\n\n\n\n<p class=\"abstract\">This article describes a progressive somatic learning process that aims to produce a body sensitive enough to interact with the non-human agents promoted in New Age and neopagan spiritual practices. Contemporary rituals organized at the archeological site in Carnac, France, are the empirical research subject of this ethnography. These rituals are approached as spaces for sensory learning where participants tune into their body in order to verify the effectiveness of the techniques. As shown in the analysis, the core elements of the somatic learning applied in the rituals include the incorporation of an alternative sensory language, body techniques, visualization, and somatic imaginaries.<\/p>\n\n\n\n<p class=\"abstract\">Keywords: sensory learning, somatic experience, spirituality, neopaganism, contemporary paganism, Carnac, megaliths, France.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Introducci\u00f3n<\/h2>\n\n\n\n<p class=\"has-drop-cap abstract\">En los \u00faltimos veinte a\u00f1os, diversos investigadores han analizado la dimensi\u00f3n corporal y sensorial de la experiencia vivida por quienes participan en pr\u00e1cticas que promueven una concepci\u00f3n holista del ser humano<a class=\"anota\" id=\"anota1\" data-footnote=1>1<\/a> (De la Torre y Guti\u00e9rrez, 2016; Jamison, 2011; Pierini <em>et al<\/em>., 2023; Pike, 2001). Los resultados obtenidos por dichos estudios han se\u00f1alado la primac\u00eda de lo sensorial en la elaboraci\u00f3n y socializaci\u00f3n de experiencias de naturaleza espiritual, as\u00ed como tambi\u00e9n el rol otorgado a los sentidos como herramientas utilizadas para construir experiencias valorizadas como trascendentes. Esto ha revelado la importancia acordada al cuerpo como espacio donde los participantes registran dichas experiencias de manera sensorial y emocional. Entre las pr\u00e1cticas hol\u00edsticas analizadas, aquellas asociadas a los fen\u00f3menos heterog\u00e9neos identificados como New Age<a class=\"anota\" id=\"anota2\" data-footnote=2>2<\/a> y neopaganismo<a class=\"anota\" id=\"anota3\" data-footnote=3>3<\/a> han servido como casos de estudio ideales para explorar nuevas jerarqu\u00edas sensoriales que valoran el tacto como sentido clave para percibir la presencia y agencia de entidades convocadas, tales como energ\u00edas y esp\u00edritus (Rountree, 2006; Lombardi, 2023: 77). re<\/p>\n\n\n\n<p>Desde la antropolog\u00eda, el an\u00e1lisis de la construcci\u00f3n cultural del cuerpo ha impulsado el conocimiento sobre la socializaci\u00f3n de las experiencias corporales y sensoriales. El enfoque corporal, interesado en c\u00f3mo determinadas pr\u00e1cticas culturales se inscriben en el cuerpo (Blacking, 1977), surgi\u00f3 como una cr\u00edtica al textualismo caracter\u00edstico de la antropolog\u00eda de principios de los a\u00f1os ochenta.<a class=\"anota\" id=\"anota4\" data-footnote=4>4<\/a> En la d\u00e9cada siguiente, el inter\u00e9s antropol\u00f3gico por el cuerpo dio lugar a un giro sensorial que centr\u00f3 la atenci\u00f3n en la identificaci\u00f3n de distintos patrones culturales de percepci\u00f3n sensorial que forjan la experiencia humana (Howes, 2018: 7). Dicho proceso dio lugar a una orientaci\u00f3n metodol\u00f3gica llamada \u201ccorporizaci\u00f3n\u201d, que est\u00e1 fuertemente influenciada por la obra de Maurice Merleau-Ponty (1945, 1964) y por los escritos de Pierre Bourdieu (1977: 124). El primero propuso romper con el dualismo cartesiano que separaba el cuerpo de la mente,<a class=\"anota\" id=\"anota5\" data-footnote=5>5<\/a> y el segundo brind\u00f3 un enfoque de la corporizaci\u00f3n en el que la noci\u00f3n del cuerpo incluye los sentidos, las emociones y la conciencia.<a class=\"anota\" id=\"anota6\" data-footnote=6>6<\/a> El paradigma de la corporizaci\u00f3n al cual me adscribo fue propuesto por Thomas J. Csordas (1990), quien aborda anal\u00edticamente la experiencia corporizada que los individuos tienen de su propio cuerpo y las formas como lo utilizan para interactuar con su entorno f\u00edsico y social. A partir de estas teorizaciones, Csordas desarroll\u00f3 la noci\u00f3n de \u201cmodos som\u00e1ticos de atenci\u00f3n\u201d (Csordas, 1993: 138), definidos como modos culturalmente elaborados de prestar atenci\u00f3n a y con el propio cuerpo, en entornos que incluyen la presencia corporizada de otros. Dichos modos no son arbitrarios ni est\u00e1n biol\u00f3gicamente determinados, sino que se encuentran culturalmente construidos.<\/p>\n\n\n\n<p>En este art\u00edculo, analizo modos som\u00e1ticos de atenci\u00f3n que son caracter\u00edsticos de las pr\u00e1cticas de inspiraci\u00f3n New Age y neopagana que se realizan en el sitio arqueol\u00f3gico de Carnac. Los datos recabados en este sitio fungen como base etnogr\u00e1fica y emp\u00edrica para abordar c\u00f3mo los participantes aprenden a experimentar estas actividades con su cuerpo y sus sentidos. El objetivo del texto es brindar una comprensi\u00f3n lo m\u00e1s completa y fiel posible del proceso de aprendizaje que moldea las experiencias sensoriales de los practicantes. Los datos presentados en este art\u00edculo fueron recolectados aplicando una etnograf\u00eda sensorial caracterizada por la implementaci\u00f3n sistem\u00e1tica de distintas herramientas (Pink, 2009). La categorizaci\u00f3n y el an\u00e1lisis de los datos me permiti\u00f3 identificar y reconstruir un proceso que denomino \u201cpedagog\u00eda som\u00e1tica\u201d. Los elementos que conforman esta clase de educaci\u00f3n sensorial progresiva son susceptibles de ser identificados en otros contextos rituales propios de las espiritualidades New Age y neopaganas. Puntualmente se trata del aprendizaje de un lenguaje sensorial alternativo, la ejecuci\u00f3n de t\u00e9cnicas corporales, la pr\u00e1ctica de la visualizaci\u00f3n y la incorporaci\u00f3n de imaginarios som\u00e1ticos.<\/p>\n\n\n\n<p>Desde un punto de vista emic, el objetivo de las pr\u00e1cticas analizadas es acceder a los \u201cpoderes curativos\u201d de los megalitos locales mediante la intervenci\u00f3n de seres no humanos llamados \u201cesp\u00edritus del lugar\u201d. Como en el caso de las ceremonias animistas contempor\u00e1neas, dichas pr\u00e1cticas funcionan como espacios donde los participantes \u201caprenden a interactuar de manera adecuada con otras personas, no todas humanas\u201d (Harvey, 2005: 17).<a class=\"anota\" id=\"anota7\" data-footnote=7>7<\/a> El efecto principalmente deseado por los participantes es la adquisici\u00f3n de estados afectivos inscritos en los reg\u00edmenes emocionales promovidos dentro del New Age y la cultura del desarrollo personal, los cuales son susceptibles de generar las condiciones \u201cobjetivamente requeridas para la plena realizaci\u00f3n del ser humano y su potencial\u201d (Mossi\u00e8re, 2018: 65). Las pr\u00e1cticas tambi\u00e9n fungen como espacios-tiempo en donde los practicantes establecen interacciones ritualizadas y corporizadas con objetos (Ishii, 2012; Whitehead, 2018), que en este caso son monumentos prehist\u00f3ricos a los que se atribuye una agentividad \u201cenerg\u00e9tica\u201d capaz de provocar una transformaci\u00f3n de identidad y un encuentro personal con el \u201cotro\u201d (lo divino, lo sagrado, lo trascendente). Las pr\u00e1cticas se encuentran organizadas a trav\u00e9s de un protocolo ritual que las divide en distintas etapas. De una etapa a la otra, los participantes desarrollan progresivamente su atenci\u00f3n corporal y prestan especial atenci\u00f3n a sus sensaciones corporales. As\u00ed es como progresivamente aprenden a utilizarlas como herramientas para verificar, experimentar y vivenciar en qu\u00e9 momento y en qu\u00e9 condiciones su cuerpo entra en contacto con la energ\u00eda de los megalitos.<\/p>\n\n\n\n<p>El texto comienza con una discusi\u00f3n sobre los trabajos que han puesto en evidencia los roles atribuidos a las sensaciones corporales y las distintas estrategias de ense\u00f1anza que son implementadas para producirlas e interpretarlas dentro de las pr\u00e1cticas de inspiraci\u00f3n New Age y neopagana. A continuaci\u00f3n se describe el contexto de nuestro caso de estudio. Se abordan seguidamente los elementos que distinguen a estas pr\u00e1cticas y las herramientas metodol\u00f3gicas aplicadas. Despu\u00e9s, se ilustra el protocolo ritual que organiza las pr\u00e1cticas a partir de un relato etnogr\u00e1fico. Finalmente, se analizan los elementos que componen la pedagog\u00eda som\u00e1tica identificada. A modo de conclusi\u00f3n, ahondo sobre la relaci\u00f3n que podemos establecer entre esta pedagog\u00eda y la eficacia otorgada a las pr\u00e1cticas analizadas, as\u00ed como tambi\u00e9n en la importancia del tacto como sentido primordial que permite al participante afectar y ser afectado por las entidades convocadas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las pr\u00e1cticas espirituales alternativas como espacios de aprendizaje<\/h2>\n\n\n\n<p class=\"abstract\">La recolecci\u00f3n de datos etnogr\u00e1ficos sobre interpretaciones heterog\u00e9neas del cuerpo, especialmente del \u201ccuerpo sensible\u201d como lugar que somos y construimos para existir (Le Breton, 2010), ha permitido explorar el significado otorgado a las experiencias som\u00e1ticas en contextos rituales propios de las espiritualidades alternativas. Algunos ejemplos son las ceremonias neopaganas en las que los participantes aprenden distintos modos som\u00e1ticos de atenci\u00f3n para interpretar ciertas sensaciones corporales como producidas por seres no humanos (Rountree, 2006); los rituales neo-cham\u00e1nicos en los que distintas experiencias sensoriales y olfativas son puestas en valor por quienes dirigen las pr\u00e1cticas como pruebas de una intervenci\u00f3n divina (Lombardi, 2023: 77); y las sesiones de curaci\u00f3n energ\u00e9tica en las que ciertas sensaciones son presentadas como evidencia de interacci\u00f3n con las \u201cenerg\u00edas invisibles\u201d (Pierini <em>et al<\/em>., 2023). La omnipresencia de referencias al cuerpo en los discursos de quienes participan en este tipo de experiencias parece deberse a los principios que organizan las pr\u00e1cticas. Como lo ilustra la investigaci\u00f3n realizada por Ren\u00e9e de la Torre y Cristina Guti\u00e9rrez (2016: 168) sobre el protocolo ritual que organiza las sesiones de ba\u00f1o de vapor prehisp\u00e1nico llamado temazcal, ciertas pr\u00e1cticas funcionan como dispositivos orientados a la producci\u00f3n de sensaciones corporales mediante interacciones ritualizadas del participante con elementos de la naturaleza (\u00e1rboles, piedras, fuego, agua y tierra, entre otros).<\/p>\n\n\n\n<p>Birgit Meyer (2006) se\u00f1ala que los estudios sobre la experiencia som\u00e1tica aportan conocimientos sobre distintas disciplinas corporales y reg\u00edmenes sensoriales promovidos por corrientes espirituales contempor\u00e1neas. Tambi\u00e9n ponen en evidencia el potencial de diversas pr\u00e1cticas hol\u00edsticas como espacios donde los practicantes descubren, experimentan e incorporan un corpus de conocimientos relativo al cuerpo y a los sentidos transferible o susceptible de ser aplicado en otros contextos. Los datos expuestos en los p\u00e1rrafos anteriores suscitan la siguiente cuesti\u00f3n: \u00bfcu\u00e1les son los componentes de los procesos de aprendizaje que permiten a los practicantes producir y experimentar estas actividades con su cuerpo culturalmente construido?<\/p>\n\n\n\n<p>Varios an\u00e1lisis han explorado c\u00f3mo el conocimiento y las habilidades asociadas al cuerpo y a los sentidos se desarrollan en contextos rituales neopaganos. El estudio de Emily Pierini (2016) sobre el proceso de aprendizaje de m\u00e9diums brasile\u00f1os identific\u00f3 c\u00f3mo los actores desarrollan habilidades para establecer relaciones con los esp\u00edritus invocados. Su investigaci\u00f3n revel\u00f3 que dicho aprendizaje toma la forma de una experiencia multidimensional que es a la vez corporal, intuitiva, performativa, conceptual e intersubjetiva. La investigaci\u00f3n de David Dupuis (2018) sobre lo que \u00e9l denomina \u201caprendizaje visionario\u201d en rituales neo-cham\u00e1nicos de ayahuasca que tienen lugar en la Amazonia peruana tambi\u00e9n reconstruy\u00f3 procesos espec\u00edficos de aprendizaje progresivo. Su estudio identific\u00f3 las interacciones discursivas y pragm\u00e1ticas que enmarcan el consumo de dicho brebaje alucin\u00f3geno y que dan forma a las interpretaciones de las visiones que tienen los participantes.<\/p>\n\n\n\n<p>Aunque estos dos estudios contribuyen a la reconstrucci\u00f3n de procesos de aprendizaje espec\u00edficos implementados para elaborar experiencias de naturaleza \u201cespiritual\u201d, considero que es necesario prestar una atenci\u00f3n m\u00e1s profunda a los elementos que configuran la educaci\u00f3n som\u00e1tica, tanto en el \u00e1mbito individual como en el colectivo, a partir de un enfoque etnogr\u00e1fico sensorial (Pink, 2009). En busca de entender c\u00f3mo los participantes producen y cultivan un cuerpo capaz de interactuar con entidades no humanas, entre 2015 y 2019 realic\u00e9 un estudio etnogr\u00e1fico en el sitio arqueol\u00f3gico de Carnac. En los \u00faltimos veinte a\u00f1os este espacio se ha convertido en escenario de numerosos cursos, encuentros y ceremonias colectivas orientados a la producci\u00f3n y socializaci\u00f3n de experiencias som\u00e1ticas provocadas por el contacto f\u00edsico del cuerpo con la superficie de monumentos prehist\u00f3ricos de piedra.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Contexto del estudio de caso<\/h2>\n\n\n\n<p class=\"abstract\">Carnac es un sitio arqueol\u00f3gico ubicado en el noroeste de Francia c\u00e9lebre por sus numerosos monumentos prehist\u00f3ricos que toman la forma de bloques de piedra llamados megalitos y de tumbas llamadas t\u00famulos (Figura 1). Diversos grupos se re\u00fanen all\u00ed para realizar pr\u00e1cticas colectivas, generalmente de un d\u00eda de duraci\u00f3n. Estas actividades promueven interacciones ritualizadas entre seres humanos y no humanos que son susceptibles de ser experimentadas som\u00e1ticamente. Una de dichas experiencias fue descrita por Marie, una participante oriunda de la regi\u00f3n de Carnac de la siguiente manera:<\/p>\n\n\n\n<p class=\"verse\">Cuando me acost\u00e9 sobre el megalito, sent\u00ed su energ\u00eda en mi cuerpo, en mi columna vertebral. Sent\u00ed que la energ\u00eda de la piedra me realineaba desde dentro. Eso fue muy poderoso. Realmente sent\u00ed la energ\u00eda del lugar, sent\u00ed lo que me estaba haciendo (Marie, 6 de mayo de 2017).<a class=\"anota\" id=\"anota8\" data-footnote=8>8<\/a><\/p>\n\n\n\n<p>Las pr\u00e1cticas analizadas entremezclan t\u00e9cnicas corporales<a class=\"anota\" id=\"anota9\" data-footnote=9>9<\/a> derivadas de tradiciones populares relativas a los poderes curativos de los megalitos (Boismoreau, 1917) y conocimientos de car\u00e1cter holista sobre el cuerpo que empezaron a difundirse en Francia a partir de 1980 a trav\u00e9s de revistas esot\u00e9ricas.<a class=\"anota\" id=\"anota10\" data-footnote=10>10<\/a> Marie, como otros participantes, considera que Carnac re\u00fane tres caracter\u00edsticas principales que hacen del lugar un espacio ideal para \u201cconectarse\u201d con ella misma, con la naturaleza y con el universo. Al igual que otros sitios arqueol\u00f3gicos convertidos en lugares de culto por quienes se adhieren a espiritualidades alternativas, el paisaje megal\u00edtico de Carnac es considerado como un \u201cpaisaje natural sagrado\u201d, un \u201clugar energ\u00e9tico\u201d y la obra de \u201cantiguos constructores\u201d que ten\u00edan \u201cotros\u201d conocimientos sobre su entorno. Como lo ilustra la siguiente frase, los discursos de los especialistas que dirigen las pr\u00e1cticas hacen eco de estas concepciones: \u201cEl paisaje natural sagrado de Carnac, con sus megalitos, nos sirve de entorno para equilibrar nuestras energ\u00edas\u201d (Eric, 13 de diciembre de 2015). Si los conocimientos de los especialistas son aceptados por los participantes como \u201cleg\u00edtimos\u201d es porque los primeros ostentan una autoridad moral ante el grupo (Durkheim, 1992 [1902]: 25). Esto significa que su autoridad solo existe si es reconocida por los participantes. Estos \u00faltimos le conceden una obediencia consentida porque consideran que el especialista tiene conocimientos sobre los megalitos que son susceptibles de ser reformulados o enriquecidos por sus propias experiencias y conocimientos.<a class=\"anota\" id=\"anota11\" data-footnote=11>11<\/a><\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg\" itemprop=\"contentUrl\" data-size=\"3072x1728\" data-index=\"0\" data-caption=\"Figura 1: Grupo haciendo una caminata energ\u00e9tica en los alineamientos (Dansac, Carnac, 2015).\" >\n                                <img decoding=\"async\" src=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Figura 1: Grupo haciendo una caminata energ\u00e9tica en los alineamientos (Dansac, Carnac, 2015).<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>Las pr\u00e1cticas analizadas no son identificadas por los especialistas como \u201cespirituales\u201d o \u201crituales\u201d. Estos las proponen como actividades l\u00fadicas y terap\u00e9uticas. Sin embargo, estas pr\u00e1cticas son experiencias que estructuran y producen subjetividades e identidades. Su potencial \u201cespiritual\u201d reside en la calidad de las relaciones y experiencias que buscan producir un reencuentro con uno mismo y un cambio en las relaciones con uno mismo y con los dem\u00e1s (Heelas, 2009: 792), as\u00ed como una b\u00fasqueda de autenticidad, verdad y trascendencia (Mossi\u00e8re, 2018: 61). Constituyen pr\u00e1cticas rituales porque son portadoras de significados, expresan una serie de valores e ideas culturales, ponen en relaci\u00f3n elementos dispares haci\u00e9ndolos interdependientes, se caracterizan por su din\u00e1mica interna y constituyen dispositivos orientados a la producci\u00f3n y socializaci\u00f3n de experiencias espec\u00edficamente de tipo som\u00e1tico. La noci\u00f3n de espiritualidad identificada en los discursos difundidos en estas pr\u00e1cticas est\u00e1 vinculada a una sem\u00e1ntica centrada en las energ\u00edas (tel\u00faricas, corporales, emocionales, divinas, c\u00f3smicas, universales). Este vocabulario evoca la posibilidad de una curaci\u00f3n de tipo hol\u00edstico en la que cada participante busca reconectarse consigo mismo, con los dem\u00e1s y con el universo (Houseman, 2002: 533).<\/p>\n\n\n\n<p>Las pr\u00e1cticas son heterog\u00e9neas en cuanto a la ideolog\u00eda que movilizan, ya que cada una ofrece un marco de interpretaci\u00f3n diferente. Pueden basarse en las energ\u00edas tel\u00faricas, la tensegridad de Carlos Castaneda,<a class=\"anota\" id=\"anota12\" data-footnote=12>12<\/a> el neo-chamanismo o la sanaci\u00f3n energ\u00e9tica del aura. El \u00fanico requisito para participar es pagar la tarifa establecida por el especialista. Los grupos son heterog\u00e9neos, cambian constantemente y est\u00e1n formados por tres tipos principales de actores. Estos desempe\u00f1an papeles espec\u00edficos, respetan una estructura jer\u00e1rquica vertical y mantienen un orden de g\u00e9nero que asigna funciones distintas a hombres y mujeres. El especialista es quien gu\u00eda a los participantes a trav\u00e9s de un protocolo que organiza las pr\u00e1cticas y construye las narrativas que les dan sentido. Todos los especialistas que conoc\u00ed eran hombres de entre cuarenta y setenta a\u00f1os, la mayor\u00eda de los cuales viv\u00edan en Par\u00eds, y hab\u00edan cursado estudios superiores. El especialista se identifica a s\u00ed mismo como \u201ccham\u00e1n\u201d o \u201c<em>coach<\/em> espiritual\u201d y rara vez es autodidacta, ya que adquiere sus conocimientos a trav\u00e9s de cursos de formaci\u00f3n en el campo de la curaci\u00f3n energ\u00e9tica. El especialista ofrece una amplia variedad de pr\u00e1cticas que se diferencian entre ellas por su duraci\u00f3n, el n\u00famero de megalitos a visitar y los marcos de interpretaci\u00f3n otorgados. Dichas actividades son propuestas en p\u00e1ginas de internet en donde el participante puede elegir la que m\u00e1s le conviene. El asistente del especialista se encarga de mediar la comunicaci\u00f3n entre los actores, evitar la monopolizaci\u00f3n de la palabra, desdramatizar una situaci\u00f3n cuando hay un problema y gestionar conflictos. Todas las asistentes que conoc\u00ed eran mujeres que ten\u00edan una relaci\u00f3n personal con el especialista. Los participantes son los que pagan la tarifa que cobran los especialistas, que var\u00eda entre ciento cincuenta y trescientos euros por d\u00eda. Los objetivos que los llevan a invertir su tiempo, dinero y esfuerzo en estas pr\u00e1cticas var\u00edan. En general, los participantes buscan vivir una experiencia capaz de provocar un cambio inmediato en la percepci\u00f3n que tienen de s\u00ed mismos, de los dem\u00e1s y de su entorno. La mayor\u00eda de los participantes que conoc\u00ed eran debutantes, viv\u00edan cerca de Carnac y eran mujeres de entre veinticuatro y setenta a\u00f1os con estudios superiores. Tienen un inter\u00e9s com\u00fan por el ocultismo, la arqueolog\u00eda, la astrolog\u00eda o el desarrollo personal. Los tres tipos de actores conforman lo que llamo \u201ccomunidades ef\u00edmeras\u201d,<a class=\"anota\" id=\"anota13\" data-footnote=13>13<\/a> ya que no entablan relaciones personales ni duraderas entre ellos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Herramientas para un estudio etnogr\u00e1fico sobre experiencias sensoriales en contextos rituales<\/h2>\n\n\n\n<p class=\"abstract\">De 2015 a 2019 llev\u00e9 a cabo un estudio etnogr\u00e1fico en veinte pr\u00e1cticas de inspiraci\u00f3n New Age y neopagana realizadas en el sitio arqueol\u00f3gico de Carnac. El objetivo del estudio fue analizar el proceso de construcci\u00f3n y socializaci\u00f3n de experiencias consideradas como \u201cespirituales\u201d que se manifiestan de forma som\u00e1tica. Para ello me enfoqu\u00e9 en la situaci\u00f3n de los cuerpos de las personas investigadas, as\u00ed como en el entorno intersubjetivo en el que generan e interpretan sus sensaciones corporales. Siguiendo estas estrategias, busqu\u00e9 aportar nuevos conocimientos sobre el contenido de la \u201cexperiencia vivida\u201d de mis interlocutores.<\/p>\n\n\n\n<p>Tomando en cuenta que el estudio se concibi\u00f3 como una fenomenolog\u00eda de la experiencia ritual en un contexto espec\u00edfico, decid\u00ed aplicar m\u00e9todos etnogr\u00e1ficos que me permitieran recopilar datos sobre la experiencia sensorial de los participantes al interior de las pr\u00e1cticas analizadas. Al inicio de mi trabajo de campo constat\u00e9 que las herramientas etnogr\u00e1ficas t\u00edpicas, como la observaci\u00f3n participante y las entrevistas semiestructuradas y estructuradas, eran \u00fatiles, pero no bastaban para obtener datos detallados sobre los procesos que permiten a los participantes generar e interpretar sus sensaciones corporales. Por ende, integr\u00e9 dos m\u00e9todos desarrollados por la etnograf\u00eda sensorial (Pink, 2009): la entrevista som\u00e1tica y la participaci\u00f3n sensorial.<\/p>\n\n\n\n<p>La entrevista som\u00e1tica es una herramienta adaptada del m\u00e9todo desarrollado por Jaida K. Samudra (2008: 670) en su investigaci\u00f3n sobre la experiencia kinest\u00e9sica. Consisti\u00f3 en hacer preguntas a los participantes sobre la manera correcta de realizar un determinado movimiento corporal indicado por el especialista y luego en seguir sus indicaciones mientras me supervisaban realiz\u00e1ndolo. Al proceder de esta manera, obtuve respuestas f\u00edsicas y verbales de parte del participantementor, quien recurrentemente correg\u00eda mi postura corporal y mis movimientos. Al mismo tiempo, yo llevaba a cabo f\u00edsicamente las instrucciones que el participante acababa de darme, incluyendo las correcciones. Durante estas entrevistas som\u00e1ticas desempe\u00f1\u00e9 el papel de aprendiz. Al ser observada y guiada por otros participantes, pude identificar cu\u00e1ndo y en qu\u00e9 condiciones se producen las experiencias som\u00e1ticas que los participantes valoran como indicadores de la presencia de \u201cenerg\u00edas\u201d, \u201cesp\u00edritus\u201d u otras entidades convocadas.<a class=\"anota\" id=\"anota14\" data-footnote=14>14<\/a> La participaci\u00f3n sensorial es una herramienta concebida por David Howes (2019) en su estudio sobre el significado atribuido a sensaciones en distintas culturas. Consisti\u00f3 en utilizar mi cuerpo, mis sentidos y experiencias corporales como herramientas para analizar la posici\u00f3n espacial de los cuerpos investigados, as\u00ed como la relaci\u00f3n entre movimientos corporales y una determinada sensaci\u00f3n.<a class=\"anota\" id=\"anota15\" data-footnote=15>15<\/a> Dicha herramienta encuentra eco en la propuesta de \u201cEl diario de campo encarnado\u201d de Hilda Mazariegos (2022), que incluye el registro de la experiencia corporal y emocional del investigador. Los dos m\u00e9todos que apliqu\u00e9 me exigieron una implicaci\u00f3n f\u00edsica y emocional intensa. Los datos recolectados por medio de la aplicaci\u00f3n de observaciones participantes, entrevistas verbales, entrevistas som\u00e1ticas y participaciones sensoriales me permitieron elaborar una triangulaci\u00f3n entre mis propias experiencias corporales, las experiencias som\u00e1ticas de mis interlocutores y sus relatos sobre las mismas.<\/p>\n\n\n\n<p>Los datos recolectados por este estudio me permitieron constatar que la implicaci\u00f3n sensorial y f\u00edsica de los participantes es intensa. La importancia que le atribuyen a sus sensaciones corporales, los usos que hacen de su cuerpo y la atenci\u00f3n que otorgan a sus sentidos es constante. Podr\u00edamos sugerir que el modo som\u00e1tico de atenci\u00f3n que dichas pr\u00e1cticas movilizan se caracteriza por los usos que los participantes dan a su cuerpo y sus sentidos como herramientas para comprobar la presencia de las \u201cenerg\u00edas de los megalitos\u201d y constatar la potencialidad de estas. Los datos tambi\u00e9n se\u00f1alaron que, desde los primeros minutos hasta el final de cada pr\u00e1ctica, los participantes deben realizar simult\u00e1neamente m\u00faltiples tareas: deben aprender a mover su cuerpo de determinadas maneras, tener pleno control de sus movimientos y prestar atenci\u00f3n a las sensaciones corporales que estos provocan. El aprendizaje progresivo de estas acciones conforma el proceso que denomino \u201cpedagog\u00eda som\u00e1tica\u201d. Mi comprensi\u00f3n de dicho proceso est\u00e1 fuertemente influenciada por el paradigma de corporizaci\u00f3n de Csordas (1990). Esta noci\u00f3n subraya la interacci\u00f3n y relaci\u00f3n entre mente y cuerpo, permite ahondar en las diversas formas en que se experimenta corporalmente la experiencia religiosa o espiritual y explora c\u00f3mo los individuos experimentan el entorno social y f\u00edsico con sus cuerpos culturalmente construidos. El concepto de corporizaci\u00f3n me permiti\u00f3 enfocarme en el cuerpo de los practicantes como base existencial de las experiencias que viven durante las pr\u00e1cticas. Al igual que Csordas (1993: 138), utilic\u00e9 el t\u00e9rmino \u201csom\u00e1tico\u201d para referirme a las sensaciones corporales que utilizan los practicantes para experimentar las pr\u00e1cticas en y con su cuerpo. Su noci\u00f3n de \u201cmodos som\u00e1ticos de atenci\u00f3n\u201d me incit\u00f3 a analizar a detalle el contexto f\u00edsico e intersubjetivo que da lugar a una determinada sensaci\u00f3n corporal.<\/p>\n\n\n\n<p>La etnograf\u00eda sensorial realizada tambi\u00e9n revel\u00f3 que dicho aprendizaje som\u00e1tico se implementa gradualmente a trav\u00e9s de un protocolo ritual compuesto por fases secuenciales lineales que gu\u00edan las pr\u00e1cticas, formando un patr\u00f3n general que siguen todos los especialistas que conoc\u00ed. En primer lugar, los participantes caminan en grupo hacia un monumento prehist\u00f3rico. A continuaci\u00f3n se colocan lejos del objeto para realizar colectivamente t\u00e9cnicas corporales. Luego, el especialista gu\u00eda a los participantes a trav\u00e9s de un ejercicio de visualizaci\u00f3n para contactar a los esp\u00edritus o guardianes que son los \u00fanicos capaces de liberar la energ\u00eda del megalito. Si la pr\u00e1ctica se realiza cerca de un megalito, cada participante toca a continuaci\u00f3n el objeto con las palmas de las manos, el pecho, la frente o la espalda. Cuando se realiza a proximidad de una tumba prehist\u00f3rica, el participante ingresa en el interior donde experimenta sensaciones corporales y olfativas variadas. Por \u00faltimo, los participantes se colocan en c\u00edrculo cerca del monumento y realizan intercambios verbales para comparar sus experiencias som\u00e1ticas entre s\u00ed. El tipo de pedagog\u00eda som\u00e1tica que implementa este protocolo se basa en cuatro elementos principales: el aprendizaje progresivo de un lenguaje sensorial, la ejecuci\u00f3n de t\u00e9cnicas corporales, la pr\u00e1ctica de la visualizaci\u00f3n y la interpretaci\u00f3n de imaginarios som\u00e1ticos. A continuaci\u00f3n ilustrar\u00e9 estos elementos a trav\u00e9s del relato etnogr\u00e1fico sobre una pr\u00e1ctica que no fue realizada en los alineamientos de Carnac, sino en una tumba prehist\u00f3rica local.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Implementaci\u00f3n de una pedagog\u00eda som\u00e1tica a trav\u00e9s de un protocolo ritual<\/h2>\n\n\n\n<p class=\"abstract\">En una pr\u00e1ctica dirigida en mayo de 2018 por Pierre, este <em>coach<\/em> espiritual nos propuso que comenz\u00e1ramos nuestras actividades visitando un monumento distinto al Gigante de Manio, un megalito de cuatro metros de altura que suele visitarse al inicio de las actividades. Nuestro punto de reuni\u00f3n fue una comunidad cerca de Carnac llamada Le Bono, donde se encuentra una tumba prehist\u00f3rica llamada el \u201ct\u00famulo de Kernous\u201d. Al llegar al lugar, aparcamos en un peque\u00f1o estacionamiento a unos cincuenta metros de la tumba. Esta ten\u00eda unos ocho metros de altura y treinta y cinco de di\u00e1metro. Estaba formada por piedras cubiertas por una gruesa capa exterior de escombros de granito. Esta estructura era la tumba. El \u00fanico acceso al interior era a trav\u00e9s de un t\u00fanel a nivel del suelo (Figura 2).<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-2-Tumba.jpg\" itemprop=\"contentUrl\" data-size=\"2000x1118\" data-index=\"0\" data-caption=\"Figura 2: Tumba prehist\u00f3rica de Kernous (Dansac, Kernous, 2018).\" >\n                                <img decoding=\"async\" src=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-2-Tumba.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Figura 2: Tumba prehist\u00f3rica de Kernous (Dansac, Kernous, 2018).<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>Una vez que todos llegamos al lugar, Pierre nos pidi\u00f3 que form\u00e1ramos un c\u00edrculo y nos explic\u00f3 que esta tumba neol\u00edtica era una de las mejor conservadas de la regi\u00f3n y que era seguro visitar su interior. A continuaci\u00f3n nos brind\u00f3 su interpretaci\u00f3n del lugar y nos indic\u00f3 el objetivo de las actividades que \u00edbamos a llevar a cabo de la siguiente manera:<\/p>\n\n\n\n<p class=\"verse\">En el pasado, los druidas realizaban ceremonias sagradas en el interior de esta tumba para aportar bienestar y vitalidad a las personas y a la comunidad. Como ellos, vamos a entrar en esta tumba para realinear y armonizar nuestros centros energ\u00e9ticos, lo que nos permitir\u00e1 aliviar nuestras dolencias f\u00edsicas y mentales. Tambi\u00e9n nos permitir\u00e1 desbloquear, reactivar y volver a estimular la circulaci\u00f3n de la energ\u00eda vital que fluye dentro de cada uno de nosotros. En primer lugar, sus cuerpos tender\u00e1n a adaptarse a la frecuencia energ\u00e9tica del lugar. En segundo lugar, la energ\u00eda de la tumba estimular\u00e1 el proceso de limpieza energ\u00e9tica de vuestro ser. Cuando salg\u00e1is, os sentir\u00e9is mejor, tanto f\u00edsica como emocionalmente. Pero primero, vamos a hacer algunos ejercicios para prepararnos y sacar el m\u00e1ximo de esta experiencia (Pierre, 6 de mayo de 2018).<\/p>\n\n\n\n<p>Tras su discurso, Pierre nos pidi\u00f3 que sigui\u00e9ramos en c\u00edrculo y nos guio a trav\u00e9s de una serie de t\u00e9cnicas corporales que nos servir\u00edan para identificar colectivamente las diversas experiencias sensoriales que se pueden tener en el interior de la tumba. En primer lugar, ten\u00edamos que respirar tranquila y profundamente, concentr\u00e1ndonos en la duraci\u00f3n de la inhalaci\u00f3n y la exhalaci\u00f3n. Luego ten\u00edamos que levantar las manos y los brazos al cielo. A continuaci\u00f3n, baj\u00e1bamos lentamente los brazos para apoyar las palmas de las manos en la cabeza y, finalmente, recorr\u00edamos con las palmas el largo de nuestro cuerpo hasta llegar a los pies (Figura 3).<\/p>\n\n\n\n<p>Despu\u00e9s de repetir esta t\u00e9cnica unas diez veces, Pierre nos pidi\u00f3 que nos pusi\u00e9ramos en parejas, frente a frente, todav\u00eda de pie y fuera de la tumba. Nos dijo que una persona de cada pareja deb\u00eda permanecer completamente quieta, con la cabeza erguida y los brazos a los lados del cuerpo. La otra persona deb\u00eda poner las palmas de las manos cerca del cuerpo de su compa\u00f1ero, sin llegar a entrar en contacto directo con \u00e9l, dejando unos diez cent\u00edmetros de distancia entre la palma y el cuerpo de la otra persona. Podr\u00edamos pensar que el participante inm\u00f3vil adopta el rol de un megalito, o de un \u00e1rbol, o incluso de la estructura exterior de la tumba. La persona que pod\u00eda mover su cuerpo ten\u00eda que levantar las manos con las palmas hacia el cielo, y luego ponerlas por encima de la cabeza de su compa\u00f1ero, sin llegar a tocarlo. Luego ten\u00eda que bajar lentamente las palmas de las manos hasta que estuvieran por encima de los hombros, luego a lo largo de los brazos y las piernas, hasta llegar a los pies de la pareja (Figura 4). Al terminar, el compa\u00f1ero inm\u00f3vil recuperaba su movilidad y el binomio intercambiaba verbalmente al respecto de las sensaciones corporales que hab\u00edan experimentado durante la actividad: ligereza o pesadez en los miembros superiores al dibujar el contorno del compa\u00f1ero; calor o fr\u00edo al ser recorrido por las palmas del otro. A continuaci\u00f3n se invert\u00edan los roles para repetir el mismo ejercicio.<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-3-Posiciones.jpg\" itemprop=\"contentUrl\" data-size=\"910x577\" data-index=\"0\" data-caption=\"Figura 3: Esquema de las posiciones corporales durante el ejercicio individual (Dansac).\" >\n                                <img decoding=\"async\" src=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-3-Posiciones.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-4-Posiciones.jpg\" itemprop=\"contentUrl\" data-size=\"452x675\" data-index=\"0\" data-caption=\"Figura 4: Esquema de las posiciones corporales durante el ejercicio en parejas (Dansac).\" >\n                                <img decoding=\"async\" src=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-4-Posiciones.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Figura 3: Esquema de las posiciones corporales durante el ejercicio individual (Dansac).<\/div><div class=\"image-analysis\"><\/div><div class=\"caption\">Figura 4: Esquema de las posiciones corporales durante el ejercicio en parejas (Dansac).<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>La pr\u00e1ctica de estas t\u00e9cnicas dur\u00f3 una hora. Al finalizar, Pierre nos dijo que ya est\u00e1bamos preparados para entrar en la tumba, pero que antes era necesario abrir el v\u00f3rtice de energ\u00eda que se encontraba dentro de dicho monumento. Para ello, necesit\u00e1bamos la intervenci\u00f3n de un ser que \u00e9l nos present\u00f3 como \u201cel guardi\u00e1n del lugar\u201d. Nos explic\u00f3 que esta entidad era la \u00fanica capaz de abrir el v\u00f3rtice. Por ende, de su presencia y colaboraci\u00f3n depend\u00eda el \u00e9xito de la pr\u00e1ctica. Seg\u00fan los especialistas, los guardianes tienen una forma antropom\u00f3rfica, carecen de atributos masculinos y femeninos, est\u00e1n hechos de luz y se comunican mentalmente con seres humanos y no humanos. Viven aqu\u00ed desde antes de la llegada del ser humano y les gusta estar cerca de los lugares \u201cpoderosos\u201d. Suelen estar sentados en el suelo y su mirada est\u00e1 siempre fija en la piedra. Para contactarlo, Pierre nos dijo que deb\u00edamos cerrar nuestros ojos y visualizarlo. Con los ojos cerrados, escuch\u00e9 al especialista describirnos lo que \u00e9l estaba visualizando de la siguiente manera:<\/p>\n\n\n\n<p class=\"verse\">El esp\u00edritu tiene forma humana, est\u00e1 hecho de luz y est\u00e1 sentado en el suelo. Est\u00e1 viendo la tumba directamente. Cada uno de vosotros debe pedirle permiso para entrar (Pierre, 6 de mayo de 2018).<\/p>\n\n\n\n<p>Durante este ejercicio de visualizaci\u00f3n, el participante no trata simplemente de imaginar un ser \u201cno humano\u201d, su objetivo es interactuar con \u00e9l sin perder de vista la naturaleza conscientemente fabricada de estos entes generalmente invisibles (Houseman, 2016: 232). Por lo tanto, debe esforzarse por reconocer en este esp\u00edritu a un ser aut\u00f3nomo y din\u00e1mico. Esta clase de interacci\u00f3n es caracter\u00edstica de los rituales neopaganos inspirados del nuevo animismo contempor\u00e1neo en los que los participantes conceden a las entidades convocadas agencia y reflexividad (Rountree, 2015: 1). Pierre consideraba a este esp\u00edritu como un ser capaz de relacionarse con el espacio en el que habitaba, con los seres humanos y no humanos, y consigo mismo.<\/p>\n\n\n\n<p>Unos minutos despu\u00e9s de haber finalizado su discurso, Pierre nos indic\u00f3 que el guardi\u00e1n hab\u00eda accedido a nuestra petici\u00f3n. El v\u00f3rtice de energ\u00eda de la tumba hab\u00eda sido abierto. Luego nos se\u00f1al\u00f3 que a medida que nos adentr\u00e1ramos en la tumba, ir\u00edamos sintiendo un cosquilleo en la piel y sensaciones de fr\u00edo, calor, ligereza y pesadez en las piernas. Dichas sensaciones ser\u00edan a\u00fan m\u00e1s fuertes una vez que hubi\u00e9ramos ingresado a la c\u00e1mara funeraria. El acceso se realiz\u00f3 en fila india, en silencio y despacio. La entrada a dicha estructura desembocaba en un corredor de piedras erguidas que estim\u00e9 en doce metros de largo, un metro de ancho y un metro y cuarto de alto. Para acceder tuvimos que inclinar la parte superior de nuestro cuerpo a casi noventa grados. El pasillo era ligeramente sinuoso y la luz del sol solo iluminaba la entrada, por lo que pronto nos enfrentamos a la oscuridad. Para iluminar el pasillo y evitar caernos en el suelo irregular, los participantes empezaron a encender la linterna de sus tel\u00e9fonos m\u00f3viles. Cuando por fin llegamos a la c\u00e1mara funeraria, pudimos ponernos de pie. La c\u00e1mara ten\u00eda forma circular, med\u00eda unos cinco metros cuadrados y ten\u00eda paredes de dos metros de altura. Pierre fue el \u00faltimo en entrar. Enseguida nos dijo que las paredes de esta c\u00e1mara estaban hechas de piedras levantadas hace diez mil a\u00f1os y que soportaban diez toneladas de piedras y tierra por encima de nuestras cabezas. Luego nos pidi\u00f3 que nos sent\u00e1ramos en el suelo y apoy\u00e1ramos la espalda contra la pared.<\/p>\n\n\n\n<p>A continuaci\u00f3n, nos dijo que guard\u00e1ramos silencio y apag\u00e1ramos las luces de nuestros tel\u00e9fonos m\u00f3viles. Todo el grupo sigui\u00f3 estas instrucciones. En cuanto apagamos los m\u00f3viles, nos vimos envueltos en una oscuridad total. Fue entonces cuando sent\u00ed de repente un sinf\u00edn de sensaciones corporales simult\u00e1neas. El olor a tierra mojada invadi\u00f3 mi nariz y la piel de mis brazos y de mis manos se eriz\u00f3 al instante. Al inhalar, not\u00e9 que el aire al interior de la tumba era muy fr\u00edo y h\u00famedo en comparaci\u00f3n con el aire c\u00e1lido del exterior. Como no ten\u00eda visi\u00f3n alguna a causa de la oscuridad, decid\u00ed cerrar los ojos y palpar las paredes y el suelo de la tumba con las palmas de mis manos. Durante este reconocimiento t\u00e1ctil del nuevo entorno, mis palmas se encontraron con las manos de los participantes que estaban sentados uno a mi lado izquierdo y el otro a mi lado derecho. Al igual que yo, palpaban el suelo y las paredes de la tumba. Durante esta inspecci\u00f3n de la c\u00e1mara funeraria, mis sentidos del o\u00eddo y del tacto empezaron a agudizarse gradualmente. Primero me concentr\u00e9 en mis sensaciones corporales y despu\u00e9s decid\u00ed dirigir mi atenci\u00f3n a las voces de los dem\u00e1s participantes. Algunos susurraban palabras y frases que me resultaban dif\u00edciles de distinguir. Es complicado para m\u00ed determinar cu\u00e1nto dur\u00f3 este momento de reconocimiento sensorial de la tumba. Estar bajo tierra, en total oscuridad y silencio, alter\u00f3 mi sentido de la orientaci\u00f3n espacial y temporal. Mis pensamientos al respecto fueron interrumpidos por la voz de Pierre, la cual reson\u00f3 de repente entre las paredes de la c\u00e1mara funeraria. Con una voz tranquila pronunci\u00f3 las siguientes palabras:<\/p>\n\n\n\n<p class=\"verse\">Estamos aqu\u00ed para volver a reconectar con lo que somos, para redescubrir lo que es esencial en nuestras vidas y poder as\u00ed sentirnos bien con nosotros mismos y con los dem\u00e1s. Este momento, como todos los dem\u00e1s que compartiremos este d\u00eda, ser\u00e1 esencial. Recargar las pilas aqu\u00ed te permitir\u00e1 tomarte un respiro, concentrarte en el momento presente, y experimentar algo que dif\u00edcilmente tendr\u00e1s en tu vida cotidiana (Pierre, 6 de mayo de 2018).<\/p>\n\n\n\n<p>Tras su explicaci\u00f3n, Pierre empez\u00f3 a guiarnos a trav\u00e9s de un ejercicio de respiraci\u00f3n. Se trataba de una t\u00e9cnica meditativa dise\u00f1ada para ayudarnos a centrar nuestra atenci\u00f3n en los problemas f\u00edsicos y emocionales que ten\u00edamos en nuestra vida cotidiana. Nos lo explic\u00f3 as\u00ed:<\/p>\n\n\n\n<p class=\"verse\">Cierra los ojos. Ahora vas a reconectar con lo que eres. Vas a concentrarte en lo esencial de tu vida para recargar tus pilas, sentirte bien contigo mismo y con los dem\u00e1s. Respira hondo y aguanta la respiraci\u00f3n unos segundos. Aprovecha este momento para reflexionar sobre lo que te causa estr\u00e9s, ansiedad, tristeza o enfado. A continuaci\u00f3n, espira suavemente y suelta las emociones negativas. Permanece atento a las sensaciones que siente tu cuerpo (Pierre, 6 de mayo de 2018).<\/p>\n\n\n\n<p>Despu\u00e9s de lo que me parecieron unos minutos, el silencio que reinaba en la c\u00e1mara funeraria fue interrumpido gradualmente por una cacofon\u00eda de palabras susurradas, suspiros e inhalaciones que me recordaron que no estaba sola. En este momento, o\u00ed a dos participantes que estaban frente a mi compartir en voz baja sus impresiones sobre sus sensaciones corporales. Escuch\u00e9 una voz masculina preguntar: \u201c\u00bfSientes el fr\u00edo? \u00bfSon las energ\u00edas?\u201d. Y una voz femenina responder: \u201cEsta aqu\u00ed, el esp\u00edritu del que nos habl\u00f3 Pierre\u201d. La voz de Pierre se oy\u00f3 de nuevo, interrumpiendo los ruidos y los intercambios susurrados. A continuaci\u00f3n, nos dirigi\u00f3 en la repetici\u00f3n de un mantra, \u201cOm\u201d.<\/p>\n\n\n\n<p>Pronunciamos el mantra unas quince veces, luego Pierre nos dijo que guard\u00e1ramos silencio para animarnos una vez m\u00e1s a la autorreflexi\u00f3n sobre nuestras emociones. Tras un momento que me pareci\u00f3 muy largo, nos invit\u00f3 a volver a encender los m\u00f3viles y a levantarnos despacio para no lastimarnos y abandonar la tumba. El encendido sistem\u00e1tico de nuestros m\u00f3viles disolvi\u00f3 de golpe este momento atemporal. La salida de la tumba sigui\u00f3 el mismo protocolo que la entrada. Doblamos nuestro tronco de nuevo para cruzar el pasillo que conduc\u00eda al exterior. Al salir, mis ojos necesitaron un breve momento para adaptarse a la luz del sol. Una vez todos fuera, Pierre nos reuni\u00f3 en c\u00edrculo a un lado del t\u00famulo y nos invit\u00f3 a compartir lo que hab\u00edamos sentido. Florence, una estudiante de psicolog\u00eda que formaba parte del grupo, asoci\u00f3 sus sensaciones corporales a un proceso de adquisici\u00f3n de las \u201cenerg\u00edas\u201d situadas en el interior de la tumba. Lo explic\u00f3 de la siguiente manera:<\/p>\n\n\n\n<p class=\"verse\">Fue una buena idea comenzar el curso aqu\u00ed. Inmediatamente sent\u00ed vibraciones muy fuertes cuando entramos en la tumba. La energ\u00eda que hay dentro es tan fuerte que no puedes hacer otra cosa que dejarte llevar (Florence, 6 de mayo de 2018).<\/p>\n\n\n\n<p>Despu\u00e9s del intercambio de experiencias, Pierre cerr\u00f3 esta primera parte de la pr\u00e1ctica dici\u00e9ndonos que deb\u00edamos dar las gracias a los esp\u00edritus de la naturaleza y de los antiguos druidas que, seg\u00fan \u00e9l, resguardaban la tumba. Algunos participantes susurran un \u201cgracias\u201d, otros no emitieron ninguna palabra, pero cerraron los ojos y bajaron ligeramente la cabeza en una actitud reverencial. Luego Pierre nos dijo que ten\u00edamos que regresar al aparcamiento para recoger los coches y dirigirnos hacia los megalitos de Carnac, donde repetir\u00edamos los mismos ejercicios, pero con una modificaci\u00f3n importante. En lugar de visitar otra tumba, ir\u00edamos al Gigante de Manio donde cada uno tendr\u00eda un momento en solitario para tocar la piedra.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Identificaci\u00f3n y an\u00e1lisis de elementos que conforman un aprendizaje sensorial progresivo<\/h2>\n\n\n\n<p class=\"abstract\">Como lo he ilustrado anteriormente, las pr\u00e1cticas constan de distintas etapas organizadas por un protocolo ritual a trav\u00e9s del cual se implementa una pedagog\u00eda som\u00e1tica. Esta conlleva el aprendizaje de un lenguaje sensorial diferente al que el practicante est\u00e1 acostumbrado en su vida cotidiana. El lenguaje al que me refiero moviliza un marco interpretativo espec\u00edfico relacionado con las sensaciones corporales y una jerarqu\u00eda particular de significados. As\u00ed, las sensaciones de fr\u00edo o calor se reinterpretan como evidencia de la penetraci\u00f3n de energ\u00edas megal\u00edticas en el cuerpo. Las sensaciones de pesadez en los miembros son interpretadas por los participantes como pruebas tangibles de la presencia de estas energ\u00edas. El tacto se valora como un sentido primordial para experimentar la eficacia de estas pr\u00e1cticas (Figura 5).<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-5-Deteccion-tactil-scaled.jpeg\" itemprop=\"contentUrl\" data-size=\"3024x4032\" data-index=\"0\" data-caption=\"Figura 5: Detecci\u00f3n t\u00e1ctil de la energ\u00eda de un megalito (Dansac, W\u00e9ris, 2023).\" >\n                                <img decoding=\"async\" src=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-5-Deteccion-tactil-scaled.jpeg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Figura 5: Detecci\u00f3n t\u00e1ctil de la energ\u00eda de un megalito (Dansac, W\u00e9ris, 2023).<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>Para que los participantes logren apropiarse de este lenguaje sensorial deben respetar tres tareas distintas que se yuxtaponen durante los ejercicios individuales y colectivos. Cada participante debe tomar \u201cconciencia de su cuerpo\u201d consider\u00e1ndolo no como un objeto, sino como un \u201ccuerpo vivo y sensible\u201d, capaz de interactuar con seres humanos y no humanos (Andrieu, 2010: 349). Al mismo tiempo, cada uno debe \u201cdespertar su cuerpo\u201d incit\u00e1ndolo a \u201csentir\u201d e interactuar con energ\u00edas invisibles (Nizard, 2020: 285). Simult\u00e1neamente, cada participante debe desarrollar su \u201catenci\u00f3n corporal\u201d (Depraz, 2014: 98) tomando conciencia del funcionamiento de su cuerpo, sus sensaciones corporales, su respiraci\u00f3n y sus pensamientos. Para realizar a la vez estas tres tareas, el participante debe hacer todos los ejercicios (nadie puede tomar el rol de espectador), tener en cuenta las instrucciones del especialista, imitar los movimientos y gestos de los dem\u00e1s y concentrarse en sus sensaciones corporales. Adem\u00e1s, debe establecer relaciones precisas entre los patrones kinest\u00e9sicos y el significado que se les da (Figura 6).<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-6-Tareas.jpg\" itemprop=\"contentUrl\" data-size=\"1512x1045\" data-index=\"0\" data-caption=\"Figura 6: Tareas simult\u00e1neas encaminadas al desarrollo de la atenci\u00f3n corporal.\" >\n                                <img decoding=\"async\" src=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-6-Tareas.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Figura 6: Tareas simult\u00e1neas encaminadas al desarrollo de la atenci\u00f3n corporal.<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>Por lo tanto, esta pedagog\u00eda tambi\u00e9n incluye la incorporaci\u00f3n de imaginarios som\u00e1ticos que se formulan asociando una t\u00e9cnica corporal a una sensaci\u00f3n corporal espec\u00edfica (Csordas, 1990: 18). Estos imaginarios son proporcionados por los especialistas (Tabla 1). Por ejemplo, antes de pedir a los participantes que caminaran lentamente hacia un megalito, Jean (observaci\u00f3n del 5 de marzo de 2016), Stephan (observaci\u00f3n del 20 de mayo de 2017) y Peter (observaci\u00f3n del 5 de mayo de 2018) les advirtieron a los participantes que muy probablemente experimentar\u00edan una sensaci\u00f3n de pesadez en las extremidades superiores e inferiores. Antes de tocar un megalito o entrar a una tumba prehist\u00f3rica, tambi\u00e9n les indicaron que podr\u00edan sentir sensaciones de hormigueo y de pinchazos en las partes del cuerpo que estuvieran en contacto directo con las piedras. Los datos recogidos muestran que los especialistas evocan constantemente estos imaginarios, desde el inicio hasta el final de las pr\u00e1cticas. En primer lugar, los participantes, que en su mayor\u00eda son principiantes, descubren y asimilan estos imaginarios. Luego los reproducen poni\u00e9ndolos en palabras para compartir sus sensaciones corporales con los dem\u00e1s. Al transmitir estos imaginarios som\u00e1ticos, los especialistas moldean las experiencias corporales de los participantes, los animan a adoptar una actitud reflexiva y les incitan a asociar sus sensaciones con la presencia de las entidades convocadas. En otras palabras, ellos est\u00e1n activamente guiando, entrenando y significando las experiencias de los participantes. El aprendizaje de estos imaginarios som\u00e1ticos permite a mis interlocutores inscribir sus cuerpos en el lenguaje sensorial de estas pr\u00e1cticas.<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/tabla_1-accion_imaginario.jpg\" itemprop=\"contentUrl\" data-size=\"1676x772\" data-index=\"0\" data-caption=\"Tabla 1: Ejemplo de imaginarios som\u00e1ticos implementados en las pr\u00e1cticas.\" >\n                                <img decoding=\"async\" src=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/tabla_1-accion_imaginario.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Tabla 1: Ejemplo de imaginarios som\u00e1ticos implementados en las pr\u00e1cticas.<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>La pr\u00e1ctica de la visualizaci\u00f3n del \u201cesp\u00edritu del lugar\u201d y de las \u201cenerg\u00edas de los megalitos\u201d es una t\u00e9cnica meditativa que estimula los sentidos de los participantes y que tambi\u00e9n participa en la elaboraci\u00f3n e interpretaci\u00f3n de sus sensaciones corporales. Cuando se practica la visualizaci\u00f3n en los rituales neopaganos contempor\u00e1neos, \u201cel paisaje f\u00edsico se traza en un marco imaginativo, como una meditaci\u00f3n guiada en la que los participantes se visualizan a s\u00ed mismos caminando por un lugar imaginario o interactuando con seres no humanos\u201d (Butler, 2020: 624). Las visualizaciones pueden tomar la forma de seres no humanos, como los esp\u00edritus de la naturaleza y las energ\u00edas. Pero en el relato etnogr\u00e1fico presentado, su funci\u00f3n no se restringe a esto. Los participantes son incitados a visualizar las energ\u00edas como entes capaces de entrar en contacto f\u00edsico con su cuerpo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"small-caps\">A manera de conclusi\u00f3n: \u00bfc\u00f3mo comprender la relaci\u00f3n entre la pedagog\u00eda som\u00e1tica implementada y la eficacia atribuida a las pr\u00e1cticas analizadas? <\/span><\/h2>\n\n\n\n<p class=\"abstract\">La eficacia que Michael Houseman (2016: 232) atribuye a las pr\u00e1cticas New Age y neopaganas reside en su capacidad de permitir al participante experimentar una \u201cidentidad refractada\u201d. Al esforzarse por ejecutar los movimientos corporales y experimentar los estados emocionales de \u201cotros\u201d (por ejemplo, los druidas mencionados por Pierre), los practicantes act\u00faan como sujetos divididos entre dos identidades diferentes. Por un lado, los \u201cdruidas\u201d que supuestamente ejecutaron y experimentaron estas pr\u00e1cticas hace milenios y, por el otro, los contempor\u00e1neos que buscan sentir en su cuerpo los efectos de estas actividades (Houseman, 2010: 65). Este proceso solo puede lograrse estableciendo un r\u00e9gimen de atenci\u00f3n particular en el que cada participante debe implicarse f\u00edsica y emocionalmente en las realidades que estas pr\u00e1cticas ponen en valor, pero sin perder de vista el car\u00e1cter conscientemente fabricado de estas realidades. La identidad refractada se produce cuando el participante se esfuerza por experimentar una experiencia \u201cextraordinaria\u201d<a class=\"anota\" id=\"anota16\" data-footnote=16>16<\/a> en la que se considera a s\u00ed mismo y a su cuerpo como extraordinarios, sin perder de vista que es una persona ordinaria con un cuerpo ordinario, y que esta experiencia ha sido concebida y organizada por el especialista que gu\u00eda la pr\u00e1ctica.<\/p>\n\n\n\n<p>Kathrine Rountree (2004) ha elaborado una definici\u00f3n similar de la eficacia de las pr\u00e1cticas New Age y neopaganas. En su obra sobre las espiritualidades asociadas a la \u201cDiosa\u201d en Nueva Zelanda, la autora subraya que los participantes son conscientes del rol del especialista en la fabricaci\u00f3n no solo de las pr\u00e1cticas rituales, sino tambi\u00e9n de los imaginarios y los discursos que moldean sus significados. Pero para los practicantes, esto no disminuye en nada los efectos de estas actividades, ya que al participar en estos rituales experimentan sensaciones corporales que asocian a estados afectivos de \u201crenovaci\u00f3n\u201d y \u201cconexi\u00f3n con la naturaleza\u201d. Seg\u00fan Michael Houseman (2016: 223), el car\u00e1cter fabricado de las pr\u00e1cticas neopaganas y New Age no afecta la experiencia de los participantes, porque al interior de estas sus intenciones y sus acciones est\u00e1n orientadas en direcciones opuestas. En lugar de asociar sus comportamientos a su estado de \u00e1nimo, estos derivan del cumplimiento de las acciones encomendadas por el especialista que, en el caso de nuestro estudio, implementa una pedagog\u00eda som\u00e1tica. Por ejemplo, en el momento de la ejecuci\u00f3n de ciertas acciones estipuladas en el relato etnogr\u00e1fico presentado, como es el caso de los ejercicios de autorreflexi\u00f3n al interior de la tumba prehist\u00f3rica, el participante se esfuerza por experimentar un estado afectivo designado por Pierre el especialista como \u201cde armon\u00eda\u201d o \u201cde realineamiento\u201d. En este contexto, el comportamiento de los actores no expresa su estado de \u00e1nimo, ya que este se encuentra dictado por los discursos del especialista. Por ende, las frases \u201creactiva la energ\u00eda vital\u201d, \u201creconecta con lo que eres\u201d o \u201csi\u00e9ntete bien contigo mismo\u201d se convierten en prescripciones que tienen un valor y una eficacia intr\u00ednsecos a los que los participantes buscan acceder (Moisseeff y Houseman, 2020: 13).<\/p>\n\n\n\n<p>La relaci\u00f3n entre la eficacia de las pr\u00e1cticas y el protocolo que siguen los participantes es a\u00fan m\u00e1s clara en el estudio de Rountree (2006: 106-107) sobre las pr\u00e1cticas neopaganas en Malta. Para los que participan, el contacto de su piel con la superficie de los templos neol\u00edticos malteses produce efectos \u201cespirituales\u201d independientemente de las sensaciones corporales experimentadas. Al tocar estas estructuras, su cuerpo y el templo \u201cse alinean\u201d y se fusionan convirti\u00e9ndose en un solo objeto \u201csagrado\u201d. La interacci\u00f3n cuerpo a cuerpo con una \u201cenerg\u00eda sagrada\u201d est\u00e1 garantizada por los principios que organizan dichas pr\u00e1cticas, en las cuales no hay imaginarios som\u00e1ticos. No hay incertidumbre o duda para los participantes, ya que cualquier sensaci\u00f3n corporal causada por el contacto de la piel con la superficie del templo se considera como prueba de la presencia de \u201cenerg\u00edas\u201d. El efecto es t\u00e1cito e inequ\u00edvoco: al tocar el templo y ser tocados por la superficie de este, los participantes establecen el tan deseado encuentro con las energ\u00edas.<\/p>\n\n\n\n<p>Si el tacto participa de manera sustancial en la verificaci\u00f3n de la veracidad de una experiencia \u201cextraordinaria\u201d es porque se ha convertido en un nuevo estilo de comunicaci\u00f3n social y comunitaria del yo. Desde los a\u00f1os noventa, Michel Maffesoli ha explorado c\u00f3mo el \u201cestilo t\u00e1ctil\u201d participa de una transmutaci\u00f3n de los valores y establece otra relaci\u00f3n con la alteridad. En este sentido, subraya que el otro \u201ces aquel al que puedo tocar y que me puede tocar\u201d (Maffesoli, 1993: 70). Esta definici\u00f3n abre la puerta a una definici\u00f3n del \u201cotro\u201d como aquel al que afecto y que me afecta. La eficacia de las pr\u00e1cticas analizadas reside en la posibilidad que le otorgan a cada participante de establecer una interacci\u00f3n sensorial rec\u00edproca con el \u201cotro\u201d, sea este lo divino, la energ\u00eda o el esp\u00edritu de la naturaleza. La pedagog\u00eda som\u00e1tica identificada le permite a cada participante aprender a tocar algo que es visible para ser tocado por algo que es invisible, extraordinario e infinito.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bibliograf\u00eda<\/h2>\n\n\n\n<p class=\"bibliography\">Aldred, Lisa (2000). \u201cPlastic Shamans and Astroturf Sun Danses: New Age Commercialization of Native American Spirituality\u201d, <em>American Indian Quarterly<\/em>, 24, (3), pp. 329-352.<\/p>\n\n\n\n<p class=\"bibliography\">Anderson, Benedict (1983). <em>Imagined Communities<\/em>: <em>Reflections on the Origin and Spread of Nationalism. <\/em>Londres: Verso.<\/p>\n\n\n\n<p class=\"bibliography\">Andrieu, Bernard (2010). <em>Philosophie du corps, exp\u00e9riences, interactions et \u00e9cologie corporelle<\/em>. Par\u00eds: Vrin.<\/p>\n\n\n\n<p class=\"bibliography\">Blacking, John (ed.) (1977). \u201cTowards an Anthropology of the Body\u201d, en <em>The Anthropology of the Body<\/em>. Londres: Academic Press, pp. 1-28<\/p>\n\n\n\n<p class=\"bibliography\">Boismoreau, \u00c9mile (1917). \u201cNotes \u00e0 propos de l\u2019utilisation th\u00e9rapeutique des m\u00e9galithes dans la Bretagne\u201d, <em>Bulletin de la Soci\u00e9t\u00e9 Pr\u00e9historique de France<\/em>, 14, (3), pp.158-160.<\/p>\n\n\n\n<p class=\"bibliography\">Bourdieu, Pierre (1977). <em>Outline of a Theory of Practice<\/em>. Cambridge: Cambridge University Press.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 y Jean-Claude Passeron (1977). <em>Reproduction in Education Society and Culture<\/em>. Londres y Beverly Hills: Sage.<\/p>\n\n\n\n<p class=\"bibliography\">Butler, Jenny (2020). \u201cContemporary Pagan Pilgrimage: Ritual and Re-Storying in the Irish Landscape\u201d, <em>Numen<\/em>, 67, (5-6), pp. 613-36.<\/p>\n\n\n\n<p class=\"bibliography\">Castaneda, Carlos (1997). <em>Magical Passes:<\/em> <em>The Practical Wisdom of the Shamans of Ancient Mexico<\/em>. Nueva York: Harper Perennial.<\/p>\n\n\n\n<p class=\"bibliography\">Csordas, Thomas J. (1990). \u201cEmbodiment as a Paradigm in Anthropology\u201d, <em>Ethos<\/em>, 18, (1), pp. 5-47.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (1993). \u201cSomatic Modes of Attention\u201d, <em>Cultural Anthropology<\/em>, 8, (2), pp. 135-156.<\/p>\n\n\n\n<p class=\"bibliography\">Dansac, Yael (2020). \u201cEmbodied Engagements with the Megaliths of Carnac: Somatic Experience, Somatic Imagery, and Bodily Techniques in Contemporary Spiritual Practices\u201d, <em>Journal of Religion in Europe<\/em>, 13, (3-4), pp. 300-324.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (2021). \u201cThe Enchantment of Archaeological Sites and the Quest for Personal Transformation\u201d, <em>Ciencias Sociales y Religion\/Ci\u00eancias Sociais e Religi\u00e3o<\/em>, 23, pp. 1-22.<\/p>\n\n\n\n<p class=\"bibliography\">De la Torre Castellanos, Ren\u00e9e y Cristina Guti\u00e9rrez Z\u00fa\u00f1iga (2011). \u201cLa mexicanidad y los circuitos New Age. \u00bfUn hibridismo sin fronteras o m\u00faltiples estrategias de s\u00edntesis espiritual?\u201d, <em>Archives des Sciences Sociales des Religions<\/em>, 153, pp. 183-206.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 y Cristina Guti\u00e9rrez Z\u00fa\u00f1iga (2016). \u201cEl Temazcal: un ritual prehisp\u00e1nico transculturalizado por redes alternativas espirituales\u201d, <em>Ciencias Sociales y Religion\/Ci\u00eancias Sociais e Religi\u00e3o<\/em>, 18, (24), pp. 153-172.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014, Cristina Guti\u00e9rrez Z\u00fa\u00f1iga y Yael Dansac (2021). \u201cLos efectos culturales de la creatividad ritual del neopaganismo\u201d, <em>Ciencias Sociales y Religion\/Ci\u00eancias Sociais e Religi\u00e3o<\/em>, 23, pp. 1-22.<\/p>\n\n\n\n<p class=\"bibliography\">Depraz, Natalie (2014). <em>Attention en vigilance. \u00c0 la crois\u00e9e de la ph\u00e9nom\u00e9nologie et des sciences sociales<\/em>. Par\u00eds: Presses Universitaires de France.<\/p>\n\n\n\n<p class=\"bibliography\">Dupuis, David (2018). \u201cApprendre \u00e0 voir l\u2019invisible. P\u00e9dagogie visionnaire et socialisation des hallucinations dans un centre chamanique d\u2019Amazonie p\u00e9ruvienne\u201d, <em>Cahiers d\u2019Anthropologie Sociale<\/em>, 2, (17), pp. 20-42<\/p>\n\n\n\n<p class=\"bibliography\">Durkheim, \u00c9mile (1992) [1902]. <em>L\u2019\u00e9ducation morale<\/em>. Par\u00eds: Presses Universitaires de France.<\/p>\n\n\n\n<p class=\"bibliography\">Harvey, Graham (2005). <em>Animism: Respecting the Living World<\/em>. Londres: Hurst.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (ed.) (2013). The <em>Handbook of Contemporary Animism<\/em>. Londres: Routledge.<\/p>\n\n\n\n<p class=\"bibliography\">Heelas, Paul (2009). \u201cSpiritualities of Life\u201d, en Peter Clarke (ed.). <em>The Oxford Handbook of the Sociology of Religion<\/em>. Oxford: Oxford University Press, pp. 758-782,<\/p>\n\n\n\n<p class=\"bibliography\">Houseman, Michael (2002). \u201cQu\u2019est-ce qu\u2019un rituel&nbsp;?\u201d, <em>L\u2019Autre<\/em>, 3, (3), pp. 533-538.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (2010) \u201cDes rituels contemporains de premi\u00e8re menstruation\u201d, <em>Ethnologie Fran\u00e7aise<\/em>, 40, (1), pp. 57-66.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (2016). \u201cComment comprendre l\u2019esth\u00e9tique affect\u00e9e des c\u00e9r\u00e9monies New Age et n\u00e9opa\u00efennes ?\u201d, <em>Archives de Sciences Sociales des Religions<\/em>, 174, pp. 213-237.<\/p>\n\n\n\n<p class=\"bibliography\">Howes, David (ed.) (2018). \u201cIntroduction: On the Geography and Anthropology of the Senses\u201d, en <em>Senses and Sensations: Critical and Primary Sources. Geography and Anthropology.<\/em> Londres: Bloomsbury, pp. 1-22.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (2019). \u201cMultisensory Anthropology\u201d, <em>Annual Review of Anthropology<\/em>, 48, (1), pp. 17-28.<\/p>\n\n\n\n<p class=\"bibliography\">Ishii, Miho (2012). \u201cActing with Things: Self-poiesis, Actuality, and Contingency in the Formation of Divine Worlds\u201d, <em>Journal of Ethnographic Theory<\/em>, 2, (2), pp. 371-388.<\/p>\n\n\n\n<p class=\"bibliography\">Jamison, Ian (2011). \u201cEmbodied Ethics and Contemporary Paganism\u201d<em>.<\/em> Tesis de doctorado. Milton: The Open University.<\/p>\n\n\n\n<p class=\"bibliography\">Le Breton, David (2010). <em>Cuerpo sensible<\/em>. Santiago de Chile: Ediciones Metales Pesados.<\/p>\n\n\n\n<p class=\"bibliography\">L\u00e9vi-Strauss, Claude (1962). <em>La Pens\u00e9e Sauvage<\/em>. Par\u00eds: Plon.<\/p>\n\n\n\n<p class=\"bibliography\">Lombardi, Denise (2023). <em>Le n\u00e9o-chamanisme. Une religion qui monte ?<\/em> Par\u00eds: Editions du Cerf.<\/p>\n\n\n\n<p class=\"bibliography\">Maffesoli, Michel (1993). <em>La contemplation du monde, figures du style communautaire<\/em>. Par\u00eds: Grasset.<\/p>\n\n\n\n<p class=\"bibliography\">Mauss, Marcel (1950). <em>La notion des techniques du Corps<\/em>. Par\u00eds: Presses Universitaires de France.<\/p>\n\n\n\n<p class=\"bibliography\">Mazariegos Herrera, Hilda Mar\u00eda Cristina (2022). \u201cEl diario de campo encarnado. Apuntes para una propuesta metodol\u00f3gica para el estudio de las emociones desde y con el cuerpo\u201d, en F. Jacobo y M. Mart\u00ednez-Moreno (eds.). <em>Las emociones de ida y vuelta. Experiencia etnogr\u00e1fica, m\u00e9todo y conocimiento antropol\u00f3gico<\/em>. M\u00e9xico: <span class=\"small-caps\">unam<\/span>, pp. 335-352.<\/p>\n\n\n\n<p class=\"bibliography\">Merleau-Ponty, Maurice (1945). <em>Ph\u00e9nom\u00e9nologie de la perception. <\/em>Par\u00eds: Gallimard.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (1964). <em>Le visible et l\u2019invisible<\/em>. Par\u00eds: Gallimard.<\/p>\n\n\n\n<p class=\"bibliography\">Meyer, Birgit (2006). <em>Religious Sensations: Why Media, Aesthetics and Power Matter in the Study of Contemporary Religion.<\/em> \u00c1msterdam: Vrije University.<\/p>\n\n\n\n<p class=\"bibliography\">Moisseeff, Marika y Michael Houseman (2020).&nbsp;\u201cL\u2019orchestration rituelle du partage des \u00e9motions et ses ressorts interactionnels\u201d, en L. Kaufmann y L. Qu\u00e9r\u00e9 (dirs.). <em>Les \u00e9motions collectives<\/em>. Par\u00eds: <span class=\"small-caps\">ehess<\/span>, pp. 133-168.<\/p>\n\n\n\n<p class=\"bibliography\">Mossi\u00e8re, G\u00e9raldine (2018). \u201cDes esprits et des hommes : regard anthropologique sur le sujet spirituel\u201d, <em>Th\u00e9ologiques<\/em>, 26, (2), pp. 59-80.<\/p>\n\n\n\n<p class=\"bibliography\">Nizard, Caroline (2020). \u201cS\u2019ac-corps-der, approfondissement de l\u2019attention corporelle dans les pratiques de yoga\u201d, en B. Andrieu (ed.). <em>Manuel d\u2019emersiologie. Apprends le langage du corps<\/em>. San Giovanni: Mimesis, pp. 272-340.<\/p>\n\n\n\n<p class=\"bibliography\">Pierini, Emily (2016). \u201cBecoming a Spirit Medium: Initiatory Learning and the Self in the Vale do Amanhecer\u201d,<em> Ethnos<\/em>, 81, (2), pp. 290-314<\/p>\n\n\n\n<p class=\"bibliography\">\u2014, Alberto Groisman y Diana Espirito Santo (2023). <em>Other Worlds, Other Bodies. Embodied Epistemologies and Ethnographies of Healing<\/em>. Nueva York y Oxford: Berghahn.<\/p>\n\n\n\n<p class=\"bibliography\">Pike, Sarah (2001). <em>Earthly Bodies, Magical Selves: Contemporary Pagans and the Search for Community<\/em>. Berkeley: University of California Press.<\/p>\n\n\n\n<p class=\"bibliography\">Pink, Sarah (2009). <em>Doing Sensory Ethnography<\/em>. Londres: Sage.<\/p>\n\n\n\n<p class=\"bibliography\">Rountree, Kathryn (2006). \u201cPerforming the Divine: Neo-Pagan Pilgrims and Embodiment at Sacred Sites\u201d, <em>Body &amp; Society<\/em>, 12, (4), pp. 95-115.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (2004). <em>Embracing the Witch and the Goddess: Feminist Ritual-Makers in New Zealand<\/em>. Londres: Routledge.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (ed.) (2015). \u201cIntroduction. Context is Everything: Plurality and Paradox in Contemporary European Paganisms\u201d, en <em>Contemporary Pagan and Native Faith Movements in Europe. Colonialist and Nationalist Impulses<\/em>. Nueva York y Oxford: Berghahn, pp.1-23.<\/p>\n\n\n\n<p class=\"bibliography\">Samudra, Jaida Kim (2008). \u201cMemory in Our Body: Thick Participation and the Translation of Kinesthetic Experience\u201d, <em>American Ethnologist<\/em>, 35, (4), pp. 665-681.<\/p>\n\n\n\n<p class=\"bibliography\">Turner, Victor (1986). \u201cDewey, Dilthey and Drama: An Essay in the Anthropology of Experience\u201d, en Victor Turner y Edward Bruner (eds.).<em> The Anthropology of Experience<\/em>. Chicago: University of Illinois Press, pp. 33-44.<\/p>\n\n\n\n<p class=\"bibliography\">Whitehead, Amy (2018). <em>Religious Objects. Uncomfortable Relations and an Ontological Turn to Things<\/em>. Londres: Taylor and Francis.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-dots\"\/>\n\n\n\n<p class=\"abstract\"><em>Yael Dansac<\/em> (Ciudad de M\u00e9xico, 1984) es investigadora posdoctoral en el Centro Interdisciplinario de Estudio de las Religiones y de la Laicidad de la Universidad Libre de Bruselas. Es doctora en Antropolog\u00eda Social y Etnolog\u00eda por la \u00c9cole des Hautes \u00c9tudes en Sciences Sociales. Ha llevado a cabo investigaciones etnogr\u00e1ficas en M\u00e9xico, Francia, B\u00e9lgica y Reino Unido. Sus temas de estudio incluyen interacciones rituales entre seres humanos y no-humanos, religi\u00f3n y ecolog\u00eda, antropolog\u00eda del cuerpo y sacralizaci\u00f3n contempor\u00e1nea de sitios arqueol\u00f3gicos. Fue investigadora visitante en la Universidad de Glasgow y becaria del programa europeo de excelencia en la investigaci\u00f3n Marie Sklodowska-Curie Actions. Entre sus numerosas publicaciones destaca el libro que coedit\u00f3 con Jean Chamel intitulado <em>Relating with More-than-Humans: Interbeing Rituality in a Living Word<\/em> (Nueva York: Palgrave Macmillan, 2022).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O artigo exp\u00f5e um processo de aprendizado som\u00e1tico progressivo que visa \u00e0 produ\u00e7\u00e3o de um corpo sens\u00edvel capaz de interagir com agentes n\u00e3o humanos promovidos em pr\u00e1ticas espirituais inspiradas na Nova Era e no neopaganismo. Os rituais contempor\u00e2neos realizados no s\u00edtio arqueol\u00f3gico de Carnac, na Fran\u00e7a, s\u00e3o tomados como base etnogr\u00e1fica e emp\u00edrica, considerando-os como espa\u00e7os de aprendizagem sensorial em que os participantes desenvolvem sua aten\u00e7\u00e3o corporal para verificar a efic\u00e1cia das t\u00e9cnicas implementadas. A an\u00e1lise mostra que os principais elementos que comp\u00f5em a pedagogia som\u00e1tica aplicada s\u00e3o o aprendizado de uma linguagem sensorial alternativa, a execu\u00e7\u00e3o de t\u00e9cnicas corporais, a pr\u00e1tica da visualiza\u00e7\u00e3o e a incorpora\u00e7\u00e3o de imagin\u00e1rios som\u00e1ticos.<\/p>","protected":false},"author":4,"featured_media":38959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[1293,1297,383,1294,1298,1295,1296],"coauthors":[551],"class_list":["post-38956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-9","tag-aprendizaje-sensorial","tag-carnac","tag-espiritualidad","tag-experiencia-somatica","tag-francia","tag-megalitos","tag-neopaganismo","personas-dansac-yael","numeros-1267"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas &#8211; Encartes<\/title>\n<meta name=\"description\" content=\"Los rituales contempor\u00e1neos realizados en el sitio arqueol\u00f3gico de Carnac, Francia como base etnogr\u00e1fica de espacios de aprendizaje sensorial\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encartes.mx\/pt\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas &#8211; Encartes\" \/>\n<meta property=\"og:description\" content=\"Los rituales contempor\u00e1neos realizados en el sitio arqueol\u00f3gico de Carnac, Francia como base etnogr\u00e1fica de espacios de aprendizaje sensorial\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encartes.mx\/pt\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/\" \/>\n<meta property=\"og:site_name\" content=\"Encartes\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-20T16:47:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T20:08:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arthur Ventura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Arthur Ventura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"39 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Arthur Ventura\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/\"},\"author\":{\"name\":\"Arthur Ventura\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/person\/97215bba1729028a4169cab07f8e58ef\"},\"headline\":\"Aprender a ver y sentir lo invisible: pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas\",\"datePublished\":\"2024-09-20T16:47:33+00:00\",\"dateModified\":\"2024-09-25T20:08:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/\"},\"wordCount\":9281,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/encartes.mx\/#organization\"},\"image\":{\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg\",\"keywords\":[\"aprendizaje sensorial\",\"Carnac\",\"espiritualidad\",\"experiencia som\u00e1tica\",\"Francia\",\"megalitos\",\"neopaganismo\"],\"articleSection\":[\"Realidades socioculturales\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/\",\"url\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/\",\"name\":\"Pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas &#8211; Encartes\",\"isPartOf\":{\"@id\":\"https:\/\/encartes.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg\",\"datePublished\":\"2024-09-20T16:47:33+00:00\",\"dateModified\":\"2024-09-25T20:08:55+00:00\",\"description\":\"Los rituales contempor\u00e1neos realizados en el sitio arqueol\u00f3gico de Carnac, Francia como base etnogr\u00e1fica de espacios de aprendizaje sensorial\",\"breadcrumb\":{\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#primaryimage\",\"url\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg\",\"contentUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/encartes.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprender a ver y sentir lo invisible: pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/encartes.mx\/#website\",\"url\":\"https:\/\/encartes.mx\/\",\"name\":\"Encartes\",\"description\":\"Revista digital multimedia\",\"publisher\":{\"@id\":\"https:\/\/encartes.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/encartes.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/encartes.mx\/#organization\",\"name\":\"Encartes Antropol\u00f3gicos\",\"url\":\"https:\/\/encartes.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"contentUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"width\":338,\"height\":306,\"caption\":\"Encartes Antropol\u00f3gicos\"},\"image\":{\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/person\/97215bba1729028a4169cab07f8e58ef\",\"name\":\"Arthur Ventura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/person\/image\/8a45818ea77a67a00c058d294424a6f6\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e8ff614b2fa0d91ff6c65f328a272c53?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e8ff614b2fa0d91ff6c65f328a272c53?s=96&d=identicon&r=g\",\"caption\":\"Arthur Ventura\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas &#8211; Encartes","description":"Los rituales contempor\u00e1neos realizados en el sitio arqueol\u00f3gico de Carnac, Francia como base etnogr\u00e1fica de espacios de aprendizaje sensorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encartes.mx\/pt\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/","og_locale":"pt_BR","og_type":"article","og_title":"Pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas &#8211; Encartes","og_description":"Los rituales contempor\u00e1neos realizados en el sitio arqueol\u00f3gico de Carnac, Francia como base etnogr\u00e1fica de espacios de aprendizaje sensorial","og_url":"https:\/\/encartes.mx\/pt\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/","og_site_name":"Encartes","article_published_time":"2024-09-20T16:47:33+00:00","article_modified_time":"2024-09-25T20:08:55+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg","type":"image\/jpeg"}],"author":"Arthur Ventura","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Arthur Ventura","Est. tempo de leitura":"39 minutos","Written by":"Arthur Ventura"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#article","isPartOf":{"@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/"},"author":{"name":"Arthur Ventura","@id":"https:\/\/encartes.mx\/#\/schema\/person\/97215bba1729028a4169cab07f8e58ef"},"headline":"Aprender a ver y sentir lo invisible: pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas","datePublished":"2024-09-20T16:47:33+00:00","dateModified":"2024-09-25T20:08:55+00:00","mainEntityOfPage":{"@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/"},"wordCount":9281,"commentCount":0,"publisher":{"@id":"https:\/\/encartes.mx\/#organization"},"image":{"@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg","keywords":["aprendizaje sensorial","Carnac","espiritualidad","experiencia som\u00e1tica","Francia","megalitos","neopaganismo"],"articleSection":["Realidades socioculturales"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/","url":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/","name":"Pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas &#8211; Encartes","isPartOf":{"@id":"https:\/\/encartes.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#primaryimage"},"image":{"@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#primaryimage"},"thumbnailUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg","datePublished":"2024-09-20T16:47:33+00:00","dateModified":"2024-09-25T20:08:55+00:00","description":"Los rituales contempor\u00e1neos realizados en el sitio arqueol\u00f3gico de Carnac, Francia como base etnogr\u00e1fica de espacios de aprendizaje sensorial","breadcrumb":{"@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#primaryimage","url":"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg","contentUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/encartes.mx\/dansac-etnografia-aprendizaje-somatico-new-age-espiritualidad-francia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/encartes.mx\/"},{"@type":"ListItem","position":2,"name":"Aprender a ver y sentir lo invisible: pedagog\u00eda som\u00e1tica en pr\u00e1cticas espirituales alternativas"}]},{"@type":"WebSite","@id":"https:\/\/encartes.mx\/#website","url":"https:\/\/encartes.mx\/","name":"Encartes","description":"Revista multim\u00eddia digital","publisher":{"@id":"https:\/\/encartes.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encartes.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/encartes.mx\/#organization","name":"Inser\u00e7\u00f5es antropol\u00f3gicas","url":"https:\/\/encartes.mx\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/","url":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","contentUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","width":338,"height":306,"caption":"Encartes Antropol\u00f3gicos"},"image":{"@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/encartes.mx\/#\/schema\/person\/97215bba1729028a4169cab07f8e58ef","name":"Arthur Ventura","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/encartes.mx\/#\/schema\/person\/image\/8a45818ea77a67a00c058d294424a6f6","url":"https:\/\/secure.gravatar.com\/avatar\/e8ff614b2fa0d91ff6c65f328a272c53?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e8ff614b2fa0d91ff6c65f328a272c53?s=96&d=identicon&r=g","caption":"Arthur Ventura"}}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/encartes.mx\/wp-content\/uploads\/2024\/09\/Figura-1-scaled.jpeg","_links":{"self":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/posts\/38956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/comments?post=38956"}],"version-history":[{"count":9,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/posts\/38956\/revisions"}],"predecessor-version":[{"id":39165,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/posts\/38956\/revisions\/39165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/media\/38959"}],"wp:attachment":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/media?parent=38956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/categories?post=38956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/tags?post=38956"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/coauthors?post=38956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}