{"id":35960,"date":"2022-09-21T18:33:01","date_gmt":"2022-09-21T18:33:01","guid":{"rendered":"https:\/\/encartes.mx\/?post_type=ensayos-fotograficos&#038;p=35960"},"modified":"2023-09-16T19:53:22","modified_gmt":"2023-09-16T19:53:22","slug":"alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos","status":"publish","type":"ensayos-fotograficos","link":"https:\/\/encartes.mx\/pt\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/","title":{"rendered":"O muro de fronteira em Tijuana. Tra\u00e7os fotogr\u00e1ficos das ofertas\/interven\u00e7\u00f5es art\u00edsticas em mem\u00f3ria de migrantes mortos 1999-2021"},"content":{"rendered":"\n<p><strong>Guillermo Alonso Meneses<\/strong><\/p>\n\n\n\n<p class=\"has-small-font-size\"><em>El Colegio de la Frontera Norte, Tijuana, M\u00e9xico.<\/em><\/p>\n\n\n\n<p class=\"has-small-font-size\"><span class=\"small-caps\">orcid<\/span>: <\/p>\n\n\n\n<div class=\"wp-block-group alignwide\" id=\"articulo\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-1 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-01.jpg\" itemprop=\"contentUrl\" data-size=\"632x417\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-01.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-02.jpg\" itemprop=\"contentUrl\" data-size=\"1976x1327\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-02.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\"><\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em>Guillermo Alonso Meneses, Playas de Tijuana<\/em><\/em>, <em><em>1999, oto\u00f1o. <\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">Las im\u00e1genes pertenecen a una filmina (diapositiva) y fotos impresas, posteriormente escaneadas, obtenidas con una c\u00e1mara anal\u00f3gica Minolta DYNAX 500 si Reflex, con un AF Zoom 28-80. Corresponden a una de las primeras intervenciones art\u00edsticas en el muro en Playas de Tijuana que se hizo con motivo del 5to aniversario de la puesta en marcha de la operaci\u00f3n Gatekeeper\/Guardi\u00e1n 1994-1999. La instalaci\u00f3n se hizo a finales de octubre. Se colocaron letras grandes sobre un soporte de madera, con la leyenda &#8220;alto a guardi\u00e1n&#8221; en may\u00fasculas. Dentro de cada letra estaban dibujados decenas de cr\u00e1neos de calaca; la calaca o cr\u00e1neo aflora como un elemento iconogr\u00e1fico y simb\u00f3lico importante. Y separado, a la derecha, se instalaron varios paneles de madera pintados en blanco con los nombres, origen y edad \u2013o bien, la leyenda &#8220;no identificado&#8221;\u2013 de 473 migrantes que hab\u00edan muerto en aquellos primeros 5 a\u00f1os. La instalaci\u00f3n con los nombres recordaba, salvando las distancias, el Vietnam Veterans Memorial, en Washington D.C., donde en un muro de granito negro est\u00e1n inscritos los nombres de miles de ca\u00eddos en la guerra de Vietnam y otros conflictos del Sureste Asi\u00e1tico. Como tantas otras veces, s\u00f3lo quedan los nombres de las v\u00edctimas expuestos p\u00fablicamente y su potente capacidad de memoria.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-2 wp-block-columns-is-layout-flex\" id=\"img-2\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p style=\"font-size:15px\"><em><em><em><em>Guillermo Alonso Meneses, buleva<\/em><\/em><\/em>r aeropuerto, 2000 y 2004.<\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">Esta imagen fue obtenida con una c\u00e1mara digital Kodak cx7430 el 29 de mayo del 2004. En el V\u00eda Crucis del a\u00f1o 2000, donde la carretera del aeropuerto dobla antes de llegar a la Colonia Libertad, se hizo una instalaci\u00f3n con una cruz central donde una figura hecha con pantalones y camisa representaba a un migrante crucificado. A ambos lados se observan tres cruces menores en blanco donde estaban los a\u00f1os de 1995 al 2000 y en la parte inferior el n\u00famero de los migrantes muertos habidos cada a\u00f1o en la frontera vigilada por el operativo Guardi\u00e1n. El muro es el original, pintado en rojo; y aunque no se alcanza a ver en su totalidad, a continuaci\u00f3n de la instalaci\u00f3n estaba pintada la leyenda: &#8220;\u00bfcu\u00e1ntos m\u00e1s?&#8221;<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-03.jpg\" itemprop=\"contentUrl\" data-size=\"2304x1728\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-03.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-3 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-04.jpg\" itemprop=\"contentUrl\" data-size=\"2304x1728\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-04.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">Ata\u00fades<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em>Guillermo Alonso Meneses, bulevar aeropuerto<\/em><\/em>, <em><em>2003. <\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">Otra instalaci\u00f3n en la misma \u00e1rea, a medio camino de la Colonia Libertad y del edificio principal del aeropuerto, junto a la carretera, fue la realizada por el artista bajacaliforniano Alberto Caro. A fines de octubre del 2003 instal\u00f3 nueve ata\u00fades pintados con diferentes colores y motivos, sobre cada uno se pint\u00f3 el a\u00f1o, el n\u00famero de v\u00edctimas y en vertical: &#8220;muertes&#8221;. Posteriormente a\u00f1adi\u00f3 un d\u00e9cimo ata\u00fad con la leyenda escrita en negro: &#8220;\u00bfcu\u00e1ntos m\u00e1s?&#8221; Y en el 2004, sobre este \u00faltimo, se pusieron tres letreros en blanco con el a\u00f1o 2004, el n\u00famero de fallecidos, que fue 373, y en vertical: &#8220;muertes&#8221;. La instalaci\u00f3n de f\u00e9retros es una singularidad iconogr\u00e1fica, representa la muerte de migrantes, y la estad\u00edstica refleja a las v\u00edctimas rescatadas e identificadas que son quienes logran una digna sepultura. Su impacto visual es mayor por su simbolismo evidente, al vincular factualmente el muro con la muerte y convertirlo en necro-artefacto de una oprobiosa necro-pol\u00edtica (necro-pol\u00edtica en sentido descriptivo; no en el sentido de la categor\u00eda anal\u00edtica propuesta por Mbembe). Obtenida con c\u00e1mara digital Kodak cx7430 el 29 de mayo del 2004.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-4 wp-block-columns-is-layout-flex\" id=\"img-2\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\"><\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em><em><em>Guillermo Alonso Meneses<\/em><\/em><\/em>, cruces junto al bulevar o carretera del aeropuerto de Tijuana y en la bajada hacia la Colonia Libertad<\/em>, <em>2003 a 2004.<\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">Las cruces, un instrumento de tortura y ejecuci\u00f3n romano extendido en el mundo latino de la antig\u00fcedad y resignificado en el cristianismo como s\u00edmbolo de Cristo [versalitas]inri[\/versalitas], s\u00edmbolo sagrado de la redenci\u00f3n y el perd\u00f3n, se coloc\u00f3 en el muro fronterizo para recordar\/denunciar las muertes de migrantes. \u201cCuando alguien muere, su familia le lleva una cruz con su nombre a la tumba\u201d (Smith). Tambi\u00e9n porque dos de las celebraciones originales fueron las posadas navide\u00f1as (la Virgen Mar\u00eda embarazada y San Jos\u00e9 como migrantes) y el V\u00eda Crucis de la Semana Santa cat\u00f3lica. Desde al menos 1997 se hace un conteo anual, por cada muerte contabilizada se colocaba una cruz blanca con informaci\u00f3n de alguien identificado o bien, con la leyenda &#8220;no identificado&#8221;. El detalle de la cruz tiene el nombre y la edad de una joven v\u00edctima y una postal con el motivo principal del cartel de Playas del 2003. Obtenidas con c\u00e1mara digital Kodak cx7430, mayo del 2004.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-05.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1125\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-05.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-06.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1125\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-06.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-5 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-07.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1125\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-07.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-08.jpg\" itemprop=\"contentUrl\" data-size=\"2304x1728\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-08.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">Instalaci\u00f3n llaga y necro-expositor<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em>Guillermo Alonso Meneses, bulevar del aeropuerto y los l\u00edmites de la Colonia Libertad, respectivamente<\/em><\/em>, <em><em>2004. <\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">En el a\u00f1o 2004 adem\u00e1s de colocarse un centenar de cruces blancas en el bulevar del aeropuerto, Michael Schnorr y otros integrantes del BAW\/TAF pintaron sobre cuatro tablones, que se anclaron al muro fronterizo espaciadamente unos con otros y en los espacios de separaci\u00f3n, la representaci\u00f3n de una herida sangrante con una frase significativa: \u201cLa frontera\u2026 una llaga abierta\u201d. Gloria Anzald\u00faa hab\u00eda escrito: \u201cThe U.S.-Mexican border es una herida abierta where the Third World grates against the first and bleeds. And before a scab form, it hemorrhages again, the lifeblood of two worlds merging to form a third country \u2013a border culture\u201d (1987: 25). El necro-expositor, a manera de vitrina y relicario de restos mortales, consta de un mueble donde a\u00fan quedan unas flores de cempas\u00fachil marchitas y secas (la foto es de varios d\u00edas despu\u00e9s del d\u00eda de muertos del 2004). Detr\u00e1s, a modo de fondo escenogr\u00e1fico, una enorme flor de cempas\u00fachil en cuyo centro a modo de estrofa de una calavera: &#8220;no identificados\u2026 por su gobierno olvidados&#8221;. En el suelo a la izquierda de la imagen se alcanza a ver el letrero del a\u00f1o 2004 que dec\u00eda: &#8220;Guardi\u00e1n aqu\u00ed empez\u00f3\u2026 diez a\u00f1os despu\u00e9s, 3000 muertes logr\u00f3&#8221;. En la cruz que se halla encima, una flor marchitada de la \u00faltima celebraci\u00f3n y una postal con el motivo principal del cartel de Playas del 2004. Esta instalaci\u00f3n se hizo en el mismo lugar donde a\u00f1os atr\u00e1s estaba la cruz con el migrante crucificado. Obtenidas con c\u00e1mara digital Kodak cx7430, mayo del 2004.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-6 wp-block-columns-is-layout-flex\" id=\"img-2\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\"><\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em><em><em>Guillermo Alonso Meneses<\/em><\/em><\/em>, Playas de Tijuana<\/em>, <em>2004.<\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">Una fecha significativa fue el a\u00f1o 2004, con motivo del d\u00e9cimo aniversario de la Operaci\u00f3n Guardi\u00e1n de la Patrulla Fronteriza el 1 de octubre, tiempo durante el cual se estimaban 3000 v\u00edctimas. La instalaci\u00f3n art\u00edstica conmemorativa consist\u00eda en tres lonas (de 4.2 metros de largo por 2.5 de alto) y de un tabl\u00f3n de madera de \u201ctriplay\u201d (de 2.5 metros de largo por 2.5 de alto), anclados al muro, donde aparece una calaca sentada en un paisaje des\u00e9rtico al pie de un saguaro empu\u00f1ando dos galones vac\u00edos que simbolizan la muerte por deshidrataci\u00f3n y calor en los desiertos. En las lonas complementarias estaba escrita la calavera \u201cGuardi\u00e1n\u2026 aqu\u00ed empez\u00f3. Diez a\u00f1os despu\u00e9s, 3000 muertos logr\u00f3\u201d. La instalaci\u00f3n fue pintada por Todd Stands y Susan Yamagata, y financiada por la CRLAF dirigida por Claudia Smith y la Coalici\u00f3n Pro Defensa del Migrante. Los elementos emblem\u00e1ticos de la iconograf\u00eda son la calaca (un esqueleto de medio cuerpo) y el gal\u00f3n vac\u00edo de agua simbolizando la sed y la muerte por deshidrataci\u00f3n en el desierto. Aug\u00e9 apunt\u00f3: \u201cLos recuerdos son moldeados por el olvido como el mar moldea los contornos de la orilla\u201d (1998:12). Las im\u00e1genes tambi\u00e9n muestran c\u00f3mo el muro de acero, tras m\u00e1s de una d\u00e9cada se estaba desmoronando por el poder corrosivo del salitre del mar, pulverizando al acero en forma de herrumbre. Otra met\u00e1fora de la dial\u00e9ctica recuerdo\/olvido. Obtenidas con c\u00e1mara digital Kodak cx7430, mayo del 2004.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-09.jpg\" itemprop=\"contentUrl\" data-size=\"2304x1536\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-09.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-10.jpg\" itemprop=\"contentUrl\" data-size=\"2304x1728\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-10.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-7 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-11.jpg\" itemprop=\"contentUrl\" data-size=\"1516x1137\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-11.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-12.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1125\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-12.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-13.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-13.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-14.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1125\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-14.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">11 a\u00f1os de Guardi\u00e1n y altar<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em><em><em><em><em>Guillermo Alonso Meneses<\/em><\/em><\/em>, Playas de Tijuana<\/em><\/em><\/em>, <em><em><em>2005.<\/em><\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">Las fotograf\u00edas fueron obtenidas con una c\u00e1mara digital Kodak cx7430, octubre\/noviembre del 2005. Ese a\u00f1o destaca la instalaci\u00f3n de unas lonas sint\u00e9ticas con la impresi\u00f3n de fotos y nombres, conmemorando once a\u00f1os de los operativos de la Patrulla Fronteriza en la regi\u00f3n, y el altar de aquel a\u00f1o puesto contra la barda sobre la arena de la playa. Destaca el cempas\u00fachil, braceros para quemar copal, calacas de dulce y veladoras. Detr\u00e1s un cuadro con la tem\u00e1tica del desierto que ironiza con la presencia de vigilantes civiles entre \u201cmuertitos\u201d. El a\u00f1o 2005 fue el a\u00f1o del movimiento de caza-migrantes denominado <em>Minuteman<\/em>. La barda que se ve, irregular e imperfecta, fue la que se construy\u00f3 para sustituir la original. Meses despu\u00e9s fue reconstruida.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-8 wp-block-columns-is-layout-flex\" id=\"img-2\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">Puertas de la frontera<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em><em><em>Guillermo Alonso Meneses<\/em><\/em><\/em>, Playas de Tijuana, 2005.<\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">En el a\u00f1o 2005, destaca la instalaci\u00f3n en la renovada barda de Playas junto al faro, de una instalaci\u00f3n de tres cuadros con tres puertas utilizadas con motivo de la \u201cPosada del Migrante\u201d. Tras esa celebraci\u00f3n fueron llevados a la playa, cerca del faro. Dos puertas est\u00e1n cerradas, simbolizando los efectos del muro y la vigilancia, la tercera est\u00e1 abierta, pero da a los letales desiertos de la frontera; toda una trampa mortal. Cada cuadro mide 2.5 metros de largo por 1 de ancho. Los autores fueron Todd Stands y Susan Yamagata. Financiada por la CRLAF y la Coalici\u00f3n Pro Defensa del Migrante. La fotograf\u00eda fue obtenida con una c\u00e1mara digital Kodak cx7430.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-15.jpg\" itemprop=\"contentUrl\" data-size=\"1080x810\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-15.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-9 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-16.jpg\" itemprop=\"contentUrl\" data-size=\"2304x1728\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-16.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-17.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1125\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-17.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">Protesta contra los <em>Minuteman<\/em><\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em>Guillermo Alonso Meneses, Playas de Tijuana, 2005. <\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">En la primavera del 2005 hubo una manifestaci\u00f3n convocada en EEUU contra los <em>Minutemen<\/em>; no ten\u00edan que ver con las organizaciones pro-migrantes de Tijuana. El lugar es el Parque de la Amistad\/Frienship Park de car\u00e1cter binacional desde 1971, donde est\u00e1 el moj\u00f3n fronterizo. Las cruces de papel son un recuerdo de las y los migrantes ca\u00eddos. En una cartulina alguien pint\u00f3: &#8220;Make Friends, No Fences&#8221;. Con el paso de los d\u00edas el viento no dej\u00f3 rastro. Otro d\u00eda alguien colg\u00f3 una manta sint\u00e9tica con el lema \u201cNo al muro de la muerte\/ No Border Wall\u201d. Obtenidas con una c\u00e1mara digital Kodak cx7430, mayo del 2005.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-10 wp-block-columns-is-layout-flex\" id=\"img-2\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">D\u00eda de muertos<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em><em><em>Guillermo Alonso Meneses<\/em><\/em><\/em>, Playas de Tijuana<\/em>, <em>2007.<\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">En 2007 se hizo una instalaci\u00f3n en madera, pero un temporal de vientos de Santana la desbarat\u00f3 pocos d\u00edas despu\u00e9s. La obra en tres dimensiones fue construida en madera y posteriormente pintada con cr\u00e1neos o calacas en cuyas frentes hab\u00eda un nombre, representando los m\u00e1s de 400 migrantes que fallecieron en lo que iba de a\u00f1o. Fue una obra colectiva realizada por estudiantes del taller de artes fronterizos del Southwestern College, de Chula Vista, San Diego; una instituci\u00f3n a la que estuvo vinculado Schnorr. <\/p>\n\n\n\n<p class=\"font-size-small justified\">La iconograf\u00eda se form\u00f3 a partir de calacas que algo tienen de cr\u00e1neos de un \u201cTzompantli\u201d y la \u201cCatrina\u201d, \u00e9sta \u00faltima con una est\u00e9tica que va de Jos\u00e9 Guadalupe Posada a Diego Rivera, daban una vuelta de tuerca. Pero si bien estas manifestaciones tienen ra\u00edces genuinamente americanas que hay que rastrear antes de 1492 o en el M\u00e9xico del siglo XIX y XX, lo cierto es que el culto a los muertos o la simbolizaci\u00f3n tanto religiosa como profana de los cr\u00e1neos es antigua. Belting nos dice que los denominados cr\u00e1neos de Jeric\u00f3 descubiertos hace m\u00e1s de 4000 a\u00f1os, que fueron recubiertos con una capa de cal y despu\u00e9s pintados, son im\u00e1genes de la muerte, por mucho que est\u00e9n pintados (Belting, 2007: 181). Estas calacas, sin embargo, entrelazan la imagen de la muerte con la vida del recuerdo. Obtenidas con una c\u00e1mara digital Casio EXP600.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-18.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1125\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-18.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-19.jpg\" itemprop=\"contentUrl\" data-size=\"1504x1128\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-19.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-11 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-20.jpg\" itemprop=\"contentUrl\" data-size=\"1502x1127\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-20.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">Cruces<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em>Guillermo Alonso Meneses, Playas de Tijuana<\/em><\/em>, <em><em>octubre\/noviembre 2009. <\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">Una de las intervenciones art\u00edsticas m\u00e1s ambiciosas, impactante y significativa fue la instalaci\u00f3n del D\u00eda de Muertos de 2009, con motivo del XV aniversario de la operaci\u00f3n Guardi\u00e1n. La Coalici\u00f3n Pro Defensa del Migrante y la CRLAF impulsaron la propuesta de Susan Yamagata y Michael Schnorr que consisti\u00f3 en construir, pintar y colocar 5100 cruces blancas, una por cada una de las muertes habidas en el periodo 1994-2009 de migrantes cruzando la frontera. Las cruces se colocaron el D\u00eda de Muertos en parte del muro frente al faro a lo largo de casi 50 metros de largo, y en un costado la calavera escrita en una tabla con un marco de flores de cempas\u00fachil frescas: &#8220;En quince a\u00f1os de Guardi\u00e1n, m\u00e1s de 5,100 muertos van&#8221;. En la parte superior a\u00fan estaban las puertas del desierto del 2005. Las instalaciones art\u00edsticas no solo fueron un ritual anual, entrelazadas como estaban al calendario anual de celebraciones cat\u00f3licas, sino que tambi\u00e9n algo ten\u00edan de <em>Miccantlamanalli<\/em> (ofrendas&nbsp;de muertos). Obtenida con una c\u00e1mara digital Panasonic DMC-TZ4.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-12 wp-block-columns-is-layout-flex\" id=\"img-2\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">Artista callejero canadiense<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em><em><em>Guillermo Alonso Meneses<\/em><\/em><\/em>, Playas de Tijuana, 2010.<\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">En diciembre del 2010 toda la barda de Playas de Tijuana a la altura del faro fue sustituida; supuso un borr\u00f3n y cuenta nueva. El lugar qued\u00f3 irreconocible y se destruyeron las intervenciones art\u00edsticas que coexistieron semanas atr\u00e1s. La primera intervenci\u00f3n del muro actual la hizo un artista canadiense. El tema es un cartel vial de precauci\u00f3n que se encuentra al principio de las autopistas al sur de San Diego; representa a tres miembros de una familia atravesando una carretera. La t\u00e9cnica utilizada es la del \u201cstencil\u201d o plantilla. Obtenidas con una c\u00e1mara digital Pentax Reflex k-r y un Teleobjetivo AF 18-200 mm.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-21.jpg\" itemprop=\"contentUrl\" data-size=\"1280x853\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-21.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-22.jpg\" itemprop=\"contentUrl\" data-size=\"1239x1652\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-22.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-23.jpg\" itemprop=\"contentUrl\" data-size=\"1300x975\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-23.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-13 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-24.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-24.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-25.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-25.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\"><\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em>Guillermo Alonso Meneses, Playas de Tijuana<\/em><\/em>, <em><em>octubre\/noviembre<\/em><\/em> <em><em>2010. <\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">En el 2010 el cuadro conmemorativo de Susan Yamagata caricaturiza al Sherif del condado de Maricopa, Arizona, Joe Arpaio, conocido por el trato duro e indigno hacia los migrantes capturados. Coincide en el espacio con el mural \u00c1ngeles de la frontera, Una puerta del desierto del a\u00f1o 2005 y las cruces del a\u00f1o 2009. Algunos d\u00edas pusieron unas calacas de aproximadamente dos metros. Comenzaba a darse una yuxtaposici\u00f3n de elementos, que anunciaba la lucha por el espacio que se dio posteriormente y que satura el muro en pleno 2021. Algo que suele ocurrir en el arte callejero en los espacios privilegiados y disputados. Obtenidas con una c\u00e1mara digital Pentax Reflex k-r y un Teleobjetivo AF 18-200 mm.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-14 wp-block-columns-is-layout-flex\" id=\"img-2\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">Mural<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em><em><em>Guillermo Alonso Meneses<\/em><\/em><\/em>, Playas de Tijuana, 2010.<\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">En el 2010 destaca un grafiti titulado \u00c1ngeles de la frontera [Boder Angels es una organizaci\u00f3n pro-migrante de EEUU], con figuras humanas estilizadas pintadas en blanco y con una cruz roja en su interior. El conjunto recuerda la iconograf\u00eda y trazos del artista callejero neoyorquino Keith Haring. La obra tiene el lema: &#8220;Ni una muerte m\u00e1s!. Reforma Ya!&#8221; La firmaba P. Breu. En aquel tiempo el espacio no era disputado por otros artistas o activistas y las obras pod\u00edan coexistir en el espacio sin yuxtaponerse totalmente. Obtenidas con una c\u00e1mara digital Panasonic DMC-TZ4.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-26.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-26.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-27.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-27.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-15 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-28.jpg\" itemprop=\"contentUrl\" data-size=\"1500x1125\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-28.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\"><\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em>Guillermo Alonso Meneses, Playas de Tijuana<\/em><\/em>, <em><em>2012. <\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">En el a\u00f1o 2012 se puede decir que fue la \u00faltima gran instalaci\u00f3n art\u00edstica de estos colectivos que luchan por la defensa y la memoria de los migrantes, para el d\u00eda de muertos. La nueva barda a\u00fan no hab\u00eda sucumbido bajo la pintura de quienes luchan por el espacio para imprimir su huella. El lugar elegido fue frente al faro, cerca del moj\u00f3n de los l\u00edmites internacionales. Se instalaron una calaca gigante y 18 calaveras, de 1995 a 2012, y a los pies un peque\u00f1o altar con ofrendas. As\u00ed como un cartel con la leyenda: \u201cGuardi\u00e1n\u2026 aqu\u00ed empez\u00f3. 18 a\u00f1os despu\u00e9s, 5,800 muertes logr\u00f3\u201d. Eran 18 a\u00f1os con el operativo Guardi\u00e1n; m\u00e1s de 18 a\u00f1os de lucha. Auspiciado por la Coalici\u00f3n Pro Defensa del Migrante, la instalaci\u00f3n fue realizada por los artistas Susan Yamagata y Todd Stands de San Diego. Puede decirse que con aquella instalaci\u00f3n culmin\u00f3 una \u00e9poca; ese mismo a\u00f1o hab\u00eda fallecido Michael Schnorr. Obtenida con una c\u00e1mara digital Panasonic DMC-TZ4.<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-16 wp-block-columns-is-layout-flex\" id=\"img-2\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">Los deportados veteranos. Otras reivindicaciones y conmemoraciones.<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em><em><em>Guillermo Alonso Meneses<\/em><\/em><\/em>, Playas de Tijuana<\/em>, <em>febrero 2013.<\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">Las deportaciones comenzaron a crecer en el segundo mandato de Bill Clinton y tuvieron un incremento en los mandatos de Bush Jr. y Obama. De ah\u00ed que en el verano del 2013 los militares veteranos deportados se asociaron y pintaron un mural junto al Parque de la Amistad\/Friendship Park, junto al faro, en Playas de Tijuana. Nac\u00eda el recuerdo de veteranos deportados, algunos de los cuales hab\u00edan fallecido sin poder regresar a EEUU. Su presencia y auge coincide con un periodo en el que declina las tradicionales instalaciones por los migrantes muertos. Obtenidas con c\u00e1mara digital Pentax Reflex k-r y un Teleobjetivo AF 18-200 mm.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-29.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-29.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-30.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-30.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-17 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-31.jpg\" itemprop=\"contentUrl\" data-size=\"1238x1651\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-31.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-32.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-32.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-primary-color has-text-color has-normal-font-size\">Deportados 2019 restaurando el mural, antes y despu\u00e9s<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em>Guillermo Alonso Meneses, Playas de Tijuana<\/em><\/em>, <em><em>febrero 2022. <\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">Seis a\u00f1os despu\u00e9s de la primera intervenci\u00f3n de los veteranos deportados en la barda de Playas de Tijuana, el deterioro tanto de la pintura como del metal ya era patente. Tambi\u00e9n era evidente que la superficie del muro en ese lugar estaba saturada de pintadas e intervenciones de todo tipo. Las im\u00e1genes muestran su restauraci\u00f3n. Tras dos d\u00e9cadas, con diferentes cambios que lo transformaron materialmente, el lugar ya no era un rinc\u00f3n solitario y abandonado donde unas cuantas veces al a\u00f1o se conmemoraba a los migrantes muertos. Se hab\u00eda metamorfoseado en un lugar ic\u00f3nico. Obtenidas con una c\u00e1mara digital Panasonic DMC-TZ4<\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide is-layout-flex wp-container-core-columns-is-layout-18 wp-block-columns-is-layout-flex\" id=\"img-2\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\">El muro como lugar tur\u00edstico<\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em><em><em>Guillermo Alonso Meneses, 2019<\/em><\/em><\/em>.<\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">El proceso de metamorfosis que sufri\u00f3 el muro en Playas de Tijuana y que lo convirti\u00f3 en escenario ic\u00f3nico, pronto comenz\u00f3 a atraer a turistas locales, nacionales, de EEUU o de otras latitudes como R.P. China. El muro sufri\u00f3 remodelaciones y reconstrucciones. Puede decirse que ya no hay espacio para que las intervenciones art\u00edsticas de a\u00f1os atr\u00e1s puedan manifestarse en solitario. Se cumpli\u00f3 el se\u00f1alamiento que hizo Belting, hay lugares que se vuelven lugares fotogr\u00e1ficos (2007: 268). Desde sus inicios el muro atrajo miradas m\u00e1s all\u00e1 de las de activistas, artistas y paseantes, se normaliz\u00f3 como objeto-lugar que atrae las c\u00e1maras fotogr\u00e1ficas y a quienes miran detr\u00e1s de ellas. Eso ya hab\u00eda ocurrido con el muro de Berl\u00edn. Obtenidas con una c\u00e1mara digital Panasonic DMC-TZ4<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-33.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-33.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-34.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-34.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p><\/p>\n<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-columns alignwide are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-19 wp-block-columns-is-layout-flex\" id=\"img-1\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-35.jpg\" itemprop=\"contentUrl\" data-size=\"2201x1022\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-35.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-36.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-36.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-37.jpg\" itemprop=\"contentUrl\" data-size=\"2203x1652\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-37.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-38.jpg\" itemprop=\"contentUrl\" data-size=\"1280x960\" data-index=\"0\" data-caption=\"\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/vol5num10-multimedia\/meneses-muro_fronterizo-38.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div><div class=\"caption\"><\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-normal-font-size\"><\/p>\n\n\n\n<p style=\"font-size:15px\"><em><em>Guillermo Alonso Meneses, el muro en el bulevar cercano al aeropuerto, 2021, y Playas de Tijuana, 2022. <\/em><\/em><\/p>\n\n\n\n<p class=\"font-size-small justified\">En los \u00faltimos a\u00f1os, el muro tanto en Playas de Tijuana como en el bulevar que discurre en paralelo al aeropuerto ha sufrido cambios importantes. Nadie reconocer\u00eda los tramos donde antiguamente colgaron cruces, intervenciones art\u00edsticas y grafitis recordando a migrantes muertos y otras injusticias. Lo mismo ocurre en el muro en Playas de Tijuana en el tramo de varios cientos de metros desde el oc\u00e9ano. La foto 73 muestra la saturaci\u00f3n de intervenciones, la 74 contrasta con la primera foto de este ensayo, la 75 muestra un migrante saltando el muro con una escalera met\u00e1lica. Tras 30 a\u00f1os el muro sigue siendo saltado. El esfuerzo y el trabajo de activistas, artistas y organizaciones que durante d\u00e9cadas lucharon contra el olvido se evapor\u00f3. Pronto solo quedar\u00e1n fotograf\u00edas. Obtenidas con un Iphone SE y con una c\u00e1mara digital Panasonic DMC-TZ4<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A instala\u00e7\u00e3o foi realizada no final de outubro. Foi colocado em letras grandes em um suporte de madeira, com a lenda Alto a Guardi\u00e1n em letras mai\u00fasculas.<\/p>","protected":false},"featured_media":35976,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"templates\/template-cover.php","class_list":["post-35960","ensayos-fotograficos","type-ensayos-fotograficos","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Intervenciones art\u00edsticas en el muro fronterizo de Tijuana &#8211; Encartes<\/title>\n<meta name=\"description\" content=\"Huellas fotogr\u00e1ficas de las ofrendas\/intervenciones art\u00edsticas en memoria de las y los migrantes muertos sobre el muro fronterizo en Tijuana\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encartes.mx\/pt\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intervenciones art\u00edsticas en el muro fronterizo de Tijuana &#8211; Encartes\" \/>\n<meta property=\"og:description\" content=\"Huellas fotogr\u00e1ficas de las ofrendas\/intervenciones art\u00edsticas en memoria de las y los migrantes muertos sobre el muro fronterizo en Tijuana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encartes.mx\/pt\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/\" \/>\n<meta property=\"og:site_name\" content=\"Encartes\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-16T19:53:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/encartes.mx\/wp-content\/uploads\/2022\/05\/meneses-muro_fronterizo-14.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Arthur Ventura\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/\",\"url\":\"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/\",\"name\":\"Intervenciones art\u00edsticas en el muro fronterizo de Tijuana &#8211; Encartes\",\"isPartOf\":{\"@id\":\"https:\/\/encartes.mx\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2022\/05\/meneses-muro_fronterizo-14.jpg\",\"datePublished\":\"2022-09-21T18:33:01+00:00\",\"dateModified\":\"2023-09-16T19:53:22+00:00\",\"description\":\"Huellas fotogr\u00e1ficas de las ofrendas\/intervenciones art\u00edsticas en memoria de las y los migrantes muertos sobre el muro fronterizo en Tijuana\",\"breadcrumb\":{\"@id\":\"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#primaryimage\",\"url\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2022\/05\/meneses-muro_fronterizo-14.jpg\",\"contentUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2022\/05\/meneses-muro_fronterizo-14.jpg\",\"width\":1500,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/encartes.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ensayos fotogr\u00e1ficos\",\"item\":\"https:\/\/encartes.mx\/ensayos-fotograficos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"El muro fronterizo en Tijuana. Huellas fotogr\u00e1ficas de las ofrendas\/intervenciones art\u00edsticas en memoria de las y los migrantes muertos 1999-2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/encartes.mx\/#website\",\"url\":\"https:\/\/encartes.mx\/\",\"name\":\"Encartes\",\"description\":\"Revista digital multimedia\",\"publisher\":{\"@id\":\"https:\/\/encartes.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/encartes.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/encartes.mx\/#organization\",\"name\":\"Encartes Antropol\u00f3gicos\",\"url\":\"https:\/\/encartes.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"contentUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"width\":338,\"height\":306,\"caption\":\"Encartes Antropol\u00f3gicos\"},\"image\":{\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intervenciones art\u00edsticas en el muro fronterizo de Tijuana &#8211; Encartes","description":"Huellas fotogr\u00e1ficas de las ofrendas\/intervenciones art\u00edsticas en memoria de las y los migrantes muertos sobre el muro fronterizo en Tijuana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encartes.mx\/pt\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/","og_locale":"pt_BR","og_type":"article","og_title":"Intervenciones art\u00edsticas en el muro fronterizo de Tijuana &#8211; Encartes","og_description":"Huellas fotogr\u00e1ficas de las ofrendas\/intervenciones art\u00edsticas en memoria de las y los migrantes muertos sobre el muro fronterizo en Tijuana","og_url":"https:\/\/encartes.mx\/pt\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/","og_site_name":"Encartes","article_modified_time":"2023-09-16T19:53:22+00:00","og_image":[{"width":1500,"height":1125,"url":"https:\/\/encartes.mx\/wp-content\/uploads\/2022\/05\/meneses-muro_fronterizo-14.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"14 minutos","Written by":"Arthur Ventura"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/","url":"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/","name":"Intervenciones art\u00edsticas en el muro fronterizo de Tijuana &#8211; Encartes","isPartOf":{"@id":"https:\/\/encartes.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#primaryimage"},"image":{"@id":"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#primaryimage"},"thumbnailUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2022\/05\/meneses-muro_fronterizo-14.jpg","datePublished":"2022-09-21T18:33:01+00:00","dateModified":"2023-09-16T19:53:22+00:00","description":"Huellas fotogr\u00e1ficas de las ofrendas\/intervenciones art\u00edsticas en memoria de las y los migrantes muertos sobre el muro fronterizo en Tijuana","breadcrumb":{"@id":"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#primaryimage","url":"https:\/\/encartes.mx\/wp-content\/uploads\/2022\/05\/meneses-muro_fronterizo-14.jpg","contentUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2022\/05\/meneses-muro_fronterizo-14.jpg","width":1500,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/encartes.mx\/fr\/ensayos-fotograficos\/alonso-tijuana-muro-intervenciones-artisticas-memoria-migrantes-muertos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/encartes.mx\/"},{"@type":"ListItem","position":2,"name":"Ensayos fotogr\u00e1ficos","item":"https:\/\/encartes.mx\/ensayos-fotograficos\/"},{"@type":"ListItem","position":3,"name":"El muro fronterizo en Tijuana. Huellas fotogr\u00e1ficas de las ofrendas\/intervenciones art\u00edsticas en memoria de las y los migrantes muertos 1999-2021"}]},{"@type":"WebSite","@id":"https:\/\/encartes.mx\/#website","url":"https:\/\/encartes.mx\/","name":"Encartes","description":"Revista multim\u00eddia digital","publisher":{"@id":"https:\/\/encartes.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encartes.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/encartes.mx\/#organization","name":"Inser\u00e7\u00f5es antropol\u00f3gicas","url":"https:\/\/encartes.mx\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/","url":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","contentUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","width":338,"height":306,"caption":"Encartes Antropol\u00f3gicos"},"image":{"@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/ensayos-fotograficos\/35960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/ensayos-fotograficos"}],"about":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/types\/ensayos-fotograficos"}],"replies":[{"embeddable":true,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/comments?post=35960"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/media\/35976"}],"wp:attachment":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/media?parent=35960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}