{"id":8,"count":0,"description":"\u00e9 uma se\u00e7\u00e3o na qual ser\u00e3o publicados debates sobre um t\u00f3pico espec\u00edfico com a participa\u00e7\u00e3o de quatro ou cinco especialistas de diferentes disciplinas. A mec\u00e2nica consiste em promover a discuss\u00e3o sobre um ensaio espec\u00edfico de um acad\u00eamico de ci\u00eancias sociais convidado pelo conselho editorial da revista para incentivar o di\u00e1logo, o debate e a discuss\u00e3o de ideias, conceitos e propostas metodol\u00f3gicas. A arbitragem ser\u00e1 aberta e p\u00fablica, utilizando a comunica\u00e7\u00e3o e o confronto acad\u00eamico como forma alternativa de avalia\u00e7\u00e3o.","link":"https:\/\/encartes.mx\/pt\/category\/01\/","name":"Col\u00f3quios interdisciplinares","slug":"01","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coloquios interdisciplinarios Archives &#8211; Encartes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encartes.mx\/pt\/category\/01\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coloquios interdisciplinarios Archives &#8211; Encartes\" \/>\n<meta property=\"og:description\" content=\"es una secci\u00f3n en que se publicar\u00e1n debates sobre un tema espec\u00edfico y se contar\u00e1 con la participaci\u00f3n de cuatro o cinco especialistas de distintas disciplinas. La mec\u00e1nica reside en promover la discusi\u00f3n sobre un ensayo espec\u00edfico de un acad\u00e9mico de las ciencias sociales invitado por el comit\u00e9 editorial de la revista para propiciar el di\u00e1logo, el debate y la discusi\u00f3n de ideas, conceptos y propuestas metodol\u00f3gicas. El arbitraje ser\u00e1 abierto y p\u00fablico, instrumentando la comunicaci\u00f3n y la confrontaci\u00f3n acad\u00e9mica como forma alternativa de evaluaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encartes.mx\/pt\/category\/01\/\" \/>\n<meta property=\"og:site_name\" content=\"Encartes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/encartes.mx\/category\/01\/\",\"url\":\"https:\/\/encartes.mx\/category\/01\/\",\"name\":\"Coloquios interdisciplinarios Archives &#8211; Encartes\",\"isPartOf\":{\"@id\":\"https:\/\/encartes.mx\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/encartes.mx\/category\/01\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/encartes.mx\/category\/01\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/encartes.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coloquios interdisciplinarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/encartes.mx\/#website\",\"url\":\"https:\/\/encartes.mx\/\",\"name\":\"Encartes\",\"description\":\"Revista digital multimedia\",\"publisher\":{\"@id\":\"https:\/\/encartes.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/encartes.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/encartes.mx\/#organization\",\"name\":\"Encartes Antropol\u00f3gicos\",\"url\":\"https:\/\/encartes.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"contentUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"width\":338,\"height\":306,\"caption\":\"Encartes Antropol\u00f3gicos\"},\"image\":{\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coloquios interdisciplinarios Archives &#8211; Encartes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encartes.mx\/pt\/category\/01\/","og_locale":"pt_BR","og_type":"article","og_title":"Coloquios interdisciplinarios Archives &#8211; Encartes","og_description":"es una secci\u00f3n en que se publicar\u00e1n debates sobre un tema espec\u00edfico y se contar\u00e1 con la participaci\u00f3n de cuatro o cinco especialistas de distintas disciplinas. La mec\u00e1nica reside en promover la discusi\u00f3n sobre un ensayo espec\u00edfico de un acad\u00e9mico de las ciencias sociales invitado por el comit\u00e9 editorial de la revista para propiciar el di\u00e1logo, el debate y la discusi\u00f3n de ideas, conceptos y propuestas metodol\u00f3gicas. El arbitraje ser\u00e1 abierto y p\u00fablico, instrumentando la comunicaci\u00f3n y la confrontaci\u00f3n acad\u00e9mica como forma alternativa de evaluaci\u00f3n.","og_url":"https:\/\/encartes.mx\/pt\/category\/01\/","og_site_name":"Encartes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/encartes.mx\/category\/01\/","url":"https:\/\/encartes.mx\/category\/01\/","name":"Coloquios interdisciplinarios Archives &#8211; Encartes","isPartOf":{"@id":"https:\/\/encartes.mx\/#website"},"breadcrumb":{"@id":"https:\/\/encartes.mx\/category\/01\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/encartes.mx\/category\/01\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/encartes.mx\/"},{"@type":"ListItem","position":2,"name":"Coloquios interdisciplinarios"}]},{"@type":"WebSite","@id":"https:\/\/encartes.mx\/#website","url":"https:\/\/encartes.mx\/","name":"Encartes","description":"Revista multim\u00eddia digital","publisher":{"@id":"https:\/\/encartes.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encartes.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/encartes.mx\/#organization","name":"Inser\u00e7\u00f5es antropol\u00f3gicas","url":"https:\/\/encartes.mx\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/","url":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","contentUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","width":338,"height":306,"caption":"Encartes Antropol\u00f3gicos"},"image":{"@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/posts?categories=8"},{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/media?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}