{"id":11,"count":33,"description":"inclui a publica\u00e7\u00e3o de diferentes produtos de pesquisas em andamento. Ser\u00e3o aceitas etnografias visuais\/relat\u00f3rios multim\u00eddia com forte apoio de trabalho de campo e uso de estruturas de ci\u00eancias sociais, ensaios fotogr\u00e1ficos, document\u00e1rios, poesia, hist\u00f3rias de vida e arquivos orais. Todo o material ser\u00e1 avaliado de forma duplamente cega.","link":"https:\/\/encartes.mx\/pt\/category\/04\/","name":"Encartes Multim\u00eddia","slug":"04","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EncArtes multimedia Archives &#8211; Encartes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encartes.mx\/pt\/category\/04\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EncArtes multimedia Archives &#8211; Encartes\" \/>\n<meta property=\"og:description\" content=\"incluye la publicaci\u00f3n de diferentes productos de investigaciones en curso. Se aceptar\u00e1n etnograf\u00edas visuales\/reportajes multimedia con fuerte soporte de trabajo de campo y uso de marcos de referencia de las ciencias sociales, ensayos fotogr\u00e1ficos, documentales, poes\u00eda, historias de vida y archivos orales. Todo material ser\u00e1 dictaminado en doble ciego.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encartes.mx\/pt\/category\/04\/\" \/>\n<meta property=\"og:site_name\" content=\"Encartes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/encartes.mx\/category\/04\/\",\"url\":\"https:\/\/encartes.mx\/category\/04\/\",\"name\":\"EncArtes multimedia Archives &#8211; Encartes\",\"isPartOf\":{\"@id\":\"https:\/\/encartes.mx\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/encartes.mx\/category\/04\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/encartes.mx\/category\/04\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/encartes.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EncArtes multimedia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/encartes.mx\/#website\",\"url\":\"https:\/\/encartes.mx\/\",\"name\":\"Encartes\",\"description\":\"Revista digital multimedia\",\"publisher\":{\"@id\":\"https:\/\/encartes.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/encartes.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/encartes.mx\/#organization\",\"name\":\"Encartes Antropol\u00f3gicos\",\"url\":\"https:\/\/encartes.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"contentUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"width\":338,\"height\":306,\"caption\":\"Encartes Antropol\u00f3gicos\"},\"image\":{\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EncArtes multimedia Archives &#8211; Encartes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encartes.mx\/pt\/category\/04\/","og_locale":"pt_BR","og_type":"article","og_title":"EncArtes multimedia Archives &#8211; Encartes","og_description":"incluye la publicaci\u00f3n de diferentes productos de investigaciones en curso. Se aceptar\u00e1n etnograf\u00edas visuales\/reportajes multimedia con fuerte soporte de trabajo de campo y uso de marcos de referencia de las ciencias sociales, ensayos fotogr\u00e1ficos, documentales, poes\u00eda, historias de vida y archivos orales. Todo material ser\u00e1 dictaminado en doble ciego.","og_url":"https:\/\/encartes.mx\/pt\/category\/04\/","og_site_name":"Encartes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/encartes.mx\/category\/04\/","url":"https:\/\/encartes.mx\/category\/04\/","name":"EncArtes multimedia Archives &#8211; Encartes","isPartOf":{"@id":"https:\/\/encartes.mx\/#website"},"breadcrumb":{"@id":"https:\/\/encartes.mx\/category\/04\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/encartes.mx\/category\/04\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/encartes.mx\/"},{"@type":"ListItem","position":2,"name":"EncArtes multimedia"}]},{"@type":"WebSite","@id":"https:\/\/encartes.mx\/#website","url":"https:\/\/encartes.mx\/","name":"Encartes","description":"Revista multim\u00eddia digital","publisher":{"@id":"https:\/\/encartes.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encartes.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/encartes.mx\/#organization","name":"Inser\u00e7\u00f5es antropol\u00f3gicas","url":"https:\/\/encartes.mx\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/","url":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","contentUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","width":338,"height":306,"caption":"Encartes Antropol\u00f3gicos"},"image":{"@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/categories\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/posts?categories=11"},{"href":"https:\/\/encartes.mx\/pt\/wp-json\/wp\/v2\/media?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}