{"id":1048,"count":1,"description":"","link":"https:\/\/encartes.mx\/en\/tag\/afectividad\/","name":"affectivity","slug":"afectividad","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>afectividad Archives &#8211; Encartes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encartes.mx\/en\/tag\/afectividad\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"afectividad Archives &#8211; Encartes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encartes.mx\/en\/tag\/afectividad\/\" \/>\n<meta property=\"og:site_name\" content=\"Encartes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/encartes.mx\/tag\/afectividad\/\",\"url\":\"https:\/\/encartes.mx\/tag\/afectividad\/\",\"name\":\"afectividad Archives &#8211; Encartes\",\"isPartOf\":{\"@id\":\"https:\/\/encartes.mx\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/encartes.mx\/tag\/afectividad\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/encartes.mx\/tag\/afectividad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/encartes.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"afectividad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/encartes.mx\/#website\",\"url\":\"https:\/\/encartes.mx\/\",\"name\":\"Encartes\",\"description\":\"Revista digital multimedia\",\"publisher\":{\"@id\":\"https:\/\/encartes.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/encartes.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/encartes.mx\/#organization\",\"name\":\"Encartes Antropol\u00f3gicos\",\"url\":\"https:\/\/encartes.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"contentUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"width\":338,\"height\":306,\"caption\":\"Encartes Antropol\u00f3gicos\"},\"image\":{\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"afectividad Archives &#8211; Encartes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encartes.mx\/en\/tag\/afectividad\/","og_locale":"en_US","og_type":"article","og_title":"afectividad Archives &#8211; Encartes","og_url":"https:\/\/encartes.mx\/en\/tag\/afectividad\/","og_site_name":"Encartes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/encartes.mx\/tag\/afectividad\/","url":"https:\/\/encartes.mx\/tag\/afectividad\/","name":"afectividad Archives &#8211; Encartes","isPartOf":{"@id":"https:\/\/encartes.mx\/#website"},"breadcrumb":{"@id":"https:\/\/encartes.mx\/tag\/afectividad\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/encartes.mx\/tag\/afectividad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/encartes.mx\/"},{"@type":"ListItem","position":2,"name":"afectividad"}]},{"@type":"WebSite","@id":"https:\/\/encartes.mx\/#website","url":"https:\/\/encartes.mx\/","name":"Encartes","description":"Multimedia digital magazine","publisher":{"@id":"https:\/\/encartes.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encartes.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/encartes.mx\/#organization","name":"Anthropological Inserts","url":"https:\/\/encartes.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/","url":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","contentUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","width":338,"height":306,"caption":"Encartes Antropol\u00f3gicos"},"image":{"@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/tags\/1048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/posts?tags=1048"},{"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/media?tags=1048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}