{"id":33940,"date":"2021-03-19T07:06:16","date_gmt":"2021-03-19T07:06:16","guid":{"rendered":"https:\/\/encartes.mx\/?p=33940"},"modified":"2023-11-17T18:19:34","modified_gmt":"2023-11-18T00:19:34","slug":"aboitiz-reconfiguraciones-sociales-errenteria","status":"publish","type":"post","link":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/","title":{"rendered":"The shadows of the future that are no longer. The social reconfigurations of hope in the deindustrialized city of Errenteria, Basque Country"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Resumen<\/strong><\/h2>\n\n\n\n<p class=\"no-indent\">Errenteria ha sido hist\u00f3ricamente uno de los principales focos industriales vascos, lo que en los sesenta y los setenta le permiti\u00f3 alcanzar el pleno empleo y la estabilidad laboral, sobre todo del empleo industrial masculino, hasta que a mediados de los setenta los gobiernos de la transici\u00f3n comenzaron a reestructurar las industrias, supuestamente para preparar la entrada a la Comunidad Econ\u00f3mica Europea y el desaf\u00edo de la competitividad del mercado libre. A la p\u00e9rdida de miles de puestos de trabajo le sigui\u00f3 una desregulaci\u00f3n del mercado laboral que gener\u00f3 una mayor precarizaci\u00f3n de las condiciones de vida, lo cual se intensific\u00f3 por la crisis financiera del 2008 y las pol\u00edticas de austeridad. En este art\u00edculo me propongo mostrar c\u00f3mo, para las generaciones m\u00e1s j\u00f3venes de esta ciudad, los futuros pasados siguen proyectando sombras en las formas de contemplar ahora un futuro marcado por una creciente incertidumbre. En ese sentido, discuto el sentido com\u00fan de \u201cretroceder\u201d, se\u00f1alando que retroceder no s\u00f3lo parece aludir a que los logros de las generaciones pasadas se deshacen, sino a una reconfiguraci\u00f3n confusa de lo que pueden esperar ahora del futuro.<\/p>\n\n\n\n<p class=\"no-indent\">Palabras claves: <a href=\"https:\/\/encartes.mx\/en\/tag\/ajuste-estructural\/\" rel=\"tag\">ajuste estructural<\/a>, <a href=\"https:\/\/encartes.mx\/en\/tag\/desindustrializacion\/\" rel=\"tag\">desindustrializaci\u00f3n<\/a>, <a href=\"https:\/\/encartes.mx\/en\/tag\/errenteria\/\" rel=\"tag\">Errenteria<\/a>, <a href=\"https:\/\/encartes.mx\/en\/tag\/esperanza\/\" rel=\"tag\">esperanza<\/a>, <a href=\"https:\/\/encartes.mx\/en\/tag\/incertidumbre\/\" rel=\"tag\">incertidumbre<\/a>, <a href=\"https:\/\/encartes.mx\/en\/tag\/prosperidad\/\" rel=\"tag\">prosperidad<\/a>, <a href=\"https:\/\/encartes.mx\/en\/tag\/temporalidad\/\" rel=\"tag\">temporalidad<\/a><\/p>\n\n\n\n<p class=\"en-title\"><span class=\"small-caps\">The Shadows of Futures Gone By: Social Reconfigurations of Hope in Deindustrialized City of Errenteria, Basque Country<\/span><\/p>\n\n\n\n<p class=\"no-indent en-text\">Errenteria has historically been one of the main industrial cities in the Basque Country, which helped it reach full employment levels and job stability in the sixties and seventies, particularly regarding male industrial jobs, up until the mid-seventies, when the transition governments began restructuring industries, allegedly to prepare for the entry into the European Economic Community and for the challenge of a free market. The loss of thousands of jobs was followed by a deregularization of the labor market, which led to a great decrease in the standards of living, which was intensified by the financial crisis of 2008 and austerity policies. This article aims to show how, for the younger generations of this city, past futures keep casting shadows on the ways of viewing a future marked by an increasing uncertainty. In this sense, I discuss the common sense of \u201cgoing backwards\u201d, pointing out that going backwards seems to allude, not only to the crumbling of the achievements of past generations, but also to a confusing reconfiguration of what they can now expect of the future.<\/p>\n\n\n\n<p class=\"no-indent en-text\">Keywords: hope, structural adjustment, uncertainty, prosperity, deindustrialization, temporality.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-drop-cap no-indent\">\u00bfQu\u00e9 sucede cuando el futuro no se configura de la manera que se esperaba y planeaba? Este art\u00edculo explora c\u00f3mo la gente de una ciudad desindustrializada del Pa\u00eds Vasco reconfigura las esperanzas a futuro al tiempo que est\u00e1 experimentando una movilidad social descendente. Mi hip\u00f3tesis consiste en que la transici\u00f3n de una organizaci\u00f3n social basada en la estabilidad y seguridad socioecon\u00f3micas a otra basada en la incertidumbre y la precariedad se ha reflejado en la producci\u00f3n de las esperanzas actuales, en tanto que se da una tensi\u00f3n entre las expectativas personales, las posibilidades de dise\u00f1ar proyectos de vida y las posibilidades reales de llevarlos a cabo. Economistas feministas como Amaia P\u00e9rez Orozco (2014) o Mona Motakef (2019), entre otras, han descrito esto como una \u201cprecariedad generalizada de la vida\u201d,<a class=\"anota\" id=\"anota1\" data-footnote=1>1<\/a> con la intenci\u00f3n de describir la inseguridad en el acceso sostenido a los recursos que se necesitan para vivir vidas significativas (nociones de bienestar que siempre son definidas hist\u00f3rica y socialmente), lo que genera p\u00e9rdida de agencia y de las capacidades y posibilidades de considerar y hacer planes a futuro.<\/p>\n\n\n\n<p>Para ello, me apoyo en una investigaci\u00f3n etnogr\u00e1fica entre los a\u00f1os 2017 y 2018 en Errenteria, una antigua ciudad industrial del Pa\u00eds Vasco, hoy desindustrializada, al haber devenido, como otros antiguos bastiones industriales de Europa, perif\u00e9rica dentro de los circuitos de acumulaci\u00f3n y de distribuci\u00f3n del capital globalizado. Hoy Errenteria es una ciudad de servicios echada a menos del cintur\u00f3n de Donostia-San Sebasti\u00e1n, que situada al norte de Espa\u00f1a y a pocos kil\u00f3metros de la frontera con Francia, ten\u00eda, en 2019, 39 471 habitantes. En la actualidad, la mayor\u00eda trabajan fuera de la ciudad, y Errenteria ocupa, m\u00e1s que otras ciudades, las escalas m\u00e1s bajas del mercado laboral, con una de las rentas de trabajo m\u00e1s bajas del territorio y donde la mitad de los asalariados es ya eventual (Eustat, 2016). El sentimiento de marginaci\u00f3n pol\u00edtica y econ\u00f3mica de la poblaci\u00f3n es un palpable resultado de una larga din\u00e1mica vinculada con el desmantelamiento del capitalismo industrial y el vaciamiento del modelo de bienestar fordista, el cual ha producido, utilizando los t\u00e9rminos de Raymond Williams (1977), una \u201cestructura de sentimiento\u201d de abandono social de una ciudad que hasta hace poco fue sin\u00f3nimo de prosperidad y milagro econ\u00f3mico.<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-%200.jpg\" itemprop=\"contentUrl\" data-size=\"1600x900\" data-index=\"0\" data-caption=\"Ilustraci\u00f3n 1: Llegada a Errenteria en tren. Fotograf\u00eda tomada durante el trabajo de campo 2017-2018. Autor\u00eda: Uzuri Aboitiz.\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-%200.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Ilustraci\u00f3n 1: Llegada a Errenteria en tren. Fotograf\u00eda tomada durante el trabajo de campo 2017-2018. Autor\u00eda: Uzuri Aboitiz.<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>Es este momento de transformaci\u00f3n material e ideol\u00f3gica el que quiero captar en el art\u00edculo. Lo que sostengo es que, en la actualidad, las vidas contempor\u00e1neas se encuentran atrapadas entre la sem\u00e1ntica de la prosperidad de la sociedad industrial y la vivencia de la incertidumbre actual. Y es que, como apuntan Susana Narotzky y Niko Besnier (2014: 58), si bien la incertidumbre no es algo excepcional y m\u00e1s bien ha sido norma en la mayor\u00eda de contextos hist\u00f3ricos, culturales y sociales, lo cierto es que s\u00ed ha chocado con el periodo de estabilidad vivido en Europa a partir de la Segunda Guerra Mundial. Pero adem\u00e1s Nauja Kleist y Stef Jansen (2016: 375) a\u00f1aden que el marco del presente est\u00e1 caracterizado por una intensificaci\u00f3n de la incertidumbre y la imprevisibilidad para amplias capas sociales, ya sea por la sensaci\u00f3n de riesgo (Beck, 1992), por la percepci\u00f3n de incontrolabilidad generada por la velocidad (Bauman, 1998) o por el debilitamiento del proyecto modernizador (Escobar, 2010), entre otros factores.<\/p>\n\n\n\n<p>Por todo ello, me interrogo acerca de c\u00f3mo se est\u00e1n reconfigurando las esperanzas en este momento de transformaci\u00f3n, poniendo especial atenci\u00f3n a los razonamientos temporales. Y es que, como dice David Zeitlyn (2015: 399), los \u201cfuturos pasados\u201d, aquellos que un d\u00eda fueron posibles y hoy ya no lo son, o no por lo menos con la misma certeza, arrojan \u201csombras\u201d en las formas en las que la gente puede y se atreve a calcular y desear. De hecho, en este preciso momento, la gente est\u00e1 decidiendo qu\u00e9 creencias, suposiciones, verdades o confiabilidades forjadas en el modelo econ\u00f3mico anterior rescata y cu\u00e1les deja atr\u00e1s.<\/p>\n\n\n\n<p>Para abordar la reconfiguraci\u00f3n de las esperanzas me apoyo en el trabajo de campo de quince meses en Errenteria, en el que estudi\u00e9 los \u201cmarcos de oportunidad\u201d y los \u201cmarcos de significaci\u00f3n\u201d por los cuales los vecinos y vecinas persiguen unas vidas que consideran \u201cdignas de ser vividas\u201d.<a class=\"anota\" id=\"anota2\" data-footnote=2>2<\/a> Inspirada en el dispositivo metodol\u00f3gico de la \u201cetnocontabilidad\u201d de Alain Cottereau y Mokhtar Mohatar Marzok (2012), el trabajo de campo consisti\u00f3 en compartir el espacio de vida y de relaci\u00f3n con los vecinos y las vecinas, viviendo en la misma casa con algunos de ellos, y siguiendo paso a paso en la medida de lo posible y con distintas intensidades seg\u00fan el v\u00ednculo construido, las formas de valorar que ten\u00eda la gente en la consecuci\u00f3n de sus proyectos vitales. Es decir, el objetivo no era otro que fijarme en las formas en que la gente act\u00faa y se esfuerza para llevar lo  que considera una \u201cbuena vida\u201d en un marco econ\u00f3mico determinado. En definitiva, observar en la situaci\u00f3n qu\u00e9 es lo importante en la vida, en todos sus aspectos y mediante uso de varias t\u00e9cnicas: cuadernos de contabilidad, diarios de campo, usos del tiempo cotidiano, entrevistas en profundidad, historias de vida o trayectorias laborales y residenciales. En total realic\u00e9 cuarenta y cuatro entrevistas formales a veintisiete vecinos y vecinas. Aun as\u00ed, las conversaciones informales y las discusiones grupales en contextos informales son m\u00e1s y tienen un valor incalculable en esta investigaci\u00f3n.<\/p>\n\n\n\n<p>En concreto, en este art\u00edculo muestro los casos de estudio de tres hijos de familias relacionadas con el trabajo industrial, con los que mantuve una estrecha relaci\u00f3n, as\u00ed como con sus familias y amigos: Ana, una mujer de cincuenta y dos a\u00f1os, acostumbrada a buscarse la vida con empleos que duran apenas unos meses; \u00c1lex, un hombre de cuarenta y dos a\u00f1os, socio cooperativista desde hace m\u00e1s de diecis\u00e9is a\u00f1os; y Eli, una mujer de treinta y siete, perceptora de ayudas sociales desde hace m\u00e1s de diez a\u00f1os. El di\u00e1logo entre los tres casos, que viven configuraciones diversas de incertidumbre, creo que permite obtener una visi\u00f3n amplia de la producci\u00f3n y reproducci\u00f3n de las esperanzas actuales en la ciudad de Errenteria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">El fin de la <em>Peque\u00f1a Manchester<\/em><\/h2>\n\n\n\n<p class=\"no-indent\">La expansi\u00f3n industrial de Errenteria fue de las m\u00e1s tempranas de Espa\u00f1a, y ya en el \u00faltimo tercio del siglo <span class=\"small-caps\">xix<\/span> contaba con una actividad industrial diversificada que abarcaba producci\u00f3n de metal, papel, textil y alimentaci\u00f3n. De este modo, para principios del siglo <span class=\"small-caps\">xx<\/span>, Errenteria empez\u00f3 a ser conocida como \u201cla peque\u00f1a Manchester\u201d por la cantidad de f\u00e1bricas, chimeneas y talleres que llenaban la ciudad, y se convirti\u00f3 junto al puerto de Pasaia en uno de los principales focos industriales vascos (Barcenilla, 1999: 38-39). Una de esas m\u00edticas f\u00e1bricas, que llenaba con su aroma la ciudad, era la f\u00e1brica de Galletas Olibet (ilustraci\u00f3n 2).<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-1.jpg\" itemprop=\"contentUrl\" data-size=\"1600x916\" data-index=\"0\" data-caption=\"Ilustraci\u00f3n 2. Empacadoras de Olibet. Fuente: Joxeba Go\u00f1i (1969). Historia de Renter\u00eda. San Sebasti\u00e1n: Caja de Ahorros Municipal de San Sebasti\u00e1n.\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-1.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Ilustraci\u00f3n 2. Empacadoras de Olibet. Fuente: Joxeba Go\u00f1i (1969). Historia de Renter\u00eda. San Sebasti\u00e1n: Caja de Ahorros Municipal de San Sebasti\u00e1n.<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>Sin embargo, este desarrollo industrial se vio frenado con la Guerra Civil espa\u00f1ola y no tuvo un nuevo despegue hasta los a\u00f1os sesenta, cuando la dictadura franquista rompi\u00f3 con su pol\u00edtica de autarqu\u00eda e inici\u00f3 un nuevo periodo desarrollista (1959-1975) (Palomera, 2015: 17). Fue entonces cuando Errenteria y otras tantas ciudades vivieron un segundo<em> boom <\/em>industrial. As\u00ed, a pesar de la represi\u00f3n y la falta de libertad sindical de aquellos a\u00f1os, Errenteria vivi\u00f3 una \u00e9poca si no del pleno empleo, si\u0301 del empleo abundante, donde la estabilidad socioecon\u00f3mica era una realidad, en especial para los hombres que se empleaban en la industria. La ciudad pas\u00f3 de tener 12 000 habitantes en la d\u00e9cada de los cincuenta para rebasar los 46 000 a mediados de la d\u00e9cada del setenta. Y es que, en muy poco tiempo, la ciudad se convirti\u00f3 en el horizonte de miles de personas provenientes de pueblos vecinos, as\u00ed como de zonas rurales del centro y sur de Espa\u00f1a que ten\u00edan la esperanza de una vida mejor ligada al empleo industrial. Como vemos en la siguiente imagen (ilustraci\u00f3n 3), de la nada se construyeron barrios enteros para acoger a las miles de personas que llegaban a Errenteria en busca de un futuro mejor.<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-2%20.jpg\" itemprop=\"contentUrl\" data-size=\"1600x1270\" data-index=\"0\" data-caption=\"Ilustraci\u00f3n 3. Obras de construcci\u00f3n del barrio obrero de Capuchinos en los a\u00f1os 1973 y 1974. Fuente: Archivo Municipal de Errenteria A015F201.\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-2%20.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Ilustraci\u00f3n 3. Obras de construcci\u00f3n del barrio obrero de Capuchinos en los a\u00f1os 1973 y 1974. Fuente: Archivo Municipal de Errenteria A015F201.<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>Sin embargo, los llamados a\u00f1os milagrosos se interrumpieron a mediados de los setenta, cuando el sistema de mecanismos internacionales que hab\u00eda apoyado los patrones de acumulaci\u00f3n de capital en las d\u00e9cadas precedentes comenz\u00f3 a desmoronarse. M\u00e1s all\u00e1 de la tan mencionada crisis del petr\u00f3leo, los factores que llevaron a esta situaci\u00f3n son muchos, y como menciona Jaime Palomera (2015: 25), destacan el fin del acuerdo de Bretton Woods, el aumento de la competencia en el sistema mundial con la aparici\u00f3n de nuevos actores, el problema del exceso de capacidad industrial o la ca\u00edda de las tasas de beneficio. Como consecuencia de todo ello, la industria entr\u00f3 en crisis, y con ello se quebr\u00f3 el modelo socioecon\u00f3mico basado en la centralidad del empleo como garante de protecci\u00f3n social y como mecanismo para trayectorias de vida estables y ascendentes.<\/p>\n\n\n\n<p>En el contexto espa\u00f1ol la crisis de los setenta coincidi\u00f3 con la muerte de Franco, y por lo tanto, con un momento hist\u00f3rico de auge de esperanzas de una vida mejor, ya sin dictadura. Sin embargo, el contexto de transici\u00f3n fue utilizado para gestar un discurso en el que se insisti\u00f3 que el camino hacia la democracia requer\u00eda de paz y estabilidad, por lo que se pidi\u00f3 a las clases trabajadoras <em>sacrificarse<\/em>. A grandes rasgos, se consolid\u00f3 la idea de que para salir de la crisis se necesitaba moderaci\u00f3n salarial, ya que de este modo las empresas en crisis aumentar\u00edan sus beneficios, los reinvertir\u00edan y crear\u00edan m\u00e1s puestos de trabajo. A cambio, el Estado empez\u00f3 a desarrollar las estructuras de bienestar en todos los \u00e1mbitos, internalizando en cierta forma los conflictos crecientes entre capital y trabajo, y seg\u00fan algunos autores como Bibiana Mendialdea y Nacho \u00c1lvarez (2005), conteniendo el malestar social y los posibles procesos revolucionarios.<\/p>\n\n\n\n<p>Poco despu\u00e9s, y con el objetivo de salir de la crisis, se dio el primero de una serie de acuerdos conocidos como los Pactos de la Moncloa (1977), en el cual, siguiendo las directrices del <span class=\"small-caps\">fmi<\/span> y la <span class=\"small-caps\">ocde<\/span>, las principales fuerzas pol\u00edticas y los dos sindicatos mayoritarios del pa\u00eds firmaron un tratado mediante el cual, seg\u00fan Miren Etxezarreta (1991), se despidieron del modelo fordista a favor de las ideas liberales que fueron tomando centralidad. Y <br>es que, como recoge Jaime Palomera (2015: 29-30), se dej\u00f3 atr\u00e1s el horizonte de pleno empleo y el fin de la pol\u00edtica econ\u00f3mica se redujo a la b\u00fasqueda de crecimiento, productividad y competitividad, marcando como prioridad la integraci\u00f3n internacional de la econom\u00eda espa\u00f1ola a trav\u00e9s de la liberalizaci\u00f3n. \u00c9ste era el camino, se dijo, para alcanzar los est\u00e1ndares de bienestar que hab\u00eda en otros Estados europeos.<\/p>\n\n\n\n<p>Para ello, los Pactos de la Moncloa apuntaron a dos procesos de liberalizaci\u00f3n y desregulaci\u00f3n. Por un lado, se dio una liberalizaci\u00f3n parcial del sistema financiero. Por el otro, buscaron la reestructuraci\u00f3n del mercado laboral, desregulando algunos de los derechos que hab\u00edan sido adquiridos por los trabajadores y reforzando formas de gesti\u00f3n de la fuerza de trabajo. Ahora bien, lo interesante aqu\u00ed, como puntualiza Elsa Santamar\u00eda (2009: 74), no es que estas formas de flexibilizaci\u00f3n fueran novedosas, de hecho, no eran desconocidas anteriormente, sino que comenzaron a ser expandidas y legitimadas en el contexto de cambio social.<\/p>\n\n\n\n<p>La promesa neoliberal de que el aumento de los beneficios empresariales generar\u00eda m\u00e1s empleo pronto result\u00f3 ser un espejismo. Con la liberalizaci\u00f3n de la econom\u00eda y la atenuaci\u00f3n de las fronteras comerciales, la industria local no pudo competir con las producciones m\u00e1s baratas de otros pa\u00edses. De hecho, las antiguas f\u00e1bricas de Errenteria segu\u00edan especializadas en sectores tradicionales de poco valor a\u00f1adido, basadas en el uso extensivo de mano de obra y con un desarrollo tecnol\u00f3gico lleno de carencias.<\/p>\n\n\n\n<p>Es as\u00ed como, en los ochenta, comenz\u00f3 el proceso de desindustrializaci\u00f3n bajo el eufemismo de la \u201creconversion industrial\u201d<em>.<\/em> La reconversi\u00f3n no fue otra cosa que un conjunto de medidas financieras, fiscales, laborales y tecno-organizativas dirigidas por el Estado y orientadas a la modernizaci\u00f3n de los sectores maduros afectados por la crisis (Torres, 1991: 166). La idea era transitar hacia una industria de valor a\u00f1adido, con empresas de menor tama\u00f1o y con buena capacidad exportadora. Sin embargo, en la pr\u00e1ctica dichas pol\u00edticas significaron el desmantelamiento de gran parte de la industria pesada que los poderes p\u00fablicos hab\u00edan dado por perdida. As\u00ed, si en 1975 hab\u00eda 10 003 empleos fabriles en Errenteria, en 1986 pas\u00f3 a haber 5 726, lo que representa que entre 1975 y 1986 se perdieron m\u00e1s de 300 empleos fabriles al a\u00f1o (Picavea, 1988: 21).<\/p>\n\n\n\n<p>En medio, cientos de personas desplazadas a otros lugares, prejubiladas o despedidas que ve\u00edan impasibles el fin de una forma de vida (Valdaliso, 2003; Barcenilla, 2004; Lacunza, 2012; Olaizola y Olaberria 2015; Ruzafa, 2017). Los despedidos volv\u00edan a casa sin expectativa laboral ninguna, al observar un mercado laboral incapaz de absorber a miles de trabajadores sobrantes en las nuevas condiciones productivas. De este modo, la ciudad pas\u00f3 de una situaci\u00f3n de pr\u00e1cticamente pleno empleo a mediados de los setenta, a una tasa de desempleo de 28.66% en 1986, lo que equivale a 4 500 personas desempleadas, o lo que es lo mismo, un desempleado de cada 2.48 personas (Picavea, 1988: 19).<\/p>\n\n\n\n<p>No obstante, detr\u00e1s de ese desempleo no s\u00f3lo se encontraban los trabajadores industriales que se hab\u00edan quedado recientemente sin trabajo. Por un lado, los j\u00f3venes de la generaci\u00f3n del <em>baby boom <\/em>se encontraron con un mercado laboral sin oportunidades para ellos. De hecho, en 1986, la mitad de los que buscaban empleo eran personas que no hab\u00edan trabajado con anterioridad (Picavea, 1988: 19). La crisis industrial se ceb\u00f3 tambi\u00e9n con las mujeres, y el desempleo entre ellas lleg\u00f3 alcanzar el 30% en 1986 (Picavea, 1988: 23). Muchas perdieron su empleo estable en la f\u00e1brica bajo el argumento de que no hab\u00eda trabajo para todos, que no quer\u00eda decir otra cosa que los hombres ten\u00edan mayor legitimidad para acceder y mantener el trabajo industrial y el <em>salario familiar.<\/em><\/p>\n\n\n\n<p>Dice Susana Narotzky (2016) que ante el fuerte desempleo estructural que se viv\u00eda en los ochenta, todas las esperanzas se depositaron en la inminente entrada a Europa. Sin embargo, la incorporaci\u00f3n en 1986 a la Comunidad Econ\u00f3mica Europea (<span class=\"small-caps\">cee<\/span>) result\u00f3 tener un precio alto, en tanto que los gobiernos de otros pa\u00edses vieron los salarios m\u00e1s bajos en Espa\u00f1a como una amenaza para sus sectores industriales y agrarios, por lo que exigieron al gobierno espa\u00f1ol que, por una parte, dejara de subvencionar a la industria nacional y, por otra, que abriera la v\u00eda de la privatizaci\u00f3n. La idea de \u201cno perder el tren de Europa\u201d y la modernidad fue repetida por las elites pol\u00edticas, econ\u00f3micas y sindicales como un argumento a favor de la reestructuraci\u00f3n de la industria y de la adopci\u00f3n de un modelo econ\u00f3mico particular cada vez m\u00e1s neoliberal<a class=\"anota\" id=\"anota3\" data-footnote=3>3<\/a> (Narotzky, 2016: 26). De hecho, como apunta Miren Etxezarreta (1991), la incorporaci\u00f3n se tradujo en una marginaci\u00f3n y subordinaci\u00f3n de la industria espa\u00f1ola a los intereses espec\u00edficos de las grandes multinacionales europeas, al tiempo que orient\u00f3 la econom\u00eda del pa\u00eds a las estrategias financieras e inmobiliarias.<\/p>\n\n\n\n<p>La incorporaci\u00f3n a Europa represent\u00f3 para Errenteria el fin definitivo de \u201cla peque\u00f1a Manchester\u201d. M\u00e1s f\u00e1bricas cerraron ante las dificultades de competir en el mercado internacional, y el resto pr\u00e1cticamente fueron adquiridas por capitales europeos. De hecho, una parte de la desindustrializaci\u00f3n de aquellos a\u00f1os fue consecuencia de la deslocalizaci\u00f3n. El cierre de las grandes f\u00e1bricas desat\u00f3 de nuevo una reacci\u00f3n en cadena: con su cierre, bajaron las persianas algunos talleres y comercios. La ciudad comenz\u00f3 una carrera hacia la terciarizaci\u00f3n; no porque el empleo en este sector ascendiera, de hecho tambi\u00e9n disminuy\u00f3, pero su peso relativo ascendi\u00f3 (Picavea, 1988: 23).<\/p>\n\n\n\n<p>Poco a poco, y tal como recogen distintos indicadores del Instituto Vasco de Estad\u00edstica, las reformas laborales empezaron a dar sus frutos, y consiguieron crear algo de empleo (de 1986 a 1991 la poblaci\u00f3n ocupada de Errenteria creci\u00f3 en casi 2 000 personas) con base en la expansi\u00f3n de los contratos de corta duraci\u00f3n, con un aumento de la temporalidad desconocida, o al menos no registrada oficialmente hasta entonces, que creci\u00f3 en ese periodo 244%. Pero adem\u00e1s, la creaci\u00f3n del empleo temporal fue de la mano de la destrucci\u00f3n del empleo fijo. En ese mismo periodo se perdieron m\u00e1s de 1 000 contratos fijos. De este modo, si a finales de los ochenta 90% de la poblaci\u00f3n asalariada ten\u00eda contrato fijo, a comienzos del noventa la cifra baj\u00f3 a 60%. Iba quedando claro que en el nuevo modelo, el mercado era incapaz de absorber una poblaci\u00f3n asalariada como lo hab\u00eda hecho. Comenzaba aqu\u00ed \u201cel mercado laboral dual\u201d, en tanto que, como resaltan Elsa Santamar\u00eda (2009: 75) o Jaime Palomera (2015: 35), se hizo visible la fragilidad de la forma asalariada de trabajo en la que se basaba el orden social, lo que borr\u00f3 la frontera que separaba a los trabajadores protegidos de los trabajadores sin protecci\u00f3n.<\/p>\n\n\n\n<p>La agon\u00eda lleg\u00f3 a los hogares cuando los subsidios por desempleo empezaron a agotarse. De hecho, a finales de los ochenta un informe elaborado por el gobierno vasco dictamin\u00f3 que algo m\u00e1s de una quinta parte de los hogares vascos se encontraban en situaci\u00f3n de pobreza (Gobierno Vasco, 1987: 77), debido al mencionado desempleo creado durante esos a\u00f1os y a la expansi\u00f3n del trabajo eventual y precario. En efecto, tal como muestran Bibiana Mendialdea y Nacho \u00c1lvarez (2005), las pol\u00edticas de flexibilidad llevadas durante estos a\u00f1os hicieron emerger el <em>working poor <\/em>o pobreza laboral, es decir, personas que a pesar de una relaci\u00f3n laboral normalizada se sit\u00faan por debajo del umbral de la pobreza, lo que expresa la ruptura con el periodo fordista que arrincon\u00f3 la pobreza en aquellos colectivos que no participaban con normalidad en el proceso del trabajo asalariado.<\/p>\n\n\n\n<p>La ciudad qued\u00f3 sumergida en una profunda crisis que abarc\u00f3 toda la d\u00e9cada de los noventa. Los empleos estables segu\u00edan destruy\u00e9ndose con el cierre continuado de las f\u00e1bricas, y aunque levemente, tambi\u00e9n se redujo el temporal. Las ruinas industriales configuraron el paisaje urbano y emocional de aquella \u00e9poca. La poblaci\u00f3n comenz\u00f3 a descender hasta caer por debajo de los 40 000 habitantes. Errenteria pas\u00f3 de ser un horizonte de vida a convertirse en una ciudad sin futuro.<\/p>\n\n\n\n<p>Sin embargo, a mediados de los noventa la luz al final del t\u00fanel comenz\u00f3 a aparecer en forma de ingentes cantidades de dinero p\u00fablico para el desarrollo de infraestructuras y equipamientos p\u00fablicos, en gran parte de las ayudas que proven\u00edan de la Uni\u00f3n Europea. Con ello, se entr\u00f3 en una vor\u00e1gine constructiva. Las obras p\u00fablicas se convirtieron en un elemento econ\u00f3mico clave de este periodo. La modernidad hab\u00eda llegado. En Errenteria, el ayuntamiento reconvirti\u00f3 el suelo, que pas\u00f3 de industrial a urbano y revaloriz\u00f3 como la espuma el metro cuadrado, y con ello las ruinas industriales dejaron sitio a parques, plazas, estacionamientos, viviendas y nuevos equipamientos p\u00fablicos, comerciales y culturales (Benito, 2007: 46). En las siguientes im\u00e1genes (ilustraciones 4 y 5) se observa la antigua f\u00e1brica de Niessen, que dio paso a un espacio compuesto por plaza, centro comercial y varios espacios culturales.<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-3.jpg\" itemprop=\"contentUrl\" data-size=\"1600x1040\" data-index=\"0\" data-caption=\"Ilustraci\u00f3n 4. Antigua f\u00e1brica de Niessen en los a\u00f1os setenta. Fuente: https:\/\/new.abb.com\/es\/100niessen\/historia, consultado el 14 de abril de 2020.\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-3.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure><figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-4.jpg\" itemprop=\"contentUrl\" data-size=\"685\u2006\u00d7\u2006400\" data-index=\"0\" data-caption=\"Ilustraci\u00f3n 5. Actual Centro Cultural Niessen. Fuente: http:\/\/www.centrocomercialniessen.com\/el-centro\/introduccion, consultado el 19 de febrero de 2021.\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-4.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Ilustraci\u00f3n 4. Antigua f\u00e1brica de Niessen en los a\u00f1os setenta. Fuente: https:\/\/new.abb.com\/es\/100niessen\/historia, consultado el 14 de abril de 2020.<\/div><div class=\"image-analysis\"><\/div><div class=\"caption\">Ilustraci\u00f3n 5. Actual Centro Cultural Niessen. Fuente: http:\/\/www.centrocomercialniessen.com\/el-centro\/introduccion, consultado el 19 de febrero de 2021.<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>De este modo, a finales de los noventa y principios de los dos mil se vivi\u00f3 una expansi\u00f3n econ\u00f3mica que redujo considerablemente las dram\u00e1ticas tasas de desempleo. Con ello Errenteria pas\u00f3 de tener casi 30% de desempleo a finales de los noventa a 11.8% en 2001 (Eustat, 2016b). Son muchos los factores que pudieran explicarlo, muy unidos a la terciarizaci\u00f3n de la econom\u00eda, entre los que destacan el auge de la construcci\u00f3n, el transporte, el comercio, la hosteler\u00eda o los servicios inmobiliarios, as\u00ed como el fortalecimiento del sector p\u00fablico y el consecuente aumento del empleo p\u00fablico en todos los \u00e1mbitos. Pero a rasgos generales, son dos las razones principales detr\u00e1s de esta expansi\u00f3n econ\u00f3mica.<\/p>\n\n\n\n<p>Por un lado, y tal como estudia Pablo Lopez Calle (2018: 6), gracias a la financiarizaci\u00f3n de la econom\u00eda, vinculada en parte con el endeudamiento de los hogares derivado de la diferencia de sus necesidades de reproducci\u00f3n y sus condiciones como fuerza de trabajo. Una financiarizaci\u00f3n que sostuvo coyunturalmente niveles de consumo que no se correspond\u00edan con los salarios de sus trabajos, lo que dio lugar a una burbuja de empleo y consumo. Por el otro, y como sostiene Jaime Palomera (2015: 35), por una mayor precarizaci\u00f3n del trabajo apoyada en sucesivas reformas laborales. Y es que, si bien estas transformaciones econ\u00f3micas hicieron surgir nuevas profesiones gracias al acceso en masa a las universidades de las nuevas generaciones, lo que a su vez se reflej\u00f3 en un cambio en la estructura ocupacional con un crecimiento de empleos cualificados, tambi\u00e9n es verdad que al mismo tiempo se extendieron los empleos precarios, temporales y parciales unidos a las necesidades de los nuevos sectores emergentes.<\/p>\n\n\n\n<p>De este modo, el mercado laboral qued\u00f3 segmentado por una clase de trabajadores con contratos fijos y estables, por una parte, y por trabajadores encadenados a contratos temporales y al subempleo por otra. En 2001 en Errenteria, 66% de las personas asalariadas ten\u00edan un contrato fijo, frente a 34% con contrato temporal (Eustat, 2016). Errenteria, con unos niveles de formaci\u00f3n visiblemente inferiores que los del territorio, aliment\u00f3 en mayor medida que la provincia este segmento. El \u201cej\u00e9rcito de reserva\u201d de este \u00faltimo segmento, clave en la expansi\u00f3n econ\u00f3mica de aquellos a\u00f1os, estaba compuesto b\u00e1sicamente por mujeres, j\u00f3venes y migrantes extracomunitarios que llegaron masivamente a la ciudad a partir de los primeros a\u00f1os del nuevo siglo y ocuparon las peores posiciones del mercado laboral: como mozos en el puerto de Pasaia o en las cadenas log\u00edsticas de las empresas de transporte, de peones en la construcci\u00f3n, de dependientas y auxiliares de camareras en las grandes superficies, as\u00ed como de trabajadoras dom\u00e9sticas.<\/p>\n\n\n\n<p>El estallido financiero de 2007-2008 vino a manifestar la fragilidad de esta expansi\u00f3n, basado en la burbuja inmobiliaria, en el endeudamiento de los hogares y la precarizaci\u00f3n de las condiciones de trabajo. Si bien la crisis generada en Errenteria no ten\u00eda parang\u00f3n con lo que hab\u00eda sucedido a\u00f1os atr\u00e1s, ni se parec\u00eda a la realidad dram\u00e1tica de otros lugares dependientes del turismo y la construcci\u00f3n, la tasa de paro tambi\u00e9n se dispar\u00f3 en la ciudad hasta alcanzar el 15.8% en el 2015 (Eustat, 2016b). Pero adem\u00e1s, las pol\u00edticas de austeridad basadas en los recortes del gasto p\u00fablico, las privatizaciones, las restricciones en la asistencia social o las reformas laborales y de pensiones, entre otros factores, intensificaron la precarizaci\u00f3n de las condiciones de vida y de trabajo de amplias capas sociales. Esto, junto con una intensa moralizaci\u00f3n sobre que hab\u00edan \u201cvivido por encima de sus posibilidades\u201d, vendr\u00eda a redefinir los marcos pol\u00edticos de redistribuci\u00f3n forjados por el Estado keynesiano fordista y reconfigurar de paso el horizonte y las esperanzas de la clase media.<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-5.jpg\" itemprop=\"contentUrl\" data-size=\"1200x901\" data-index=\"0\" data-caption=\"Ilustraci\u00f3n 6. Ni\u00f1o jugando en el barrio obrero de Capuchinos. Foto donada por un interlocutor de Errenteria.\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-5.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Ilustraci\u00f3n 6. Ni\u00f1o jugando en el barrio obrero de Capuchinos. Foto donada por un interlocutor de Errenteria.<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<h2 class=\"wp-block-heading\">La ruptura generacional: de los pasados pr\u00f3speros y los presentes precarios<\/h2>\n\n\n\n<p class=\"no-indent\">Ana, \u00c1lex y Eli provienen de familias de entornos rurales que llegaron a Errenteria con la esperanza de que el trabajo industrial les garantizar\u00eda una vida mejor. Atra\u00eddos por la r\u00e1pida industrializaci\u00f3n, la abundancia del trabajo y el crecimiento econ\u00f3mico que parec\u00eda vivir la ciudad, vieron en Errenteria la forma de prosperar y vivir dignamente.<\/p>\n\n\n\n<p>Ana, proven\u00eda de una de familia rural del centro de Espa\u00f1a que se termin\u00f3 convirtiendo en una de las familias protagonistas del primer flujo migratorio del siglo <span class=\"small-caps\">xx<\/span> hacia Errenteria. Su madre, maravillada de la vida que dec\u00eda disfrutar su hermana, que hab\u00eda migrado en los cincuenta a la ciudad, convenci\u00f3 pocos a\u00f1os despu\u00e9s a su pareja para que empezaran un nuevo proyecto de vida en el norte. En pocos a\u00f1os, \u00e9l consigui\u00f3 trabajo en una de las grandes f\u00e1bricas de la ciudad, y ella se encarg\u00f3 de criar a los tres hijos que tuvieron.<\/p>\n\n\n\n<p>De igual manera, a principios de los sesenta la madre de \u00c1lex dej\u00f3 con diecisiete a\u00f1os su peque\u00f1o pueblo rural del norte siguiendo a tantas otras vecinas que empezaron a emplearse en las grandes industrias de Errenteria y Pasaia. Ah\u00ed conoci\u00f3 al que ser\u00eda su marido, un joven de un pueblo aleda\u00f1o apasionado por el campo, pero convertido en alba\u00f1il. La madre de \u00c1lex trabaj\u00f3 en la f\u00e1brica hasta que la comentada <em>reconversi\u00f3n industrial<\/em> la termin\u00f3 de expulsar, y desde entonces la familia se apoy\u00f3 en el dinero que tra\u00eda el padre a casa. Ella cri\u00f3 a los cuatro hijos que tuvieron, y \u00e9l trabaj\u00f3 en la construcci\u00f3n por cuenta propia hasta que se prejubil\u00f3 a principios del 2000.<\/p>\n\n\n\n<p>La madre de Eli tambi\u00e9n deposit\u00f3 su esperanza en que el trabajo industrial posibilitar\u00eda un futuro mejor. Por eso en los setenta se acerc\u00f3 desde un pueblo vecino a trabajar a las grandes f\u00e1bricas de la ciudad. Sin embargo, como la madre de \u00c1lex, con la <em>reconversi\u00f3n<\/em> tambi\u00e9n se repleg\u00f3 en casa a cuidar de sus dos hijos, mientras su marido trabaj\u00f3 como funcionario administrativo hasta tomar una buena prejubilaci\u00f3n. Tanto ella como la madre de \u00c1lex no volvieron a emplearse hasta a\u00f1os m\u00e1s tarde, cuando los hijos hab\u00edan crecido, ya como fuerza de trabajo precarizada en el sector de servicios. En cualquier caso, de una forma y otra, todas ellas acataron lo que Jane Lewis (2002: 332) describe como el modelo de organizaci\u00f3n social que sosten\u00eda la reproducci\u00f3n del modelo de bienestar keynesiano fordista, el cual otorgaba al hombre la responsabilidad de proveer a la familia y lo defin\u00eda como \u201cel hombre ganador del pan\u201d, mientras que la mujer se defin\u00eda desde la vocaci\u00f3n al trabajo dom\u00e9stico para configurarse como \u201cama de casa\u201d.<\/p>\n\n\n\n<p>En definitiva, para estos hogares el acceso al empleo no fue un problema grave, y en principio, si uno quer\u00eda, era m\u00e1s o menos factible tener el mismo empleo de por vida. El problema en todo caso era el mal sueldo, o que el bienestar y los proyectos de vida estaban ligados a los estrechos m\u00e1rgenes de la familia. Una \u201c\u00e9tica del trabajo y la industriosidad\u201d estaba en la base de estos proyectos de vida, que justificaba los sacrificios que se deb\u00edan hacer, en el empleo como en el hogar, para lograr mejores condiciones de vida. Es decir, estos sacrificios cotidianos sosten\u00edan y cobraban sentido en relaci\u00f3n con las proyecciones futuras. Adem\u00e1s, las luchas sindicales y sus continuadas huelgas iban haciendo posibles aumentos salariales sustanciales que mejoraban las perspectivas futuras. Todo ello proporcion\u00f3 un grado de certidumbre para entablar proyectos de vida duraderos y consistentes, un poder pensar a futuro como unidad econ\u00f3mica. Pero adem\u00e1s era un poder mirar al futuro con tranquilidad, dando por hecho la jubilaci\u00f3n o la protecci\u00f3n social, sobre todo para los que Luis Enrique Alonso (2007: 100) llama los \u201cciudadanos laborales\u201d, es decir, los ciudadanos que se encuentran dentro de la realidad salarial, en tanto que resalta que buena parte de los derechos sociales pasan por la contribuci\u00f3n al mercado laboral. De hecho, este modelo garantiz\u00f3 pensiones dignas sobre todo a los que se emplearon en los trabajos estables de la industria, mientras que ellas accedieron en mayor medida a pensiones ajustadas y precarias. Finalmente era un poder mirar al futuro mediante unas aspiraciones ascendentes, donde el progreso material, eso s\u00ed como unidad econ\u00f3mica, entraba en los c\u00e1lculos de los hogares.<\/p>\n\n\n\n<p>De este modo, Ana, \u00c1lex y Eli a menudo comparaban sus vidas con los est\u00e1ndares alcanzados por las generaciones anteriores en etapas similares de su vida. Los tres consideraban que sus familias hab\u00edan conseguido convertirse en esas clases medias que pose\u00edan en cierta forma seguridad, estabilidad y comodidad. Insist\u00edan que sus padres partieron de condiciones humildes, pero que al final terminaron alcanzando los est\u00e1ndares de clase media. Todos ellos, por ejemplo, se hicieron en un momento u otro de una segunda vivienda, algo impensable para ellos. De ah\u00ed que al valorar sus trayectorias vitales los tres afirmaban sentir una involuci\u00f3n de sus expectativas biogr\u00e1ficas. En particular, se centraban en sus experiencias laborales, que lejos de ser lineales y ascendentes se caracterizaban por ser trayectorias fragmentadas, reversibles, flexibles y precarizadas para confirmar dicho retroceso.<\/p>\n\n\n\n<p>Eli, por ejemplo, dej\u00f3 sus estudios a edad temprana para trabajar de cuidadora a \u00faltimos de los noventa. Con diecinueve a\u00f1os empez\u00f3 a vivir con su pareja, un electricista que trabajaba de manera informal, para dos a\u00f1os despu\u00e9s con la llegada de su primer hijo la pareja acordara que Eli se dedicar\u00eda a cuidar del beb\u00e9 y la casa. Eran los a\u00f1os de auge de la construcci\u00f3n y con el dinero que \u00e9l tra\u00eda a casa se las arreglaban para vivir. Diez a\u00f1os m\u00e1s tarde, en pleno estallido financiero y con un segundo hijo en brazos, se divorciaron. Eli se encontr\u00f3 entonces con que s\u00f3lo ten\u00eda estudios secundarios, no ten\u00eda dinero propio, ni apenas experiencia laboral. \u201c\u00bfQu\u00e9 hago yo ahora?\u201d, se pregunt\u00f3; y es que con el fin de su matrimonio ca\u00eda tambi\u00e9n el modelo econ\u00f3mico en el que bas\u00f3 su confianza. Eli acudi\u00f3 a servicios sociales y a los meses accedi\u00f3 a la \u201cRenta de Garant\u00eda de Ingresos\u201d (<span class=\"small-caps\">rgi<\/span>), una prestaci\u00f3n econ\u00f3mica mensual del gobierno vasco que fue creada para dar respuesta a la crisis fordista y que en la actualidad representa la cobertura o el sistema de protecci\u00f3n m\u00e1s avanzado de todo el Estado espa\u00f1ol.<\/p>\n\n\n\n<p>Gracias a esa prestaci\u00f3n social, Eli pudo sacar su vida y la de sus hijos adelante, no sin pocos \u201cmalabarismos\u201d (Villarreal 2017: 92), ya que el dinero que recib\u00eda mes a mes nunca fue suficiente para vivir.<\/p>\n\n\n\n<p>Para \u00c1lex la sensaci\u00f3n de retroceso que experimentaba su generaci\u00f3n era demasiado evidente. \u201cLos buenos tiempos\u201d, como sol\u00eda describir los tiempos de bonanza, hab\u00edan pasado y ahora ellos ten\u00edan menos oportunidades y tendr\u00edan que afrontar condiciones de vida m\u00e1s duras que las generaciones mayores:<\/p>\n\n\n\n<p class=\"verse\">Yo creo que ten\u00edamos metido dentro del imaginario colectivo que vivir\u00edamos mejor que la generaci\u00f3n anterior, \u00bfno? Yo por parte de mis padres tambi\u00e9n recib\u00ed ese mensaje. Ellos tuvieron que trabaj\u00e1rselo mucho. Mi padre no fue a la escuela, y mi madre s\u00ed que fue y quiso seguir estudiando, pero no pudo. \u00bfEntonces, es eso, no? Poder dar esas oportunidades, no tener que trabaj\u00e1rselo tanto para poder disfrutar de la vida. Y en algunas cosas s\u00ed (que lo hemos podido hacer), pero en otras cosas\u2026 o igual s\u00ed que lo vivimos, igual hasta que yo fui a la universidad s\u00ed que hab\u00eda ese contexto socioecon\u00f3mico, pero luego ya me di cuenta de que para conseguir una casa o tener otro nivel de bienestar lo tendr\u00edamos m\u00e1s dif\u00edcil.<\/p>\n\n\n\n<p>Para \u00e9l, la promesa de movilidad social ascendente result\u00f3 falsa a pocos a\u00f1os de terminar sus estudios en la universidad. Realmente la universidad hab\u00eda tenido para \u00e9l un sentido m\u00e1s de crecimiento personal que laboral, aunque confiaba que una carrera universitaria le abrir\u00eda las puertas a una vida mejor en una econom\u00eda que parec\u00eda orientarse al trabajo cualificado. Aun as\u00ed, a principios del 2000, despu\u00e9s de trabajar unos a\u00f1os como becario en proyectos de investigaci\u00f3n en la universidad y cansado de no llegar a fin de mes, pas\u00f3 a la hosteler\u00eda. Sin grandes esperanzas laborales, con veintis\u00e9is a\u00f1os le ofrecieron trabajo en una cooperativa, y aunque ese trabajo tampoco estaba relacionado con sus estudios, \u00c1lex acept\u00f3. Empez\u00f3 con pocas horas, compagin\u00e1ndolo con trabajo en bares, y en menos de cinco a\u00f1os pas\u00f3 a ser socio cooperativista. Por aquel entonces la rotaci\u00f3n de trabajadores en la cooperativa era grande, ya que los sueldos no eran gran cosa. Pero despu\u00e9s lleg\u00f3 la crisis del 2008, lo que a principios del 2000 se denunciaba como un mal sueldo empez\u00f3 a verse como un sueldo aceptable. Es decir que ser mileurista,<a class=\"anota\" id=\"anota4\" data-footnote=4>4<\/a> en tanto ser joven con estudios e idiomas, con un sueldo alrededor de los mil euros y en empleos que no iban acordes con su formaci\u00f3n no parec\u00eda tanto drama, y con la bajada de expectativas la rotaci\u00f3n de trabajadores disminuy\u00f3. Hab\u00edan pasado diecis\u00e9is a\u00f1os desde que entr\u00f3 en la cooperativa y \u00c1lex segu\u00eda ah\u00ed. Sin embargo, hab\u00eda imaginado que a estas alturas su situaci\u00f3n econ\u00f3mica ser\u00eda considerablemente m\u00e1s holgada y estable, lo que a su vez influ\u00eda en unas aspiraciones cada vez m\u00e1s descendentes:<\/p>\n\n\n\n<p class=\"verse\">Eh, a ver. Yo con veinte a\u00f1os he tenido mejores condiciones de vida que mis padres. Con cuarenta a\u00f1os est\u00e1 siendo parecido. Y con sesenta tengo mis dudas. Yo creo que tendr\u00e9 menos oportunidades, menos recursos que mis padres.<\/p>\n\n\n\n<p>Una vida segura y estable no fue nunca algo que busc\u00f3 Ana. Aunque se cri\u00f3 a partir de esos marcos, y sus padres \u201cesperaban que fuera ministra por lo menos\u201d, Ana y parte de una generaci\u00f3n que vivi\u00f3 la juventud entre los ochenta y noventa construyeron sus vidas en oposici\u00f3n a esta sem\u00e1ntica y estos horizontes de clase media. Su generaci\u00f3n fue la carne de ca\u00f1\u00f3n del mercado flexible. Primero se configuraron como \u201cla generaci\u00f3n perdida\u201d y se encontraron con un mercado laboral de dif\u00edcil acceso. Como retrata Victoria Goddard (2019: 12), la desindustrializaci\u00f3n interrumpi\u00f3 los ciclos de trabajo y las formas de vida transmitidas de forma intergeneracional en estas ciudades, lo que hizo perder la credibilidad y la eficacia de los proyectos de vida construidos por la generaci\u00f3n anterior. Esta generaci\u00f3n convivi\u00f3 con el desempleo y con los empleos temporales o \u201ccurrillos\u201d, empleos de corta duraci\u00f3n, mal pagados y generalmente tareas menos valoradas y con menos estatus que el empleo industrial, con lo cual se configur\u00f3 como la carne de ca\u00f1\u00f3n del mercado flexible y precario. De hecho, una parte de esta generaci\u00f3n percibi\u00f3 el mercado flexible como un signo de libertad, lejos de las rigideces de las formas de trabajo y de vida de sus padres. Es m\u00e1s, muchos encontraron en el no-futuro, en tanto una despreocupaci\u00f3n por \u00e9l, la liberaci\u00f3n. Fue una incertidumbre impuesta por el marco de oportunidades, pero tambi\u00e9n en cierta forma deseada, buscada y compartida:<\/p>\n\n\n\n<p class=\"verse\">O sea, que te quiero decir que yo soy consciente de que podr\u00eda tener m\u00e1s pasta (dinero), que hubiera podido tener un curro (trabajo) seguro, pero yo qu\u00e9 s\u00e9. He optado por otro tipo de vida. Como ir a M\u00e9xico y montar el centro cultural La Habanera. Si hubiera tenido una hipoteca, familia, un curro fijo, pues no hubiera montado La Habanera. Y no hubi\u00e9ramos bailado as\u00ed.<\/p>\n\n\n\n<p>De hecho, Ana era percibida por muchos como una \u201cbuscavidas\u201d, por verla siempre cambiando de un trabajo a otro para ganarse la vida a pesar de que avanzaba en la edad. Y es que, en estos <em>otros <\/em>marcos, el trabajo s\u00f3lo deb\u00eda garantizar el hoy, que diera \u201clo suficiente para vivir\u201d era lo que buscaba, como ella lo define \u201cpara comer, para echarme unos tragos, para fumar y poco m\u00e1s\u201d. Y de hecho, era posible. Y en ese contexto de abundancia laboral, que los empleos no se sostuvieran en el tiempo, fuera por la raz\u00f3n que fuera, no era un problema. De hecho, Ana siempre se busc\u00f3 la vida con empleos que duraban de uno a tres a\u00f1os vista. Por lo general sin contrato, Ana ha trabajado, en m\u00e1s de 20 \u201ccurrillos\u201d, mayormente en hosteler\u00eda, pero tambi\u00e9n como transportista, agente de seguros, cuidadora o vigilante.<\/p>\n\n\n\n<p>Sin embargo, este proyecto de vida se hab\u00eda hecho especialmente vulnerable los \u00faltimos a\u00f1os, con la disminuci\u00f3n de la oferta de trabajo y la devaluaci\u00f3n salarial impulsada por sucesivas reformas laborales. \u201cSiempre he tenido mucho acceso a mierdas de trabajo, y ya ves que ahora ya no hay ni mierdas\u201d, se quejaba al valorar su trayectoria laboral a partir del 2011. Con el \u00faltimo estallido financiero, Ana empez\u00f3 a notar que ya no le ofrec\u00edan ni tantos trabajos, ni en las condiciones de antes. En los \u00faltimos tres a\u00f1os hab\u00eda tenido cuatro empleos consecutivos y los hab\u00eda alternado con otros cuatro \u201ccurrillos\u201d, y cada vez, reconoc\u00eda, se le hac\u00eda m\u00e1s dif\u00edcil mantener un empleo en el tiempo. A la corta durabilidad de sus trabajos se a\u00f1ad\u00eda el hecho que \u00faltimamente se alargaban los meses en desempleo.<\/p>\n\n\n\n<p>De ah\u00ed que Ana se empezaba a sentir que ya no ten\u00eda la energ\u00eda que ese estilo de vida requer\u00eda. Que la mayor\u00eda de la gente con la que compart\u00eda ese modo de vida se hubiera, como dice ella, \u201checho mayor\u201d, \u201casentado\u201d, hac\u00eda que se sintiera cada vez m\u00e1s sola, vulnerable e incomprendida en su modo de vida. \u201cTodo era m\u00e1s f\u00e1cil antes\u201d, cuando era joven y ese proyecto de vida que abrazaba el cortoplacismo ten\u00eda un modelo econ\u00f3mico para sostenerse y un grupo de gente para compartirlo.<\/p>\n\n\n\n<p>De hecho, cuando en el transcurso de trabajo de campo los conoc\u00ed, me pareci\u00f3 que de formas muy distintas la incertidumbre atravesaba sus medios de vida. La consideraci\u00f3n de que no hubiera recursos monetarios en un futuro inmediato, o no saber c\u00f3mo ser\u00edan \u00e9stos a medio plazo, entraba de lleno en los c\u00e1lculos cotidianos de todos ellos. Bien por la falta de garant\u00edas futuras, o bien por la propia escasez presupuestaria, el hecho es que sus econom\u00edas solo parec\u00edan poder abarcar, como mucho, lo inminente. Los tres consum\u00edan sus ingresos al mes y apenas ten\u00edan posibilidades de generar ahorro monetario.<\/p>\n\n\n\n<p>A Ana, a sus cincuenta y dos a\u00f1os, reci\u00e9n le hab\u00edan llamado de un programa para mujeres en peligro de exclusi\u00f3n del gobierno local, ofreci\u00e9ndole un trabajo protegido. Con ello, dejaba la cocina de un bar en el que trabajaba veinte horas los fines de semana. Con este nuevo empleo Ana trabajar\u00eda a jornada completa de lunes a viernes por 900 euros mensuales. Sin embargo, este nuevo trabajo tambi\u00e9n ten\u00eda fecha de caducidad, ya que era una oferta de empleo por seis meses y no podr\u00eda volver a optar a ella hasta pasados tres a\u00f1os. Y sin embargo Ana acept\u00f3; despu\u00e9s, como ella dec\u00eda, ya se buscar\u00eda la vida.<\/p>\n\n\n\n<p>A \u00c1lex, en cambio, aunque sent\u00eda la seguridad de tener el trabajo garantizado, le segu\u00eda angustiando que su sueldo estuviera sujeto a la contrataci\u00f3n de servicios, como cuando empez\u00f3. Es decir, que a sus cuarenta y dos a\u00f1os y con m\u00e1s de quince a\u00f1os trabajando en la misma cooperativa, Alex no sab\u00eda lo que ganar\u00eda, ni el horario en que trabajar\u00eda un a\u00f1o tras otro, lo que le creaba inseguridad y ansiedad. Adem\u00e1s, desde el segundo a\u00f1o del estallido financiero y hasta hac\u00eda apenas tres a\u00f1os, Alex hab\u00eda tenido su sueldo congelado debido a la bajada de clientes y a las pol\u00edticas de ajuste que recortaron las subvenciones para cooperativas como la suya. Su sueldo cuando le conoc\u00ed rondaba los 1 280 euros. Adem\u00e1s, su angustia por no saber lo que ganar\u00eda se intensific\u00f3 desde hac\u00eda dos a\u00f1os, cuando decidi\u00f3 destinar todos sus ahorros para acceder a una hipoteca y comprarse una peque\u00f1a casa, debido a que de nuevo los sueldos comenzaban, aunque levemente, a crecer.<\/p>\n\n\n\n<p>Y Eli segu\u00eda diez a\u00f1os despu\u00e9s siendo perceptora de la <span class=\"small-caps\">rgi<\/span>. Ten\u00eda entonces treinta y siete a\u00f1os y tres hijos menores de quince a\u00f1os. Viv\u00eda con su pareja actual y sus hijos en una casa cuya hipoteca reci\u00e9n hab\u00edan adquirido. El salario social, junto con la manutenci\u00f3n alimentaria del padre de los primeros dos hijos, tambi\u00e9n en una situaci\u00f3n de crisis despu\u00e9s de que la construcci\u00f3n parara, ten\u00eda unos ingresos mensuales de 940 euros. Adem\u00e1s, acced\u00eda a algunas otras ayudas sociales durante el a\u00f1o. Y aunque el dinero recibido no era suficiente para tirar adelante, y siempre era necesario llevar a cabo malabarismos, lo que m\u00e1s le pesaba a Eli durante estos a\u00f1os era el control institucional que deb\u00eda aguantar con tal de mantener la ayuda. Y es que la tendencia restrictiva en las ayudas sociales que puede rastrearse desde el 2012, y cuya \u00faltima expresi\u00f3n era la propuesta de reforma del 2018, adem\u00e1s de intensificar las medidas restrictivas ten\u00eda una clara vocaci\u00f3n disciplinadora, pues legitimaba el control permanente y reforzado de quienes recib\u00edan la prestaci\u00f3n. Con ello se polariz\u00f3 el debate sobre qui\u00e9n era merecedor del salario social. \u201cTengo la sensaci\u00f3n de que estoy pidiendo de rodillas, darme por favor\u201d, me explicaba Eli para enfatizar lo costoso que vital y socialmente le resultaba mantener la prestaci\u00f3n social, por lo que en los \u00faltimos a\u00f1os y siempre que pod\u00eda, Eli hab\u00eda optado por llevar a escondidas su condici\u00f3n de perceptora en los nuevos c\u00edrculos sociales, ya fueran vecinos, padres y madres de la escuela etc\u00e9tera.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u201cViviremos peor que nuestros padres\u201d: la percepci\u00f3n de retroceso y la desorientaci\u00f3n sobre el ma\u00f1ana<\/h2>\n\n\n\n<p class=\"no-indent\">Dice David Zeitlyn (2015: 399) que los futuros pasados, incluyendo las esperanzas y los temores recordados, interfieren de alguna forma en el futuro real. Lo hacen porque en contra del sentido com\u00fan que supone que el pasado es algo fijo e inamovible, \u00e9ste es significado y sentido tantas veces como se necesite. En efecto, como apunta Magdalena Villarreal (2008: 102), el tiempo no es tanto un marco evolutivo externo dentro del cual se dan las relaciones sociales, sino que es tambi\u00e9n construido y, como tal, se significa y se utiliza. Pero adem\u00e1s, Zeitlyn pone la atenci\u00f3n en que las din\u00e1micas afectivas son como las sensaciones que producen v\u00e9rtigo, estancamiento, entusiasmo, ansiedad o desorientaci\u00f3n, y se\u00f1ala que son centrales a la hora de comprender los procesos de cambio social.<\/p>\n\n\n\n<p>De ah\u00ed se puede suponer que a medida que se han transformado las trayectorias vitales se haya distorsionado tambi\u00e9n la experiencia temporal de progreso econ\u00f3mico implacable. Ahora bien, tal como constatara Daniel Knight (2016) al examinar las consecuencias de la austeridad prolongada en el contexto griego, el material etnogr\u00e1fico recogido en Errenteria tambi\u00e9n evidencia un intenso momento de confusi\u00f3n y de \u201cv\u00e9rtigo temporal\u201d en el contexto vasco. En particular, las pol\u00edticas de ajuste estructural, y muy especialmente las reformas en el Sistema P\u00fablico de Pensiones hab\u00edan colocado el futuro en el presente y hecho expl\u00edcita la quiebra de la <br>reproducci\u00f3n social. C\u00f3mo proveerse materialmente y de cuidados en <br>la vejez era algo que generaba inquietud y confusi\u00f3n. Por ejemplo, a Eli, por un lado, le asustaba no haber tenido a\u00f1os cotizados, pero de todos modos dec\u00eda que tampoco confiaba en que el sistema de pensiones perdurara: \u201cLo \u00fanico que me ha preocupado ha sido no cotizar para la jubilaci\u00f3n. Pero bueno, que luego tambi\u00e9n pienso que la jubilaci\u00f3n va a desaparecer. Entonces, total: no s\u00e9, no s\u00e9\u201d.<\/p>\n\n\n\n<p>Para \u00c1lex tambi\u00e9n, aunque evitara conscientemente pensar en el futuro y la jubilaci\u00f3n, la preocupaci\u00f3n y la angustia siempre estaban ah\u00ed:<\/p>\n\n\n\n<p class=\"verse\">La otra vez tambi\u00e9n creo que te lo dije. A m\u00ed me preocupa bastante, bueno que no lo tengo metido aqu\u00ed \u2013y se toca la cabeza\u2013 , porque si no me agobiar\u00eda; pero lo de las pensiones, cuando nos retiremos, yo no s\u00e9 qu\u00e9 ser\u00e1 de nuestras vidas. No s\u00e9 si tendremos pensi\u00f3n, o c\u00f3mo ser\u00e1n las pensiones, para qu\u00e9 nos dar\u00e1 eso. Y entonces yo en esas cosas veo que estamos yendo para atr\u00e1s. Que viviremos peores condiciones. Que al mismo tiempo tampoco es verdad, porque yo, claro, he podido ir a la universidad, y eso para mis padres era inimaginable.<\/p>\n\n\n\n<p>Era una desorientaci\u00f3n que en ocasiones tambi\u00e9n ten\u00eda que ver con la rapidez con la que las condiciones cambiaban, por lo que se hac\u00eda dif\u00edcil incluso trazar estrategias a futuro, o como dec\u00eda Ana respecto de sus planes de futuro, que ten\u00eda \u201cdemasiados y ninguno\u201d<em>.<\/em><\/p>\n\n\n\n<p>De hecho, aunque ciertas alternativas pol\u00edticas hab\u00edan suscitado promesas de mejora y cambio social, muchos se encontraban relativamente desilusionados por una sensaci\u00f3n de incontrolabilidad y de limitaci\u00f3n a la hora de poder mejorar las condiciones de vida, lo que Marina Garc\u00e9s (2017: 16) denomina \u201cla nueva experiencia del l\u00edmite\u201d. Con ello, las esperanzas de llevar una buena vida se formulaban como estrategias individuales centradas en la familia. Lejos del ideal de autosuficiencia del <em>homo economicus<\/em> y ante el desmantelamiento latente del estado de bienestar, cada vez era m\u00e1s aceptada la idea de necesitar de la ayuda de la familia para echar a andar y sostener los propios proyectos de vida y las expectativas generacionales. Se configuraba as\u00ed lo que James Petras (1995: 28-29) denomina \u201cel sistema de bienestar familiar\u201d, en el sentido en que las vidas y expectativas de estas personas precarizadas se sosten\u00edan gracias a la prosperidad pasada, ya fuera por las viviendas en propiedad libre de hipoteca, los ahorros y las buenas pensiones sobre todo de los \u201chombres proveedores del pan\u201d<em>.<\/em> Y a\u00f1adir\u00eda, por el servicio continuado de \u201clas abuelas\u201d en tareas de prestaci\u00f3n de cuidados.<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-6.jpg\" itemprop=\"contentUrl\" data-size=\"1600x900\" data-index=\"0\" data-caption=\"Ilustraci\u00f3n 7. \u201cPensionistas y f\u00e1bricas\u201d. Fotograf\u00eda tomada en el trabajo de campo 2017-2018. Autor\u00eda: Uzuri Aboitiz.\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-6.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Ilustraci\u00f3n 7. \u201cPensionistas y f\u00e1bricas\u201d. Fotograf\u00eda tomada en el trabajo de campo 2017-2018. Autor\u00eda: Uzuri Aboitiz.<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>Sin embargo, la vulnerabilidad de los proyectos de vida y la necesidad de apoyarse en la familia eran vividas para la mayor\u00eda con cierta frustraci\u00f3n, al entenderlas como una involuci\u00f3n de los proyectos de vida y una p\u00e9rdida de autonom\u00eda de lo que ten\u00eda que significar la vida adulta. Esto era especialmente visible en Eli y \u00c1lex. Por ejemplo, a Eli le frustraba encontrarse cotidianamente pidiendo favores a sus padres y pareja para llegar a fin de mes, al mismo tiempo que exigia a la familia su deber de ayudar como responsabilidad moral natural de los lazos familiares. A \u00c1lex, que siempre hab\u00eda intentando no necesitar ayuda de nadie, el desmantelamiento del estado de bienestar y la \u201crehogarizaci\u00f3n\u201d<a class=\"anota\" id=\"anota5\" data-footnote=5>5<\/a> del sostenimiento de la vida lo hac\u00eda sentir profundamente desprotegido. \u201c\u00bfQui\u00e9n cuidar\u00e1 de m\u00ed cuando me haga mayor?\u201d, me dijo una vez angustiado, \u00e9l que no pretend\u00eda tener ni pareja ni hijos. El futuro se presentaba vago y poco esperanzador:<\/p>\n\n\n\n<p class=\"verse\">Creo que se avecinan crisis, y ser\u00e1n cada vez m\u00e1s seguidas, lo tengo claro. \u00bfQu\u00e9 pasar\u00e1 con nuestras pensiones? \u00bfQu\u00e9 haremos cuando nos hagamos mayores? \u00bfQu\u00e9 hacemos, continuar trabajando? Lo imagino como un agujero negro. Me imagino como en Estados Unidos, todo lleno de <em>homeless<\/em> las calles. Es algo que me preocupa mucho.<\/p>\n\n\n\n<p>En definitiva, las promesas de una vida de goce, disfrute y oportunidades ilimitadas se desdibujaban. Los futuros posibles se reduc\u00edan, los sue\u00f1os menguaban y las aspiraciones descend\u00edan. En su juventud, \u00c1lex se hab\u00eda imaginado una vida resuelta en su vejez, en el que volver\u00eda a la universidad por gusto, mientras tendr\u00eda las necesidades cubiertas. Ahora, sin embargo, sent\u00eda que hab\u00eda que conformarse con menos, y reconoc\u00eda que algunos de sus sue\u00f1os a futuro comenzaban a supeditarse:<\/p>\n\n\n\n<p class=\"verse\">Me acuerdo cuando era m\u00e1s joven, en la universidad, me fui de Erasmus<a class=\"anota\" id=\"anota6\" data-footnote=6>6<\/a> y conoc\u00ed a una chica sueca. Por aquel entonces, yo sol\u00eda decir que cuando me jubile volver\u00eda a la universidad y volver\u00eda a ir de Erasmus. Los dos ten\u00edamos ese plan. Ahora me doy cuenta que esto no podr\u00e1 ser.<\/p>\n\n\n\n<p>Ahora bien, los periodos de crisis abren tambi\u00e9n ventanas temporales donde pasado, presente y futuro se rearticulan de maneras singulares abriendo nuevos caminos a la esperanza. De hecho, a pesar de los futuros perdidos, las promesas no cumplidas, los planes devastados y los retrocesos experimentados de todas las formas sociales y materiales imaginables, muchas de las personas con las que conviv\u00ed conservaban la esperanza de mantener e incluso a veces mejorar su nivel de vida. Esta creencia en un mejor futuro se manifestaba recurrentemente como una despreocupaci\u00f3n por ella. Sin embargo, esto no debe confundirse con la ausencia de ideas sobre lo que saben que puede depararles el futuro, sino m\u00e1s bien como una forma deliberada de no dejarse abrumar por el futuro.<\/p>\n\n\n\n<p>En caso de Eli, la creencia en la recuperaci\u00f3n econ\u00f3mica, o mejor dicho en la capacidad de autocorrecci\u00f3n del sistema, le hac\u00eda entender la precariedad del presente como \u201cuna mala racha\u201d, por lo que se\u00f1alaba que pronto \u201cvendr\u00e1n tiempos mejores\u201d<em>. <\/em>Y as\u00ed, aunque atravesaba uno de los momentos econ\u00f3micos m\u00e1s duros de su vida, Eli se mostraba optimista y esperanzada y encontraba en la incertidumbre la condici\u00f3n previa a la esperanza. \u00c1lex, en cambio, depositaba la confianza en los cambios que podr\u00edan generar las fuerzas de izquierdas en las instituciones. Esta fe en que \u201cDios proveer\u00e1\u201d, en forma de una confianza en las fuerzas del cambio, le tranquilizaba y le hac\u00eda despreocuparse en cierta medida de sus pocas posibilidades de generar ahorros. Mientras que Ana pon\u00eda su confianza en su capacidad para salir adelante, en raz\u00f3n de las experiencias pasadas en las que de una u otra forma sali\u00f3 adelante, en ese \u201cya me buscar\u00e9 la vida\u201d. As\u00ed tambi\u00e9n me lo expres\u00f3 Eli en otras ocasiones:<\/p>\n\n\n\n<p class=\"verse\">Yo pensaba mucho en el ma\u00f1ana, siempre en el ma\u00f1ana, en el ma\u00f1ana. Y ya he empezado a pensar en el hoy, el hoy y el hoy. Y s\u00e9 que es muy t\u00edpico, pero es que es verdad; no sabes lo que vas a vivir, y mira: yo ya he visto muchas cosas, y sales de todo menos de la muerte, eso est\u00e1 claro. \u00bfEntonces, preocuparme?<\/p>\n\n\n\n<p>En definitiva, todos ellos eran ejercicios de confianza. Como se\u00f1alan Valerie H\u00e4nsch, Lena Kroeker y Silke Oldenburg (2017: 13), la confianza se opone a la incertidumbre, y tal vez de este modo el futuro deja de ser de alguna forma un tanto incierto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La responsabilizaci\u00f3n familiar e individual ante el ma\u00f1ana<\/h2>\n\n\n\n<p class=\"no-indent\">Las formas de ganarse la vida hoy en Errenteria son m\u00e1s individualizadas, inestables e inciertas que cuarenta a\u00f1os atr\u00e1s, lo que produce precariedad material, desprotecci\u00f3n social, ansiedad emocional e incertidumbre vital en amplios sectores de la poblaci\u00f3n. En este sentido, hacer etnograf\u00eda en una ciudad desindustrializada como Errenteria nos permite acercarnos a las transformaciones materiales y morales que se han producido con el fin de la sociedad industrial y las pol\u00edticas keynesianas de distribuci\u00f3n de la riqueza. Y es que, es de suponer, que los acontecimientos dados en este tiempo ya hayan tenido un efecto duradero en la forma en que la gente percibe y articula los tiempos pasados de prosperidad, la actual era de precariedad y sus expectativas de reconstruir su futuro.<\/p>\n\n\n\n<p>El trabajo de campo ha manifestado una idealizaci\u00f3n del pasado y unas reconfiguraciones m\u00edticas de esos recuerdos, en los que se omiten las precariedades e incertezas que vivieron las generaciones mayores, en especial las mujeres. Por lo general los \u201cbuenos tiempos\u201d se imaginan, recuerdan y transmiten como tiempos en los que era posible trazarse el propio futuro, mediante trabajo y sacrificio. Para la mayor\u00eda, esos tiempos terminaron en los a\u00f1os noventa con la desindustrializaci\u00f3n de la ciudad. Es a partir de esa significaci\u00f3n del pasado industrial desde donde hoy los hijos de esas clases obreras entienden el sentimiento de retroceso y su movilidad social descendente.<\/p>\n\n\n\n<div class=\"image-slider\">\n                <div class=\"frame\">\n                    <div class=\"picture\" itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\">\n                        <figure itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\" class=\"slider-element\">\n                              <a href=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-7.jpg\" itemprop=\"contentUrl\" data-size=\"1600\u2006\u00d7\u2006900\" data-index=\"0\" data-caption=\"Ilustraci\u00f3n 8. De camino al barrio de Galtzaraborda. Fotograf\u00eda tomada en el trabajo de campo, 2017-2018. Autor\u00eda: Uzuri Aboitiz.\" >\n                                <img decoding=\"async\" src=\"https:\/\/archive.org\/download\/gutierrez_alvarado-siva-video-1-pieza_arqueologica_de_shiva_penes_con_rostro\/aboitiz-sombras_futuro-7.jpg\" itemprop=\"thumbnail\">\n                                <i class=\"fa fa-expand expand\" aria-hidden=\"true\"><\/i>\n                            <\/a>\n                            <\/figure>                    <\/div>    \n                <\/div>\n                    <div class=\"caption\">Ilustraci\u00f3n 8. De camino al barrio de Galtzaraborda. Fotograf\u00eda tomada en el trabajo de campo, 2017-2018. Autor\u00eda: Uzuri Aboitiz.<\/div><div class=\"image-analysis\"><\/div>                <div class=\"bullets\"><\/div>\n            <\/div>\n\n\n\n<p>Sin embargo, la percepci\u00f3n de retroceso puede llevarnos a una idea un tanto simplista de suponer una sensaci\u00f3n generalizada de desesperanza, ruptura o de renuncia a construir el futuro. Y es que, como se ha mostrado a lo largo del art\u00edculo, los vecinos y vecinas de esta ciudad, a pesar de haber visto alteradas sus trayectorias de vida y sus promesas del ma\u00f1ana, siguen luchando por salir adelante e incluso conservan la esperanza de proteger, mantener y a veces aumentar su nivel de vida y sentido de dignidad; lo que cuestiona, por lo menos, la percepci\u00f3n del momento actual como una ruptura hist\u00f3rica irreversible. De hecho, a pesar de las incertidumbres cotidianas mis interlocutores siguen aspirando a \u201cpoder vivir tranquilos\u201d, que no es otra cosa que su idea de \u201cvivir bien\u201d con cierta seguridad y protecci\u00f3n.<\/p>\n\n\n\n<p>Ahora bien, ese \u201cpoder vivir tranquilos\u201d va acompa\u00f1ado por asumir que va a ser m\u00e1s dif\u00edcil de lo que fue para la generaci\u00f3n anterior, por ejemplo, en tanto normalizar que hay que trabajar y aguantar m\u00e1s y en peores condiciones, ya sea en el empleo o en la casa. Por otra parte, el \u00e9xito en las expectativas biogr\u00e1ficas se asume como una responsabilidad b\u00e1sicamente individual o familiar, algo que va en la l\u00ednea de las medidas de privatizaci\u00f3n de las formas de gesti\u00f3n social del riesgo dadas los \u00faltimos a\u00f1os. Es decir, en cierta forma se acepta la desresponsabilizaci\u00f3n del Estado, lo que podr\u00eda sugerir que los principios del pensamiento neoliberal se han visto reforzados durante esta larga din\u00e1mica, en tanto que, como afirma Sandra Ezquerra (2012: 134), se ha dado una transformaci\u00f3n en las expectativas y los derechos percibidos de la poblaci\u00f3n respecto de los servicios p\u00fablicos o los bienes comunes.<\/p>\n\n\n\n<p>En definitiva, es ampliamente aceptado que existe una inflexi\u00f3n en las expectativas y planes vitales de amplias capas sociales. La noci\u00f3n de vida a la que se aspiraba ha menguado y algunos sue\u00f1os y aspiraciones empiezan a ser supeditados y postergados. \u201cEn cuanto se pueda\u201d se convierte en la muletilla que sigue a muchas de las conversaciones sobre el futuro. Y es que los cambios en los campos de oportunidades han desajustado las expectativas creadas generacionalmente, produciendo una sensaci\u00f3n de desorientaci\u00f3n. Cuando les preguntaba sobre el futuro a mis interlocutores, la mayor\u00eda formulaban sue\u00f1os en lugar de proyectos. En efecto, cuando observaba la formulaci\u00f3n de expectativas de cerca, se hac\u00edan visibles la vaguedad y la indeterminaci\u00f3n desde las que se enunciaban. La gente se encuentra movi\u00e9ndose entre modelos econ\u00f3micos y moralidades opuestas, rescatando lo que le es \u00fatil para hacer m\u00e1s seguro su proyecto de vida. O, como dir\u00eda David Zeitlyn (2015: 399), los \u201cfuturos pasados\u201d siguen proyectando \u201csombras\u201d sobre las vidas, los sue\u00f1os y anhelos de los vecinos de Errenteria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Bibliograf\u00eda<\/h2>\n\n\n\n<p class=\"bibliography\">Alonso, Luis E. (2007). <em>La crisis de la ciudadan\u00eda laboral.<\/em> Barcelona: Anthropos.<\/p>\n\n\n\n<p class=\"bibliography\">Barcenilla, Miguel \u00c1. (1999). <em>La peque\u00f1a Manchester. Origen y consolidaci\u00f3n de un n\u00facleo industrial gipuzcoano. Errenteria (1845-1905).<\/em> San Sebasti\u00e1n: Diputaci\u00f3n Foral de Gip\u00fazcoa.<\/p>\n\n\n\n<p class=\"bibliography\">Barcenilla, Miguel \u00c1. (2004). \u201cEl pasado de Oarsoaldesa. Vivir entre fabricas\u201d. En <em>100 a\u00f1os de desarrollismo en Errenteria y su comarca<\/em>. Errenteria: Agencia de Desarrollo Comarcal Oarsoaldea y Ayuntamiento de Errenteria, pp. 11-42.<\/p>\n\n\n\n<p class=\"bibliography\">Bauman, Zygmunt (1998). <em>Globalisation: The Human Consequences. <\/em>Cambridge: Polity Press.<\/p>\n\n\n\n<p class=\"bibliography\">Beck, Ulrich (1992). <em>Risk Society: Towards a New Modernity.<\/em> Londres: Sage.<\/p>\n\n\n\n<p class=\"bibliography\">Benito, Ana M. (2007). \u201cEl Patrimonio Industrial de Renter\u00eda\u201d. <em>Oarso, <\/em>n\u00fam. 42, pp. 45-49.<\/p>\n\n\n\n<p class=\"bibliography\">Cottereau, Alain y Mokhtar M. Marzok (2012). <em>Une famille andalouse. Ethnocomptibilit\u00e9 d\u00b4une \u00e9conomie invisible<\/em>. Par\u00eds: Bouchene.<\/p>\n\n\n\n<p class=\"bibliography\">Escobar, Arturo (2010). \u201cLatin America at a Crossroads: Alternative Modernizations, Postliberalism, or Post Development?\u201d. <em>Cultural Studies,<\/em> vol. 24, n\u00fam. 1, pp. 1-65. https:\/\/doi.org\/10.1080\/09502380903424208<\/p>\n\n\n\n<p class=\"bibliography\">Etxezarreta, Miren (1991). <em>La reestructuraci\u00f3n del capitalismo en Espa\u00f1a.<\/em> Madrid: Fuhem e Icaria.<\/p>\n\n\n\n<p class=\"bibliography\">Eustat, Instituto Vasco de Estad\u00edstica (2016). <em>Censos de poblaci\u00f3n y viviendas. Poblaci\u00f3n de 16 y m\u00e1s a\u00f1os ocupada de la C.A. de Euskadi por municipio, situaci\u00f3n profesional y periodo<\/em>. [Base de datos].&nbsp;Recuperado de: https:\/\/www.eustat.eus\/bankupx\/pxweb\/es\/spanish\/-\/PX_2314_po11.px\/table\/tableViewLayout1\/?rxid=6a2ae2d5-979a-4f58-bdbc-e35c680b99d1, consultado el 19 de febrero de 2021.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (2016b). <em>Tasa de paro de la poblaci\u00f3n de 16 y m\u00e1s a\u00f1os de la C.A. de Euskadi por \u00e1mbitos territoriales, sexo y periodo.<\/em> [Base de datos].&nbsp;Recuperado de: https:\/\/es.eustat.eus\/bankupx\/pxweb\/es\/spanish\/-\/PX_2315_pp04a.px\/table\/tableViewLayout1\/?rxid=2d04795f-3f67-4428-8596-9d43330341b1, consultado el 19 de febrero de 2021.<\/p>\n\n\n\n<p class=\"bibliography\">Ezquerra, Sandra (2012). \u201cAcumulaci\u00f3n por desposesi\u00f3n, g\u00e9nero y crisis en el Estado Espa\u00f1ol\u201d. <em>Econom\u00eda Cr\u00edtica<\/em>, vol. 14, n\u00fam. 2, pp. 124-147. Recuperado de http:\/\/www.revistaeconomiacritica.org\/sites\/default\/files\/revistas\/n14\/Semimonografico-2.-Ezquerra.pdf, consultado el 4 de febrero de 2021.<\/p>\n\n\n\n<p class=\"bibliography\">H\u00e4nsch, Valerie, Lena Kroeker y Silke Oldenburg (2017). \u201cUncertain Future(s). Perceptions on Time between the Immediate and the Imagined\u201d. <em>Tsantsa<\/em>, vol. 22, pp. 4-17. https:\/\/doi.org\/10.36950\/tsantsa.2017.22.7342<\/p>\n\n\n\n<p class=\"bibliography\">Harvey, David (2007). <em>Breve historia del neoliberalismo. <\/em>Madrid: Akal.<\/p>\n\n\n\n<p class=\"bibliography\">Garc\u00e9s, Marina (2017). <em>Nova il.lustraci\u00f3 radical. <\/em>Barcelona: Anagrama.<\/p>\n\n\n\n<p class=\"bibliography\">Gobierno Vasco (1987). <em>La pobreza en la Comunidad Aut\u00f3noma Vasca.<\/em> Vitoria-Gasteiz: Gobierno Vasco.<\/p>\n\n\n\n<p class=\"bibliography\">Goddard, Victoria (2019). \u201cTrabajo y la buena vida o vida digna. Reflexiones y cr\u00edticas desde un an\u00e1lisis feminista\u201d. <em>Quaderns,<\/em> n\u00fam 35, pp. 5-22.<\/p>\n\n\n\n<p class=\"bibliography\">Kleist, Nauja y Stef Jansen (2016). \u201cIntroduction: Hope over Time &#8211; Crisis, Immobility and Future-Making\u201d. <em>History and Anthropology,<\/em>&nbsp;n\u00fam. 27, vol. 4, pp. 373-392. https:\/\/doi.org\/10.1080\/02757206.2016.1207636<\/p>\n\n\n\n<p class=\"bibliography\">Knight, Daniel M. (2016). \u201cTemporal Vertigo and Time Vortices on Greece\u2019s Central Plain\u201d. <em>The Cambridge Journal of Anthropology<\/em>, n\u00fam 34, vol 1, pp. 32-44. https:\/\/doi.org\/10.3167\/ca.2016.340105<\/p>\n\n\n\n<p class=\"bibliography\">Lacunza, Juan M. (2012). \u201cLa empresa Victorio Luzuriaga en Renter\u00eda\u201d. <em>Oarso<\/em>, n\u00fam 47, pp. 27-30.<\/p>\n\n\n\n<p class=\"bibliography\">L\u2019Estoile, Beno\u00eet de (2014). \u201cMoney Is Good, but a Friend Is Better. Uncertainty, Orientation to the Future, and the Economy\u201d. <em>Current Anthropology<\/em>, vol. 55, n\u00fam. 9, pp. 62-73. https:\/\/doi.org\/10.1086\/676068<\/p>\n\n\n\n<p class=\"bibliography\">Lewis, Jane (2002). \u201cGender and Welfare State Change\u201d. <em>European Societies<\/em>, vol. 4, n\u00fam. 4, pp. 331-357. https:\/\/doi.org\/10.1080\/1461669022000022324<\/p>\n\n\n\n<p class=\"bibliography\">L\u00f3pez Calle, Pablo (2018). \u201cSubjetividad precaria como recurso productivo: crisis, trabajo e identidad en las periferias metropolitanas desindustrializadas\u201d. <em>Revista Espa\u00f1ola de Sociolog\u00eda, <\/em>n\u00fam. 27, pp. 1-18<\/p>\n\n\n\n<p class=\"bibliography\">Mendialdea, Bibiana y Nacho \u00c1lvarez (2005). \u201cAjuste neoliberal y pobreza salarial: los <em>working poor<\/em> en la Uni\u00f3n Europea\u201d. <em>Viento Sur<\/em>, n\u00fam. 82, pp. 55-64<\/p>\n\n\n\n<p class=\"bibliography\">Motakef, Monta (2019). \u201cRecognition and Precarity of Life Arrangement: towards an Enlarged Understanding of Precarious Working and Living Conditions\u201d. <em>Distinktion: Journal of Socia Theory<\/em>, vol. 2, n\u00fam. 20, pp. 156-172. https:\/\/doi.org\/10.1080\/1600910X.2019.1610019<\/p>\n\n\n\n<p class=\"bibliography\">Narotzky,&nbsp;Susana y&nbsp;Niko&nbsp;Besnier (2014). \u201cCrisis, Value, and Hope: Rethinking the Economy: An Introduction to Supplement 9\u201d. <em>Current Anthropology<\/em>, vol. 55, n\u00fam. 9, pp. 4\u201316. https:\/\/doi.org\/10.1086\/676327<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 (2016). \u201cSpain is the Problem, Europe the Solution: Economic Models, Labour Organization and the Hope for a Better Future\u201d, en John Gledhill (ed.), <em>World Anthropologies in Practice.<\/em> Londres: Bloomsbury, pp. 19-39. https:\/\/doi.org\/10.4324\/9781003087441-3<\/p>\n\n\n\n<p class=\"bibliography\">Olaizola Eizagire, I\u00f1aki y Juan P. Olaberria Egiguren (2015). \u201cLuzuriaga, un astillero gipuzcoano (1960-2000)\u201d. <em>Itsas Memoria. Revista de Estudios Mari\u0301timos del Pai\u0301s Vasco,<\/em> n\u00fam 8, pp. 91-151.<\/p>\n\n\n\n<p class=\"bibliography\">Palomera, Jaime (2015). <em>The Political Economy of Spain. The Brief Story (1939-2014). <\/em>Documento de trabajo del <span class=\"small-caps\">erc<\/span> Greco Project. Recuperado de https:\/\/www.academia.edu\/22098898\/_2015_The_Political_Economy_of_Spain_A_brief_history_1939_2014, consultado el 4 de febrero de 2021.<\/p>\n\n\n\n<p class=\"bibliography\">Petras, James (1995). <em>El Informe Petras. Padres-Hijos. Dos generaciones de trabajadores espa\u00f1oles.<\/em> Barcelona: <span class=\"small-caps\">cgt<\/span>.<\/p>\n\n\n\n<p class=\"bibliography\">P\u00e9rez Orozco, Amaia (2014). <em>Subversi\u00f3n feminista de la econom\u00eda. Aportes sobre un debate sobre el conflicto capital-vida.<\/em> Madrid: Traficantes de sue\u00f1os.<\/p>\n\n\n\n<p class=\"bibliography\">Picavea, Pedro (1988). \u201cRenter\u00eda (1975-1986). Las transformaciones demogr\u00e1ficas de un municipio industrial\u201d. <em>Bilduma. Revista del Servicio de Archivo del Ayuntamiento de Errenteria<\/em>, n\u00fam. 2, pp. 9-24.<\/p>\n\n\n\n<p class=\"bibliography\">Ruzafa, Rafael (2017). \u201cCaras tristes de un proceso hist\u00f3rico. La desindustrializaci\u00f3n de la r\u00eda de Bilbao en el \u00faltimo cuarto del siglo <span class=\"small-caps\">xx<\/span>\u201d. <em>Historia, Trabajo y Sociedad,<\/em> n\u00fam. 8, pp. 11-33.<\/p>\n\n\n\n<p class=\"bibliography\">Santamar\u00eda, Elsa (2009). <em>Trayectorias laborales en los m\u00e1rgenes del empleo: experiencias de precariedad en los procesos de construcci\u00f3n identitaria.<\/em> Bilbao: Euskal Herriko Unibertsitatea.<\/p>\n\n\n\n<p class=\"bibliography\">Torres Enjuto, Mar\u00eda Concepci\u00f3n (1991). \u201cDiez a\u00f1os de reconversi\u00f3n industrial en Euskadi, 1980-1990)\u201d. <em>Bolet\u00edn de la Asociaci\u00f3n de Ge\u00f3grafos Espa\u00f1oles<\/em>, n\u00fam. 13, pp.165-186<\/p>\n\n\n\n<p class=\"bibliography\">Valdaliso, Jes\u00fas M. (2003). \u201cCrisis y reconversi\u00f3n de la industria de construcci\u00f3n naval en el Pa\u00eds Vasco\u201d. <em>Ekonomiaz<\/em>, n\u00fam. 54, pp. 53-67.<\/p>\n\n\n\n<p class=\"bibliography\">Villarreal, Magdalena (2008). \u201cDeudas, drogas, fiado y prestado en las tiendas de abarrotes rurales\u201d. <em>Ruris, <\/em>n\u00fam. 1, vol. 2, pp. 99-128.<\/p>\n\n\n\n<p class=\"bibliography\">\u2014 Lya Ni\u00f1o y Joshua Greene (2017). \u201cMalabarismos financieros en contextos transfronterizos\u201d, en Magdalena Barros y Agust\u00edn Escobar (coord.), <em>Migraci\u00f3n internacional, interna y en tr\u00e1nsito: actores y procesos.<\/em> Libro 1: <em>Nuevos procesos en la migraci\u00f3n internacional y mercados de trabajo.<\/em> M\u00e9xico: <span class=\"small-caps\">ciesas,<\/span> pp. 81-98.<\/p>\n\n\n\n<p class=\"bibliography\">Williams, Raymond (1977). <em>Marxism and Literature.<\/em> Oxford: Oxford University Press.<\/p>\n\n\n\n<p class=\"bibliography\">Zeitlyn, David (2015). \u201cLooking Forward, Looking Back\u201d. <em>History and Anthropology,<\/em> vol. 26, n\u00fam. 4, pp. 381\u2013407. https:\/\/doi.org\/10.1080\/02757206.2015.1076813<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"no-indent\"><em>Uzuri Aboitiz<\/em> es investigadora predoctoral contratada (2016-2019) en Sociedad y Cultura, \u00e1mbito de Antropolog\u00eda asociada al Grupo de Estudios de Reciprocidad de la Universidad de Barcelona. Ha realizado una estancia de investigaci\u00f3n en el curso 2018-2019 en <span class=\"small-caps\">ciesas<\/span> Occidente, bajo el paraguas del Seminario Internacional de Antropolog\u00eda y Dinero (<span class=\"small-caps\">ade<\/span>), asociado al mismo centro y al Institute for Money, Technology &amp; Financial Inclusion (<span class=\"small-caps\">imtfi<\/span>). En su investigaci\u00f3n doctoral estudia la reconfiguraci\u00f3n de los marcos de significaci\u00f3n y de las pr\u00e1cticas a la hora de sacar la vida adelante y construir proyectos de vida sucedidos en la transici\u00f3n de un Estado Keynesiano Fordista a otro de corte neoliberal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Errenteria has historically been one of the main Basque industrial centers, which in the 1960s and 1970s allowed it to achieve full employment and job stability, especially male industrial employment, until the transition governments in the mid-1970s they began to restructure industries, supposedly to prepare for entry into the European Economic Community and the challenge of free market competitiveness. The loss of thousands of jobs was followed by a deregulation of the labor market that generated a greater precariousness of living conditions, which was intensified by the financial crisis of 2008 and the austerity policies. In this article I propose to show how, for the younger generations of this city, past futures continue to cast shadows in the ways of contemplating now a future marked by growing uncertainty. In that sense, I dispute the common sense of &quot;going backwards&quot;, pointing out that going backwards seems to allude not only to the achievements of past generations unraveling, but to a confusing reconfiguration of what they can now expect from the future.<\/p>","protected":false},"author":8,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[279],"tags":[712,709,707,711,710,708,637],"coauthors":[704,551],"class_list":["post-33940","post","type-post","status-publish","format-standard","hentry","category-279","tag-ajuste-estructural","tag-desindustrializacion","tag-errenteria","tag-esperanza","tag-incertidumbre","tag-prosperidad","tag-temporalidad","personas-aboitiz-uzuri","numeros-705"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las sombras de los futuros que ya no son en Errenteria &#8211; Encartes<\/title>\n<meta name=\"description\" content=\"En Errenteria la p\u00e9rdida de miles de puestos de trabajo le sigui\u00f3 una desregulaci\u00f3n del mercado laboral que gener\u00f3 una mayor precarizaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las sombras de los futuros que ya no son en Errenteria &#8211; Encartes\" \/>\n<meta property=\"og:description\" content=\"En Errenteria la p\u00e9rdida de miles de puestos de trabajo le sigui\u00f3 una desregulaci\u00f3n del mercado laboral que gener\u00f3 una mayor precarizaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/\" \/>\n<meta property=\"og:site_name\" content=\"Encartes\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-19T07:06:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-18T00:19:34+00:00\" \/>\n<meta name=\"author\" content=\"Sergio Vel\u00e1zquez, Arthur Ventura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sergio Vel\u00e1zquez, Arthur Ventura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"45 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/\"},\"author\":{\"name\":\"Sergio Vel\u00e1zquez\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/person\/5be8636bb6a3e2486cf548bf3c500765\"},\"headline\":\"Las sombras de los futuros que ya no son. Las reconfiguraciones sociales de la esperanza en la ciudad desindustrializada de Errenteria, Pa\u00eds Vasco\",\"datePublished\":\"2021-03-19T07:06:16+00:00\",\"dateModified\":\"2023-11-18T00:19:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/\"},\"wordCount\":10957,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/encartes.mx\/#organization\"},\"keywords\":[\"ajuste estructural\",\"desindustrializaci\u00f3n\",\"Errenteria\",\"esperanza\",\"incertidumbre\",\"prosperidad\",\"temporalidad\"],\"articleSection\":[\"Dosier\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/\",\"url\":\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/\",\"name\":\"Las sombras de los futuros que ya no son en Errenteria &#8211; Encartes\",\"isPartOf\":{\"@id\":\"https:\/\/encartes.mx\/#website\"},\"datePublished\":\"2021-03-19T07:06:16+00:00\",\"dateModified\":\"2023-11-18T00:19:34+00:00\",\"description\":\"En Errenteria la p\u00e9rdida de miles de puestos de trabajo le sigui\u00f3 una desregulaci\u00f3n del mercado laboral que gener\u00f3 una mayor precarizaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/encartes.mx\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las sombras de los futuros que ya no son. Las reconfiguraciones sociales de la esperanza en la ciudad desindustrializada de Errenteria, Pa\u00eds Vasco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/encartes.mx\/#website\",\"url\":\"https:\/\/encartes.mx\/\",\"name\":\"Encartes\",\"description\":\"Revista digital multimedia\",\"publisher\":{\"@id\":\"https:\/\/encartes.mx\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/encartes.mx\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/encartes.mx\/#organization\",\"name\":\"Encartes Antropol\u00f3gicos\",\"url\":\"https:\/\/encartes.mx\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"contentUrl\":\"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png\",\"width\":338,\"height\":306,\"caption\":\"Encartes Antropol\u00f3gicos\"},\"image\":{\"@id\":\"https:\/\/encartes.mx\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/person\/5be8636bb6a3e2486cf548bf3c500765\",\"name\":\"Sergio Vel\u00e1zquez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/encartes.mx\/#\/schema\/person\/image\/ceeac9312f7124efe61e88a7a1c4299d\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/13dd71176282795f75f8cf619517c1b9?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/13dd71176282795f75f8cf619517c1b9?s=96&d=identicon&r=g\",\"caption\":\"Sergio Vel\u00e1zquez\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las sombras de los futuros que ya no son en Errenteria &#8211; Encartes","description":"En Errenteria la p\u00e9rdida de miles de puestos de trabajo le sigui\u00f3 una desregulaci\u00f3n del mercado laboral que gener\u00f3 una mayor precarizaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/","og_locale":"en_US","og_type":"article","og_title":"Las sombras de los futuros que ya no son en Errenteria &#8211; Encartes","og_description":"En Errenteria la p\u00e9rdida de miles de puestos de trabajo le sigui\u00f3 una desregulaci\u00f3n del mercado laboral que gener\u00f3 una mayor precarizaci\u00f3n.","og_url":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/","og_site_name":"Encartes","article_published_time":"2021-03-19T07:06:16+00:00","article_modified_time":"2023-11-18T00:19:34+00:00","author":"Sergio Vel\u00e1zquez, Arthur Ventura","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Sergio Vel\u00e1zquez, Arthur Ventura","Est. reading time":"45 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/#article","isPartOf":{"@id":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/"},"author":{"name":"Sergio Vel\u00e1zquez","@id":"https:\/\/encartes.mx\/#\/schema\/person\/5be8636bb6a3e2486cf548bf3c500765"},"headline":"Las sombras de los futuros que ya no son. Las reconfiguraciones sociales de la esperanza en la ciudad desindustrializada de Errenteria, Pa\u00eds Vasco","datePublished":"2021-03-19T07:06:16+00:00","dateModified":"2023-11-18T00:19:34+00:00","mainEntityOfPage":{"@id":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/"},"wordCount":10957,"commentCount":0,"publisher":{"@id":"https:\/\/encartes.mx\/#organization"},"keywords":["ajuste estructural","desindustrializaci\u00f3n","Errenteria","esperanza","incertidumbre","prosperidad","temporalidad"],"articleSection":["Dosier"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/","url":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/","name":"Las sombras de los futuros que ya no son en Errenteria &#8211; Encartes","isPartOf":{"@id":"https:\/\/encartes.mx\/#website"},"datePublished":"2021-03-19T07:06:16+00:00","dateModified":"2023-11-18T00:19:34+00:00","description":"En Errenteria la p\u00e9rdida de miles de puestos de trabajo le sigui\u00f3 una desregulaci\u00f3n del mercado laboral que gener\u00f3 una mayor precarizaci\u00f3n.","breadcrumb":{"@id":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/encartes.mx\/en\/aboitiz-reconfiguraciones-sociales-errenteria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/encartes.mx\/"},{"@type":"ListItem","position":2,"name":"Las sombras de los futuros que ya no son. Las reconfiguraciones sociales de la esperanza en la ciudad desindustrializada de Errenteria, Pa\u00eds Vasco"}]},{"@type":"WebSite","@id":"https:\/\/encartes.mx\/#website","url":"https:\/\/encartes.mx\/","name":"Encartes","description":"Multimedia digital magazine","publisher":{"@id":"https:\/\/encartes.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/encartes.mx\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/encartes.mx\/#organization","name":"Anthropological Inserts","url":"https:\/\/encartes.mx\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/","url":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","contentUrl":"https:\/\/encartes.mx\/wp-content\/uploads\/2017\/04\/Logo-04.png","width":338,"height":306,"caption":"Encartes Antropol\u00f3gicos"},"image":{"@id":"https:\/\/encartes.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/encartes.mx\/#\/schema\/person\/5be8636bb6a3e2486cf548bf3c500765","name":"Sergio Velazquez","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/encartes.mx\/#\/schema\/person\/image\/ceeac9312f7124efe61e88a7a1c4299d","url":"https:\/\/secure.gravatar.com\/avatar\/13dd71176282795f75f8cf619517c1b9?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13dd71176282795f75f8cf619517c1b9?s=96&d=identicon&r=g","caption":"Sergio Vel\u00e1zquez"}}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/posts\/33940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/comments?post=33940"}],"version-history":[{"count":52,"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/posts\/33940\/revisions"}],"predecessor-version":[{"id":37958,"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/posts\/33940\/revisions\/37958"}],"wp:attachment":[{"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/media?parent=33940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/categories?post=33940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/tags?post=33940"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/encartes.mx\/en\/wp-json\/wp\/v2\/coauthors?post=33940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}